{"id":109344,"date":"2025-12-31T08:04:13","date_gmt":"2025-12-31T12:04:13","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109344"},"modified":"2025-12-31T08:04:14","modified_gmt":"2025-12-31T12:04:14","slug":"junior-lake-conecta-jonron-en-victoria-leones-toros-triunfan","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/junior-lake-conecta-jonron-en-victoria-leones-toros-triunfan\/","title":{"rendered":"Junior Lake conecta jonr\u00f3n en victoria Leones; Toros triunfan"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/12\/Jorge-Mateo-6-300x200-1.jpg\" alt=\"\" class=\"wp-image-109345\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- Un jonr\u00f3n de dos carreras en el s\u00e9ptimo episodio por parte de Junior Lake rompi\u00f3 un empate a uno para que los Leones del Escogido vencieran 3-2 este martes a los Gigantes del Cibao para extender su invicto a 4-0 en el Todos contra Todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cuadrangular de Lake contra Yovanny Cruz recorri\u00f3 388 pies de distancia por el jard\u00edn izquierdo a una velocidad de 104.8 millas por hora<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los capitale\u00f1os fabricaron su primera vuelta en el cuarto acto, en el que Raimel Tapia y Jorge Mateo pegaron sencillos consecutivos al jard\u00edn izquierdo frente a Cristopher Molina; en la jugada un error del guardabosque Leury Garc\u00eda permiti\u00f3 que Mateo llegara a la intermedia. Posteriormente, un rodado de Jos\u00e9 Marmolejos a la inicial llev\u00f3 a Tapia a la goma con la primera de los locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el quinto cap\u00edtulo, ante Kenny Hern\u00e1ndez con las bases llenas y dos outs, Francisco Mej\u00eda conect\u00f3 un rodado por segunda que oblig\u00f3 al intermedista Jorge Mateo a desplazarse a su derecha con el guante de rev\u00e9s para lograr un disparo de piconazo que retuvo el inicialista Jos\u00e9 Marmolejos para cerrar la entrada sin anotaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los visitantes marcaron en el sexto ante Grant Gavin, a quien Nicholas Torres le peg\u00f3 triple al central y luego anot\u00f3 con elevado de sacrificio de Garc\u00eda al prado derecho. La otra rayita lleg\u00f3 en el noveno contra Aneurys Zabala (1), que pese a esa anotaci\u00f3n consigui\u00f3 el salvamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlos Teller (2-0) fue el lanzador ganador al presentarse en dos tercios en blanco. La derrota fue para Fernando Abad (0-1) a cuya cuenta fue una de las vueltas que produjo el bambinazo de Lake.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque no complet\u00f3 las cinco entradas para obtener la victoria, el abridor escarlata Radham\u00e9s Liz tir\u00f3 buena pelota al presentarse en 4.2 episodios en blanco de cuatro hits, tres ponches y dos boletos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con su 4-0, los campeones nacionales y del Caribe siguen liderando el Round Robin. Los Gigantes (0-4) siguen en el s\u00f3tano sin conocer la victoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los rojos, Lake se fue de 4-1, con jonr\u00f3n, dos producidas y una anotada; Tapia, de 4-1, con una anotada, y Michael De la Cruz, de 2-1, con una anotada y una transferencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los nordestanos, Torres bate\u00f3 de 4-1, con triple y una anotada, y Marco Hern\u00e1ndez, de 5-2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TOROS 8 AGUILAS 7<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el juego empatado 5-5 en el octavo,\u00a0Bryan De La Cruz\u00a0conect\u00f3 un enorme cuadrangular por todo el jard\u00edn izquierdo con dos a bordo, para completar un rally de cuatro carreras en este inning, y darle la victoria a los Toros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LA ROMANA.-\u00a0Bryan De La Cruz\u00a0contin\u00faa modo \u201cMVP\u201d, se visti\u00f3 de h\u00e9roe pegando jonr\u00f3n enorme de tres carreras en el octavo para la ventaja, y remolc\u00f3 cinco vueltas, para liderar la remontada de los Toros del Este, que vencieron 8-5 a las \u00c1guilas Cibae\u00f1as, en partido celebrado Estadio\u00a0Francisco A. Micheli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para de La Cruz, este fue su primer cuadrangular del Round Robin y segundo de los Toros de manera colectiva en esta etapa. Adem\u00e1s del jonr\u00f3n,\u00a0Bryan De La Cruz\u00a0tambi\u00e9n peg\u00f3 dos dobletes, empuj\u00f3 cinco y sigue modo MVP, siendo el l\u00edder actual de bateo con AVG .529, un cuadrangular y ocho remolcadas, tambi\u00e9n l\u00edder de este encasillado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria fue para el relevista romanense\u00a0Miguel Castro\u00a0(1-0, 11.57) tras lanzar el octavo d\u00f3nde ponch\u00f3 uno;\u00a0Joe Corbett\u00a0obtuvo el salvamento (1\u00ba) con un inning en blanco, propin\u00f3 un ponche, mientras la derrota fue para el relevista aguilucho Richard Rodr\u00edguez (0-1, 18.00), permitiendo dos hits y dos carreras en el octavo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pitcheo de los Toros volvi\u00f3 a sacar outs a la hora buena, provocando que los bateadores amarillos dejaran 11 hombres en base luego de batear de 14-3 con corredores en posici\u00f3n anotadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los Toros,\u00a0Bryan De La Cruz\u00a0de 5-3, jonr\u00f3n, dos dobles, cinco empujadas, tres anotadas;\u00a0Eloy Jim\u00e9nez\u00a0de 3-2, doble y sencillo, remolc\u00f3 dos;\u00a0Sergio Alc\u00e1ntara\u00a0de 3-2 con doble;\u00a0Luis Liberat<a href=\"https:\/\/torosdeleste.com\/roster\/luis-liberato\">o<\/a>\u00a0de 4-3, una impulsada, tres anotadas y\u00a0Gilberto Celestino\u00a0de 4-2, dos sencillos, un boleto y anot\u00f3 una.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por las \u00c1guilas, Leody taveras de 2-1, doble, dos producidas y una anotada;\u00a0Webster Riva<a href=\"https:\/\/torosdeleste.com\/roster\/webster-rivas\">s<\/a>\u00a0de 2-1, dos impulsadas y\u00a0Cristhian Adames\u00a0de 5-3, dos dobles, una empujada y una anotada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">POSICIONES ROUND ROBIN<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-left\" data-align=\"left\">EQUIPO<\/th><th class=\"has-text-align-left\" data-align=\"left\">J<\/th><th class=\"has-text-align-left\" data-align=\"left\">G<\/th><th class=\"has-text-align-left\" data-align=\"left\">P<\/th><th class=\"has-text-align-left\" data-align=\"left\">PCT<\/th><th class=\"has-text-align-left\" data-align=\"left\">DIF<\/th><th class=\"has-text-align-left\" data-align=\"left\">RACHA<\/th><\/tr><\/thead><tbody><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/671.svg\" alt=\"ESC\" \/><\/td><td>4<\/td><td>4<\/td><td>0<\/td><td>1.000<\/td><td>\u2013<\/td><td>W4<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/668.svg\" alt=\"TOR\" \/><\/td><td>4<\/td><td>3<\/td><td>1<\/td><td>.750<\/td><td>1<\/td><td>W2<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/667.svg\" alt=\"Aguilas Cibaenas\" \/><\/td><td>4<\/td><td>1<\/td><td>3<\/td><td>.250<\/td><td>3<\/td><td>L2<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/670.svg\" alt=\"GIG\" \/><\/td><td>4<\/td><td>0<\/td><td>4<\/td><td>.000<\/td><td>4<\/td><td>L4<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">of-am<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Un jonr\u00f3n de dos carreras en el s\u00e9ptimo episodio por parte de Junior Lake rompi\u00f3 un empate a uno para que los Leones del Escogido vencieran 3-2 este martes a los Gigantes del Cibao para extender su invicto a 4-0 en el Todos contra Todos. El cuadrangular de Lake contra Yovanny Cruz recorri\u00f3 388 pies de distancia por el jard\u00edn izquierdo a una velocidad de 104.8 millas por hora Los capitale\u00f1os fabricaron su primera vuelta en el cuarto acto, en el que Raimel Tapia y Jorge Mateo pegaron sencillos consecutivos al jard\u00edn izquierdo frente a Cristopher Molina; en la jugada un error del guardabosque Leury Garc\u00eda permiti\u00f3 que Mateo llegara a la intermedia. Posteriormente, un rodado de Jos\u00e9 Marmolejos a la inicial llev\u00f3 a Tapia a la goma con la primera de los locales. En el quinto cap\u00edtulo, ante Kenny Hern\u00e1ndez con las bases llenas y dos outs, Francisco Mej\u00eda conect\u00f3 un rodado por segunda que oblig\u00f3 al intermedista Jorge Mateo a desplazarse a su derecha con el guante de rev\u00e9s para lograr un disparo de piconazo que retuvo el inicialista Jos\u00e9 Marmolejos para cerrar la entrada sin anotaciones. Los visitantes marcaron en el sexto ante Grant Gavin, a quien Nicholas Torres le peg\u00f3 triple al central y luego anot\u00f3 con elevado de sacrificio de Garc\u00eda al prado derecho. La otra rayita lleg\u00f3 en el noveno contra Aneurys Zabala (1), que pese a esa anotaci\u00f3n consigui\u00f3 el salvamento. Carlos Teller (2-0) fue el lanzador ganador al presentarse en dos tercios en blanco. La derrota fue para Fernando Abad (0-1) a cuya cuenta fue una de las vueltas que produjo el bambinazo de Lake. Aunque no complet\u00f3 las cinco entradas para obtener la victoria, el abridor escarlata Radham\u00e9s Liz tir\u00f3 buena pelota al presentarse en 4.2 episodios en blanco de cuatro hits, tres ponches y dos boletos. Con su 4-0, los campeones nacionales y del Caribe siguen liderando el Round Robin. Los Gigantes (0-4) siguen en el s\u00f3tano sin conocer la victoria. Por los rojos, Lake se fue de 4-1, con jonr\u00f3n, dos producidas y una anotada; Tapia, de 4-1, con una anotada, y Michael De la Cruz, de 2-1, con una anotada y una transferencia. Por los nordestanos, Torres bate\u00f3 de 4-1, con triple y una anotada, y Marco Hern\u00e1ndez, de 5-2. TOROS 8 AGUILAS 7 Con el juego empatado 5-5 en el octavo,\u00a0Bryan De La Cruz\u00a0conect\u00f3 un enorme cuadrangular por todo el jard\u00edn izquierdo con dos a bordo, para completar un rally de cuatro carreras en este inning, y darle la victoria a los Toros. LA ROMANA.-\u00a0Bryan De La Cruz\u00a0contin\u00faa modo \u201cMVP\u201d, se visti\u00f3 de h\u00e9roe pegando jonr\u00f3n enorme de tres carreras en el octavo para la ventaja, y remolc\u00f3 cinco vueltas, para liderar la remontada de los Toros del Este, que vencieron 8-5 a las \u00c1guilas Cibae\u00f1as, en partido celebrado Estadio\u00a0Francisco A. Micheli. Para de La Cruz, este fue su primer cuadrangular del Round Robin y segundo de los Toros de manera colectiva en esta etapa. Adem\u00e1s del jonr\u00f3n,\u00a0Bryan De La Cruz\u00a0tambi\u00e9n peg\u00f3 dos dobletes, empuj\u00f3 cinco y sigue modo MVP, siendo el l\u00edder actual de bateo con AVG .529, un cuadrangular y ocho remolcadas, tambi\u00e9n l\u00edder de este encasillado. La victoria fue para el relevista romanense\u00a0Miguel Castro\u00a0(1-0, 11.57) tras lanzar el octavo d\u00f3nde ponch\u00f3 uno;\u00a0Joe Corbett\u00a0obtuvo el salvamento (1\u00ba) con un inning en blanco, propin\u00f3 un ponche, mientras la derrota fue para el relevista aguilucho Richard Rodr\u00edguez (0-1, 18.00), permitiendo dos hits y dos carreras en el octavo. El pitcheo de los Toros volvi\u00f3 a sacar outs a la hora buena, provocando que los bateadores amarillos dejaran 11 hombres en base luego de batear de 14-3 con corredores en posici\u00f3n anotadora. Por los Toros,\u00a0Bryan De La Cruz\u00a0de 5-3, jonr\u00f3n, dos dobles, cinco empujadas, tres anotadas;\u00a0Eloy Jim\u00e9nez\u00a0de 3-2, doble y sencillo, remolc\u00f3 dos;\u00a0Sergio Alc\u00e1ntara\u00a0de 3-2 con doble;\u00a0Luis Liberato\u00a0de 4-3, una impulsada, tres anotadas y\u00a0Gilberto Celestino\u00a0de 4-2, dos sencillos, un boleto y anot\u00f3 una. Por las \u00c1guilas, Leody taveras de 2-1, doble, dos producidas y una anotada;\u00a0Webster Rivas\u00a0de 2-1, dos impulsadas y\u00a0Cristhian Adames\u00a0de 5-3, dos dobles, una empujada y una anotada. POSICIONES ROUND ROBIN EQUIPO J G P PCT DIF RACHA 4 4 0 1.000 \u2013 W4 4 3 1 .750 1 W2 4 1 3 .250 3 L2 4 0 4 .000 4 L4 of-am<\/p>\n","protected":false},"author":9,"featured_media":109345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-109344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109344"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109344\/revisions"}],"predecessor-version":[{"id":109346,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109344\/revisions\/109346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109345"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}