{"id":109391,"date":"2026-01-03T06:36:21","date_gmt":"2026-01-03T10:36:21","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109391"},"modified":"2026-01-03T06:36:23","modified_gmt":"2026-01-03T10:36:23","slug":"leones-dispone-toros-aguilas-sufren-pero-vencen-a-gigantes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/leones-dispone-toros-aguilas-sufren-pero-vencen-a-gigantes\/","title":{"rendered":"Leones dispone Toros; Aguilas sufren pero vencen a Gigantes"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"221\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/Erik-Gonzalez-2-300x221-1.jpg\" alt=\"\" class=\"wp-image-109392\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">LA ROMANA.- A ritmo de 14 hits, los Leones del Escogido extendieron su invicto a 5-0 al derrotar la noche de este viernes a los Toros del Este 10-5 en el estadio Francisco A. Micheli, de esta ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El triunfo aleja a los campeones nacionales y del Caribe a dos juegos del segundo lugar, que ocupan precisamente los Toros con marca de 3-2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los melenudos madrugaron con tres anotaciones en el primer episodio contra Justin Courtney producto de base por bolas a Erik Gonz\u00e1lez, sencillo de S\u00f3crates Brito al jard\u00edn izquierdo, un doble robo y un rodado de Yamaico Navarro a la inicial que remolc\u00f3 Brito. Las bases se llenaron con boletos a Raimel Tapia y Jorge Mateo, y un imparable de Jos\u00e9 Marmolejos al prado derecho empuj\u00f3 otras dos para los visitantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los romanenses fabricaron dos rayitas en la parte baja del primero, pero los escarlatas ampliaron ventaja en el segundo con otras dos vueltas gracias a indiscutible de Junior Lake al bosque derecho, pasando a segunda por robo y anotando con incogible de Gonz\u00e1lez al jard\u00edn izquierdo. Un sencillo de Navarro a la misma zona produjo la quinta de los rojos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los capitale\u00f1os sumaron una m\u00e1s en el cuarto, pero luego de dos outs en el quinto, ante Anderson Severino, Michael De la Cruz conect\u00f3 indiscutible al bosque izquierdo, se estaf\u00f3 la intermedia y anot\u00f3 con doble al central por parte de Jonathan Guzm\u00e1n, quien alcanz\u00f3 la goma con la octava de los escogidistas tras imparable de Lake frente a Jhan Mar\u00ed\u00f1ez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la parte baja, el conjunto naranja llen\u00f3 las almohadillas y un doble de Eloy Jim\u00e9nez al jard\u00edn izquierdo contra Phillips Valdez llev\u00f3 a tres corredores a la registradora, aunque dos de esas carreras fueron a la cuenta de Travis Lakins, que termin\u00f3 sin decisi\u00f3n al no completar las cinco entradas reglamentarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brito peg\u00f3 un cuadrangular de dos vueltas por el prado derecho en el octavo ante Miguel Castro para colocar el juego 10-5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hansel Marcelino se alz\u00f3 con la victoria (1-0) luego de presentarse en 1.1 innings en blanco, consiguiendo dos ponches. Courtney (0-1) fue el lanzador derrotado al permitir las tres anotaciones del primer acto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los melenudos, Brito se fue de 5-4, con jonr\u00f3n, tres empujadas, dos anotadas y dos bases robadas; Gonz\u00e1lez, de 4-2, con doble, tres anotadas, una producida, transferencia y base robada;&nbsp; Lake, de 4-2, con dos anotadas, una impulsada, una base por bolas y una base robada, y Marmolejos, de 4-2, con dos remolcadas, transferencia y una base robada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los taurinos, Jim\u00e9nez bate\u00f3 de 3-1, con doble y cuatro empujadas, y Liberato, de 3-1, con doble, anotada y boleto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AGUILAS 8 GIGANTES 7<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;SANTIAGO DE LOS CABALLEROS.- Las \u00c1guilas Cibae\u00f1as tuvieron un s\u00e9ptimo episodio de tres jonrones y Julio E. Rodr\u00edguez dispar\u00f3 un sencillo con las bases congestionadas para darle el triunfo en 10 entradas 8-7 a las \u00c1guilas Cibae\u00f1as sobre los Gigantes del Cibao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la derrota de los Toros del Este (3-2) ante los Leones del Escogido (5-0) ahora las \u00c1guilas, que comienzan bien el a\u00f1o, se ponen a un juego en esta semifinal round robin que retorna despu\u00e9s de la pausa de fin de a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las \u00c1guilas se recuperaron de un rally de cinco vueltas de los Gigantes en el octavo, adem\u00e1s de que tambi\u00e9n vieron a los macorisanos irse delante 7-6 en la alta del cap\u00edtulo 10.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adisyn Coffey tuvo problemas en el d\u00e9cimo y adem\u00e1s de permitir la del empate le dej\u00f3 una herencia negativa a Bryan Rodr\u00edguez al encontrar las bases llenas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue entonces cuando lleg\u00f3 el hit decisivo de Rodr\u00edguez en un cap\u00edtulo de dos carreras para las rapaces que se ponen con 2-3 al dejar en el terreno a los francomacorisanos que a\u00fan no consiguen ganar en cinco juegos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La particularidad de los jonrones de Clase y Encarnaci\u00f3n es que fue abriendo la baja del s\u00e9ptimo y ambos al primer lanzamiento servido por el relevista Reymin Gudu\u00e1n. El palo de Encarnaci\u00f3n sali\u00f3 por encima del pared\u00f3n (385) verde del Estadio Cibao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El bambinazo de Berroa, por el prado izquierdo, lleg\u00f3 despu\u00e9s de dos outs, calculado en 376 pies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria fue para Yoan L\u00f3pez (2-0) y perdi\u00f3 Coffey.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">POSICIONES ROUND ROBIN<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-left\" data-align=\"left\">EQUIPO<\/th><th class=\"has-text-align-left\" data-align=\"left\">J<\/th><th class=\"has-text-align-left\" data-align=\"left\">G<\/th><th class=\"has-text-align-left\" data-align=\"left\">P<\/th><th class=\"has-text-align-left\" data-align=\"left\">PCT<\/th><th class=\"has-text-align-left\" data-align=\"left\">DIF<\/th><th class=\"has-text-align-left\" data-align=\"left\">RACHA<\/th><\/tr><\/thead><tbody><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/671.svg\" alt=\"ESC\" \/><\/td><td>5<\/td><td>5<\/td><td>0<\/td><td>1.000<\/td><td>\u2013<\/td><td>W5<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/668.svg\" alt=\"TOR\" \/><\/td><td>5<\/td><td>3<\/td><td>2<\/td><td>.600<\/td><td>2<\/td><td>L1<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/667.svg\" alt=\"Aguilas Cibaenas\" \/><\/td><td>5<\/td><td>2<\/td><td>3<\/td><td>.400<\/td><td>3<\/td><td>W1<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/www.mlbstatic.com\/team-logos\/670.svg\" alt=\"GIG\" \/><\/td><td>5<\/td><td>0<\/td><td>5<\/td><td>.000<\/td><td>5<\/td><td>L5<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">of-am<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA ROMANA.- A ritmo de 14 hits, los Leones del Escogido extendieron su invicto a 5-0 al derrotar la noche de este viernes a los Toros del Este 10-5 en el estadio Francisco A. Micheli, de esta ciudad. El triunfo aleja a los campeones nacionales y del Caribe a dos juegos del segundo lugar, que ocupan precisamente los Toros con marca de 3-2. Los melenudos madrugaron con tres anotaciones en el primer episodio contra Justin Courtney producto de base por bolas a Erik Gonz\u00e1lez, sencillo de S\u00f3crates Brito al jard\u00edn izquierdo, un doble robo y un rodado de Yamaico Navarro a la inicial que remolc\u00f3 Brito. Las bases se llenaron con boletos a Raimel Tapia y Jorge Mateo, y un imparable de Jos\u00e9 Marmolejos al prado derecho empuj\u00f3 otras dos para los visitantes. Los romanenses fabricaron dos rayitas en la parte baja del primero, pero los escarlatas ampliaron ventaja en el segundo con otras dos vueltas gracias a indiscutible de Junior Lake al bosque derecho, pasando a segunda por robo y anotando con incogible de Gonz\u00e1lez al jard\u00edn izquierdo. Un sencillo de Navarro a la misma zona produjo la quinta de los rojos. Los capitale\u00f1os sumaron una m\u00e1s en el cuarto, pero luego de dos outs en el quinto, ante Anderson Severino, Michael De la Cruz conect\u00f3 indiscutible al bosque izquierdo, se estaf\u00f3 la intermedia y anot\u00f3 con doble al central por parte de Jonathan Guzm\u00e1n, quien alcanz\u00f3 la goma con la octava de los escogidistas tras imparable de Lake frente a Jhan Mar\u00ed\u00f1ez. En la parte baja, el conjunto naranja llen\u00f3 las almohadillas y un doble de Eloy Jim\u00e9nez al jard\u00edn izquierdo contra Phillips Valdez llev\u00f3 a tres corredores a la registradora, aunque dos de esas carreras fueron a la cuenta de Travis Lakins, que termin\u00f3 sin decisi\u00f3n al no completar las cinco entradas reglamentarias. Brito peg\u00f3 un cuadrangular de dos vueltas por el prado derecho en el octavo ante Miguel Castro para colocar el juego 10-5 Hansel Marcelino se alz\u00f3 con la victoria (1-0) luego de presentarse en 1.1 innings en blanco, consiguiendo dos ponches. Courtney (0-1) fue el lanzador derrotado al permitir las tres anotaciones del primer acto. Por los melenudos, Brito se fue de 5-4, con jonr\u00f3n, tres empujadas, dos anotadas y dos bases robadas; Gonz\u00e1lez, de 4-2, con doble, tres anotadas, una producida, transferencia y base robada;&nbsp; Lake, de 4-2, con dos anotadas, una impulsada, una base por bolas y una base robada, y Marmolejos, de 4-2, con dos remolcadas, transferencia y una base robada. Por los taurinos, Jim\u00e9nez bate\u00f3 de 3-1, con doble y cuatro empujadas, y Liberato, de 3-1, con doble, anotada y boleto. AGUILAS 8 GIGANTES 7 &nbsp;SANTIAGO DE LOS CABALLEROS.- Las \u00c1guilas Cibae\u00f1as tuvieron un s\u00e9ptimo episodio de tres jonrones y Julio E. Rodr\u00edguez dispar\u00f3 un sencillo con las bases congestionadas para darle el triunfo en 10 entradas 8-7 a las \u00c1guilas Cibae\u00f1as sobre los Gigantes del Cibao. Con la derrota de los Toros del Este (3-2) ante los Leones del Escogido (5-0) ahora las \u00c1guilas, que comienzan bien el a\u00f1o, se ponen a un juego en esta semifinal round robin que retorna despu\u00e9s de la pausa de fin de a\u00f1o. Las \u00c1guilas se recuperaron de un rally de cinco vueltas de los Gigantes en el octavo, adem\u00e1s de que tambi\u00e9n vieron a los macorisanos irse delante 7-6 en la alta del cap\u00edtulo 10. Adisyn Coffey tuvo problemas en el d\u00e9cimo y adem\u00e1s de permitir la del empate le dej\u00f3 una herencia negativa a Bryan Rodr\u00edguez al encontrar las bases llenas. Fue entonces cuando lleg\u00f3 el hit decisivo de Rodr\u00edguez en un cap\u00edtulo de dos carreras para las rapaces que se ponen con 2-3 al dejar en el terreno a los francomacorisanos que a\u00fan no consiguen ganar en cinco juegos. La particularidad de los jonrones de Clase y Encarnaci\u00f3n es que fue abriendo la baja del s\u00e9ptimo y ambos al primer lanzamiento servido por el relevista Reymin Gudu\u00e1n. El palo de Encarnaci\u00f3n sali\u00f3 por encima del pared\u00f3n (385) verde del Estadio Cibao. El bambinazo de Berroa, por el prado izquierdo, lleg\u00f3 despu\u00e9s de dos outs, calculado en 376 pies. La victoria fue para Yoan L\u00f3pez (2-0) y perdi\u00f3 Coffey. POSICIONES ROUND ROBIN EQUIPO J G P PCT DIF RACHA 5 5 0 1.000 \u2013 W5 5 3 2 .600 2 L1 5 2 3 .400 3 W1 5 0 5 .000 5 L5 of-am<\/p>\n","protected":false},"author":9,"featured_media":109392,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-109391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109391"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109391\/revisions"}],"predecessor-version":[{"id":109393,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109391\/revisions\/109393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109392"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}