{"id":109486,"date":"2026-01-08T08:14:36","date_gmt":"2026-01-08T12:14:36","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109486"},"modified":"2026-01-08T08:14:40","modified_gmt":"2026-01-08T12:14:40","slug":"eeuu-ordena-retirada-de-66-entidades-casi-la-mitad-en-onu","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eeuu-ordena-retirada-de-66-entidades-casi-la-mitad-en-onu\/","title":{"rendered":"EEUU ordena \u00abretirada\u00bb de 66 entidades, casi la mitad en ONU"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/ee-uu-onu-1024x576.jpg\" alt=\"\" class=\"wp-image-109487\" style=\"width:286px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/ee-uu-onu-1024x576.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/ee-uu-onu-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/ee-uu-onu-768x432.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/ee-uu-onu.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">WASHINGTON 8 Ene.-&nbsp;El inquilino de la Casa Blanca, Donald Trump, ha ordenado este mi\u00e9rcoles la \u00abretirada\u00bb de Estados Unidos de 66 organizaciones internacionales, incluidas una treintena de entidades de la ONU a las que acusa de actuar contra los intereses del pa\u00eds norteamericano en cuestiones relaciones con su seguridad, econom\u00eda o soberan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo recoge un memor\u00e1ndo firmado por el mandatario que obliga a \u00abtodos\u00bb los Departamentos y agencias a no \u00abparticipar\u00bb ni financiar a 31 organizaciones de Naciones Unidas y otras 35 no pertenecientes al organismo multilateral, sin aportar nombres, alegando que \u00aboperan en contra de los interes nacionales, la prosperidad econ\u00f3mica o la soberan\u00eda de Estados Unidos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La medida, se\u00f1ala el escrito, impedir\u00e1 que el dinero de los contribuyentes acabe en entidades que \u00abpromueven agendas globalistas por encima de las prioridades estadounidenses o que abordan cuestiones importantes de manera ineficaz o ineficiente\u00bb, sino que \u00e9ste se asignar\u00e1 \u00abmejor de otras maneras para apoyar las misiones pertinentes\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta l\u00ednea, Trump denuncia que las organizaciones afectadas \u00absocavan la independencia\u00bb de Washington, en particular, al promover \u00abpol\u00edticas clim\u00e1ticas radicales, gobernanza global y programas ideol\u00f3gicos que entran en conflicto con la soberan\u00eda y la fortaleza econ\u00f3mica de Estados Unidos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLos contribuyentes estadounidenses han gastado miles de millones en estas organizaciones con escasos resultados, mientras que estas suelen criticar las pol\u00edticas de Estados Unidos (\u2026) Al abandonar estas entidades, el presidente Trump est\u00e1 ahorrando dinero a los contribuyentes y reorientando los recursos hacia las prioridades de \u2018America First\u2019 (Estados Unidos primero)\u00bb, agrega el documento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El texto recuerda que la Administraci\u00f3n Trump ya orden\u00f3 la retirada del Acuerdo Clim\u00e1tico de Par\u00eds y del Consejo de Derechos Humanos de Naciones Unidas (CDHNU) y prohibi\u00f3 cualquier financiaci\u00f3n futura para la Agencia de Naciones Unidas para los Refugiados de Palestina en Oriente Pr\u00f3ximo (UNRWA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OF-AM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON 8 Ene.-&nbsp;El inquilino de la Casa Blanca, Donald Trump, ha ordenado este mi\u00e9rcoles la \u00abretirada\u00bb de Estados Unidos de 66 organizaciones internacionales, incluidas una treintena de entidades de la ONU a las que acusa de actuar contra los intereses del pa\u00eds norteamericano en cuestiones relaciones con su seguridad, econom\u00eda o soberan\u00eda. As\u00ed lo recoge un memor\u00e1ndo firmado por el mandatario que obliga a \u00abtodos\u00bb los Departamentos y agencias a no \u00abparticipar\u00bb ni financiar a 31 organizaciones de Naciones Unidas y otras 35 no pertenecientes al organismo multilateral, sin aportar nombres, alegando que \u00aboperan en contra de los interes nacionales, la prosperidad econ\u00f3mica o la soberan\u00eda de Estados Unidos\u00bb. La medida, se\u00f1ala el escrito, impedir\u00e1 que el dinero de los contribuyentes acabe en entidades que \u00abpromueven agendas globalistas por encima de las prioridades estadounidenses o que abordan cuestiones importantes de manera ineficaz o ineficiente\u00bb, sino que \u00e9ste se asignar\u00e1 \u00abmejor de otras maneras para apoyar las misiones pertinentes\u00bb. En esta l\u00ednea, Trump denuncia que las organizaciones afectadas \u00absocavan la independencia\u00bb de Washington, en particular, al promover \u00abpol\u00edticas clim\u00e1ticas radicales, gobernanza global y programas ideol\u00f3gicos que entran en conflicto con la soberan\u00eda y la fortaleza econ\u00f3mica de Estados Unidos\u00bb. \u00abLos contribuyentes estadounidenses han gastado miles de millones en estas organizaciones con escasos resultados, mientras que estas suelen criticar las pol\u00edticas de Estados Unidos (\u2026) Al abandonar estas entidades, el presidente Trump est\u00e1 ahorrando dinero a los contribuyentes y reorientando los recursos hacia las prioridades de \u2018America First\u2019 (Estados Unidos primero)\u00bb, agrega el documento. El texto recuerda que la Administraci\u00f3n Trump ya orden\u00f3 la retirada del Acuerdo Clim\u00e1tico de Par\u00eds y del Consejo de Derechos Humanos de Naciones Unidas (CDHNU) y prohibi\u00f3 cualquier financiaci\u00f3n futura para la Agencia de Naciones Unidas para los Refugiados de Palestina en Oriente Pr\u00f3ximo (UNRWA). OF-AM<\/p>\n","protected":false},"author":9,"featured_media":109487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-109486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109486"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109486\/revisions"}],"predecessor-version":[{"id":109488,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109486\/revisions\/109488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109487"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}