{"id":109694,"date":"2026-01-16T06:35:50","date_gmt":"2026-01-16T10:35:50","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109694"},"modified":"2026-01-16T06:35:52","modified_gmt":"2026-01-16T10:35:52","slug":"delcy-acusa-ee-uu-de-impedir-a-venezuela-vender-su-petroleo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/delcy-acusa-ee-uu-de-impedir-a-venezuela-vender-su-petroleo\/","title":{"rendered":"Delcy acusa EE.UU de impedir a Venezuela vender su petr\u00f3leo"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/Delcy-Rodriguez-1-300x206-1.jpg\" alt=\"\" class=\"wp-image-109695\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/Delcy-Rodriguez-1-300x206-1.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/Delcy-Rodriguez-1-300x206-1-75x52.jpg 75w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Caracas (EFE).- La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, acus\u00f3 este jueves a Estados Unidos de cercar las posibilidades del pa\u00eds suramericano de vender los productos de su industria petrolera en el exterior tras un \u00abbloqueo naval\u00bb previo a la captura del mandatario Nicol\u00e1s Maduro el 3 de enero por tropas estadounidenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQuiero empezar pidiendo amablemente de parte de todos los presentes un minuto de aplauso para nuestros j\u00f3venes h\u00e9roes y hero\u00ednas que murieron en combate contra el agresor invasor\u00bb, dijo la funcionaria, en referencia a EE.UU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, pidi\u00f3 \u00abhonor y gloria\u00bb a los \u00abj\u00f3venes humildes venezolanos y venezolanas que combatieron en la madrugada tan oscura de ese 3 de enero\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la rendici\u00f3n de cuentas en nombre de Maduro, Rodr\u00edguez asegur\u00f3 que hay un plan para este nuevo a\u00f1o, pese al \u00abbloqueo naval\u00bb que, asegur\u00f3, ha buscado cercar las posibilidades de Venezuela de exportar en \u00abrelaciones libres, comerciales con el mundo\u00bb su crudo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo es que la presidenta encargada tiene miedo porque est\u00e1 amenazada. No. Venezuela toda est\u00e1 amenazada (\u2026). Si alg\u00fan d\u00eda me tocase, como presidenta encargada, ir a Washington lo har\u00e9 de pie, caminando, no arrastrada. Lo har\u00e9 con la bandera tricolor\u00bb, manifest\u00f3 Rodr\u00edguez en la redici\u00f3n de la memoria y cuenta en nombre de Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La industria petrolera venezolana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria tambi\u00e9n acus\u00f3 a Estados Unidos de limitar las posibilidades del pa\u00eds suramericano de vender los productos de su industria petrolera en el exterior tras el \u00abbloqueo naval\u00bb que asegura se dio previo a la captura de Maduro con el despliegue militar en aguas internacionales del Caribe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rodr\u00edguez asegur\u00f3 que hay un plan para este nuevo a\u00f1o, pese al \u00abbloqueo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En diciembre pasado, Estados Unidos dio la orden de confiscar buques petroleros sancionados que entren y salgan desde Venezuela lo que, a juicio de Rodr\u00edguez, fue un paso previo para la captura de Maduro y su esposa, Cilia Flores, tras un ataque militar a Caracas y otras regiones de Venezuela el pasado 3 de enero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">an\/am<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caracas (EFE).- La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, acus\u00f3 este jueves a Estados Unidos de cercar las posibilidades del pa\u00eds suramericano de vender los productos de su industria petrolera en el exterior tras un \u00abbloqueo naval\u00bb previo a la captura del mandatario Nicol\u00e1s Maduro el 3 de enero por tropas estadounidenses. \u00abQuiero empezar pidiendo amablemente de parte de todos los presentes un minuto de aplauso para nuestros j\u00f3venes h\u00e9roes y hero\u00ednas que murieron en combate contra el agresor invasor\u00bb, dijo la funcionaria, en referencia a EE.UU. Adem\u00e1s, pidi\u00f3 \u00abhonor y gloria\u00bb a los \u00abj\u00f3venes humildes venezolanos y venezolanas que combatieron en la madrugada tan oscura de ese 3 de enero\u00bb. En la rendici\u00f3n de cuentas en nombre de Maduro, Rodr\u00edguez asegur\u00f3 que hay un plan para este nuevo a\u00f1o, pese al \u00abbloqueo naval\u00bb que, asegur\u00f3, ha buscado cercar las posibilidades de Venezuela de exportar en \u00abrelaciones libres, comerciales con el mundo\u00bb su crudo. \u00abNo es que la presidenta encargada tiene miedo porque est\u00e1 amenazada. No. Venezuela toda est\u00e1 amenazada (\u2026). Si alg\u00fan d\u00eda me tocase, como presidenta encargada, ir a Washington lo har\u00e9 de pie, caminando, no arrastrada. Lo har\u00e9 con la bandera tricolor\u00bb, manifest\u00f3 Rodr\u00edguez en la redici\u00f3n de la memoria y cuenta en nombre de Maduro. La industria petrolera venezolana La mandataria tambi\u00e9n acus\u00f3 a Estados Unidos de limitar las posibilidades del pa\u00eds suramericano de vender los productos de su industria petrolera en el exterior tras el \u00abbloqueo naval\u00bb que asegura se dio previo a la captura de Maduro con el despliegue militar en aguas internacionales del Caribe. Rodr\u00edguez asegur\u00f3 que hay un plan para este nuevo a\u00f1o, pese al \u00abbloqueo\u00bb. En diciembre pasado, Estados Unidos dio la orden de confiscar buques petroleros sancionados que entren y salgan desde Venezuela lo que, a juicio de Rodr\u00edguez, fue un paso previo para la captura de Maduro y su esposa, Cilia Flores, tras un ataque militar a Caracas y otras regiones de Venezuela el pasado 3 de enero. an\/am<\/p>\n","protected":false},"author":9,"featured_media":109695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-109694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109694"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109694\/revisions"}],"predecessor-version":[{"id":109696,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109694\/revisions\/109696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109695"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}