{"id":109708,"date":"2026-01-17T07:47:45","date_gmt":"2026-01-17T11:47:45","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109708"},"modified":"2026-01-17T07:47:46","modified_gmt":"2026-01-17T11:47:46","slug":"delcy-nombra-nuevos-titulares-de-tres-ministerios-venezuela","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/delcy-nombra-nuevos-titulares-de-tres-ministerios-venezuela\/","title":{"rendered":"Delcy nombra nuevos titulares de tres ministerios Venezuela"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"594\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/IMG_9534-1024x594.jpeg\" alt=\"\" class=\"wp-image-109709\" style=\"aspect-ratio:1.7225800249927905;width:304px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/IMG_9534-1024x594.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/IMG_9534-300x174.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/IMG_9534-768x446.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/IMG_9534.jpeg 1223w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">CARACAS,17 Ene. (EUROPA PRESS) -La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, ha designado este viernes nuevos titulares para las carteras de Comunicaci\u00f3n e Informaci\u00f3n, Transporte y Ecosocialismo del Ejecutivo venezolano, despu\u00e9s de anunciar esta misma semana un \u00abnuevo momento pol\u00edtico\u00bb en el pa\u00eds latinoamericano, abogando por el \u00abentendimiento\u00bb tras la detenci\u00f3n de Nicol\u00e1s Maduro, capturado el pasado 3 de enero en un ataque de Estados Unidos sobre Caracas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abInformo al pa\u00eds que he designado al VA An\u00edbal Coronado como nuevo Ministro del Poder Popular para el Transporte. Agradecemos el compromiso y el trabajo del compa\u00f1ero Ram\u00f3n Vel\u00e1squez Araguay\u00e1n, quien ha estado al frente de esta cartera ministerial\u00bb, ha comunicado en la primera de una serie de publicaciones compartidas en redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siguiendo la misma f\u00f3rmula, Rodr\u00edguez ha revelado que la cartera de Ecosocialismo pasar\u00e1 a ser dirigida por Freddy \u00d1\u00e1\u00f1ez, a quien ha encomendado \u00abla labor de seguir impulsando las pol\u00edticas p\u00fablicas para la protecci\u00f3n de (la) Pachamama y todo lo relacionado en materia ambiental\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, la presidenta encargada ha escogido al fil\u00f3sofo, escritor y comunicador Miguel P\u00e9rez Pirela como ministro del Poder Popular para la Comunicaci\u00f3n e Informaci\u00f3n. \u00abSu formaci\u00f3n acad\u00e9mica, experiencia y convicci\u00f3n seguir\u00e1n fortaleciendo la batalla comunicacional en defensa de la verdad de Venezuela\u00bb, ha argumentado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este anuncio llega despu\u00e9s de que la propia Rodr\u00edguez augurase este mi\u00e9rcoles la entrada del pa\u00eds en un \u00abnuevo momento pol\u00edtico\u00bb con el prop\u00f3sito de \u00ababrir espacios pol\u00edticos\u00bb, subrayando que este \u00abfue el objetivo que se traz\u00f3 el presidente Nicol\u00e1s Maduro en diciembre de 2025, cuando procedieron 194 liberaciones\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CARACAS,17 Ene. (EUROPA PRESS) -La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, ha designado este viernes nuevos titulares para las carteras de Comunicaci\u00f3n e Informaci\u00f3n, Transporte y Ecosocialismo del Ejecutivo venezolano, despu\u00e9s de anunciar esta misma semana un \u00abnuevo momento pol\u00edtico\u00bb en el pa\u00eds latinoamericano, abogando por el \u00abentendimiento\u00bb tras la detenci\u00f3n de Nicol\u00e1s Maduro, capturado el pasado 3 de enero en un ataque de Estados Unidos sobre Caracas. \u00abInformo al pa\u00eds que he designado al VA An\u00edbal Coronado como nuevo Ministro del Poder Popular para el Transporte. Agradecemos el compromiso y el trabajo del compa\u00f1ero Ram\u00f3n Vel\u00e1squez Araguay\u00e1n, quien ha estado al frente de esta cartera ministerial\u00bb, ha comunicado en la primera de una serie de publicaciones compartidas en redes sociales. Siguiendo la misma f\u00f3rmula, Rodr\u00edguez ha revelado que la cartera de Ecosocialismo pasar\u00e1 a ser dirigida por Freddy \u00d1\u00e1\u00f1ez, a quien ha encomendado \u00abla labor de seguir impulsando las pol\u00edticas p\u00fablicas para la protecci\u00f3n de (la) Pachamama y todo lo relacionado en materia ambiental\u00bb. Por \u00faltimo, la presidenta encargada ha escogido al fil\u00f3sofo, escritor y comunicador Miguel P\u00e9rez Pirela como ministro del Poder Popular para la Comunicaci\u00f3n e Informaci\u00f3n. \u00abSu formaci\u00f3n acad\u00e9mica, experiencia y convicci\u00f3n seguir\u00e1n fortaleciendo la batalla comunicacional en defensa de la verdad de Venezuela\u00bb, ha argumentado. Este anuncio llega despu\u00e9s de que la propia Rodr\u00edguez augurase este mi\u00e9rcoles la entrada del pa\u00eds en un \u00abnuevo momento pol\u00edtico\u00bb con el prop\u00f3sito de \u00ababrir espacios pol\u00edticos\u00bb, subrayando que este \u00abfue el objetivo que se traz\u00f3 el presidente Nicol\u00e1s Maduro en diciembre de 2025, cuando procedieron 194 liberaciones\u00bb.<\/p>\n","protected":false},"author":9,"featured_media":109709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-109708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109708"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109708\/revisions"}],"predecessor-version":[{"id":109710,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109708\/revisions\/109710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109709"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}