{"id":109765,"date":"2026-01-21T08:11:16","date_gmt":"2026-01-21T12:11:16","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109765"},"modified":"2026-01-21T08:11:17","modified_gmt":"2026-01-21T12:11:17","slug":"avion-de-trump-reporta-falla-y-regresa-a-eu-tras-salida-hacia-davos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/avion-de-trump-reporta-falla-y-regresa-a-eu-tras-salida-hacia-davos\/","title":{"rendered":"Avi\u00f3n de Trump reporta falla y regresa a EU tras salida hacia Davos"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"835\" height=\"512\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/w3oa11rf.png\" alt=\"\" class=\"wp-image-109766\" style=\"width:294px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/w3oa11rf.png 835w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/w3oa11rf-300x184.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/w3oa11rf-768x471.png 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/01\/w3oa11rf-440x270.png 440w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">WASHINGTON.- El avi\u00f3n del presidente de Estados Unidos, Donald Trump, sufri\u00f3 una falla tras despegar hacia Suiza para asistir al Foro Econ\u00f3mico Mundial de Davos, inform\u00f3 este martes la Casa Blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trat\u00f3 de un \u00abproblema el\u00e9ctrico menor\u00bb, precis\u00f3 la administraci\u00f3n. Por precauci\u00f3n, el Air Force 1 volver\u00e1 a la Base Conjunta Andrews en Maryland.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl presidente y su equipo abordar\u00e1n otro avi\u00f3n y continuar\u00e1n su viaje hacia Suiza\u00bb, concluy\u00f3 la Casa Blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Casa Blanca cit\u00f3 una grabaci\u00f3n de la conversaci\u00f3n entre los controladores y la tripulaci\u00f3n del Boeing presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 se sabe sobre el Air Force One?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los dos aviones que se utilizan actualmente como Air Force 1 llevan casi cuatro d\u00e9cadas en actividad. Boeing ha estado trabajando en su sustituci\u00f3n, pero el programa ha sufrido una serie de retrasos, seg\u00fan informa Fox News.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Air Force 1 debe tener cuatro motores, a diferencia de la mayor\u00eda de los actuales aviones de pasajeros, que tienen dos. Est\u00e1n equipados con capacidad de reabastecimiento en vuelo, para poder volar todo el tiempo que sea necesario. Adem\u00e1s, ha sido dise\u00f1ado para los peores escenarios posibles, como una guerra nuclear, de modo que el presidente pueda seguir dirigiendo las fuerzas militares desde el cielo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o pasado, Catar le regal\u00f3 a Trump un lujoso jet Boeing 747-8 para a\u00f1adirlo a la flota del Air Force 1, un obsequio que fue objeto de gran escrutinio. Ese avi\u00f3n est\u00e1 siendo actualmente remodelado para cumplir con los requisitos de seguridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON.- El avi\u00f3n del presidente de Estados Unidos, Donald Trump, sufri\u00f3 una falla tras despegar hacia Suiza para asistir al Foro Econ\u00f3mico Mundial de Davos, inform\u00f3 este martes la Casa Blanca. Se trat\u00f3 de un \u00abproblema el\u00e9ctrico menor\u00bb, precis\u00f3 la administraci\u00f3n. Por precauci\u00f3n, el Air Force 1 volver\u00e1 a la Base Conjunta Andrews en Maryland. \u00abEl presidente y su equipo abordar\u00e1n otro avi\u00f3n y continuar\u00e1n su viaje hacia Suiza\u00bb, concluy\u00f3 la Casa Blanca. La Casa Blanca cit\u00f3 una grabaci\u00f3n de la conversaci\u00f3n entre los controladores y la tripulaci\u00f3n del Boeing presidencial. \u00bfQu\u00e9 se sabe sobre el Air Force One? Los dos aviones que se utilizan actualmente como Air Force 1 llevan casi cuatro d\u00e9cadas en actividad. Boeing ha estado trabajando en su sustituci\u00f3n, pero el programa ha sufrido una serie de retrasos, seg\u00fan informa Fox News. El Air Force 1 debe tener cuatro motores, a diferencia de la mayor\u00eda de los actuales aviones de pasajeros, que tienen dos. Est\u00e1n equipados con capacidad de reabastecimiento en vuelo, para poder volar todo el tiempo que sea necesario. Adem\u00e1s, ha sido dise\u00f1ado para los peores escenarios posibles, como una guerra nuclear, de modo que el presidente pueda seguir dirigiendo las fuerzas militares desde el cielo. El a\u00f1o pasado, Catar le regal\u00f3 a Trump un lujoso jet Boeing 747-8 para a\u00f1adirlo a la flota del Air Force 1, un obsequio que fue objeto de gran escrutinio. Ese avi\u00f3n est\u00e1 siendo actualmente remodelado para cumplir con los requisitos de seguridad.<\/p>\n","protected":false},"author":9,"featured_media":109766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-109765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109765"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109765\/revisions"}],"predecessor-version":[{"id":109767,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109765\/revisions\/109767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109766"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}