{"id":110028,"date":"2026-02-06T07:58:44","date_gmt":"2026-02-06T11:58:44","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=110028"},"modified":"2026-02-06T07:58:47","modified_gmt":"2026-02-06T11:58:47","slug":"piden-hasta-20-anos-para-adan-caceres-y-otros-por-caso-fraude","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/piden-hasta-20-anos-para-adan-caceres-y-otros-por-caso-fraude\/","title":{"rendered":"Piden hasta 20 a\u00f1os para Ad\u00e1n C\u00e1ceres y otros por caso fraude"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/02\/Juicio-Adan-Caceres-300x199-1.jpg\" alt=\"\" class=\"wp-image-110029\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO (Rep\u00fablica Dominicana).-<\/strong>&nbsp;El Ministerio P\u00fablico solicit\u00f3 este jueves al Primer Tribunal Colegiado del Distrito Nacional penas de 20 a\u00f1os de prisi\u00f3n y multas de 400 salarios m\u00ednimos a&nbsp;<strong>los generales Ad\u00e1n Benoni C\u00e1ceres Silvestre, Juan Carlos Torres Robiou y Julio Camilo De los Santos Viola,<\/strong>&nbsp;procesados por un entramado de corrupci\u00f3n que supuestamente defraud\u00f3 al Estado con m\u00e1s de RD$4,500 millones durante el pasado gobierno de Danilo Medina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los fiscales, encabezados por la procuradora de corte Mirna Ortiz, titular de la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (Pepca), solicitaron la misma pena para los acusados&nbsp;<strong>coronel Rafael N\u00fa\u00f1ez de Aza, general Boanerges Reyes Batista y capit\u00e1n Franklin Antonio Mata Flores.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>15 A\u00d1OS PARA LA \u201cPASTORA\u201d y OTROS DOS &nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n solicitaron 15 a\u00f1os de prisi\u00f3n y el pago de 300 salarios m\u00ednimos para la procesada Rossy Maybelline Guzm\u00e1n S\u00e1nchez (la Pastora), Kelman Santana Mart\u00ednez y Pedro Roberto Castillo Nolasco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DIEZ Y 5 A\u00d1OS PARA EL RESTO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico solicit\u00f3, asimismo, la imposici\u00f3n de&nbsp; diez a\u00f1os de prisi\u00f3n y multas de 200 salarios para Yehudy Blandesmil Guzm\u00e1n Alc\u00e1ntara, para el cabo policial Tanner Antonio Flete Guzm\u00e1n, Erasmo Roger P\u00e9rez N\u00fa\u00f1ez, Jos\u00e9 Manuel Rosario Pir\u00f3n, Jehohanan Luc\u00eda Rodr\u00edguez Jim\u00e9nez, Guillermo de Jes\u00fas Torres Robiou, Esmeralda Ortega Polanco, al sargento Alejandro Jos\u00e9 Montero Cruz, Epifanio Pe\u00f1a Lebr\u00f3n, Luc\u00eda De los Santos Viola, Manuel de Jes\u00fas Alba Solano, Elida Mar\u00eda Trinidad Santiago, Enmanuel Antonio Alba Trinidad, Raymel Pastor del Rosario Viola, Onoris Beatriz Soto De los Santos y Eric Daniel Pereyra N\u00fa\u00f1ez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, 5 a\u00f1os de prisi\u00f3n para el mayor Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez (multa de 200 salarios m\u00ednimos), Carlos Augusto Lantigua Cruz (multa de 500 mil pesos) y Miguel Ventura (multa de RD$500 mil).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHemos tenido largas jornadas en este tribunal y, tal y como le dijimos a las juzgadoras desde el primer d\u00eda que demostrar\u00edamos cada una de las imputaciones, as\u00ed lo hemos hecho\u201d, dijo Ortiz, al responder a la prensa a su salida de la audiencia celebrada en el Palacio de Justicia de Ciudad Nueva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon cada elemento probatorio, con cada testimonio, con cada documento, con cada pericia, hemos demostrado todos los puntos de nuestra acusaci\u00f3n\u201d, a\u00f1adi\u00f3\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn esa virtud hemos solicitado las condenas, condenas que van desde 5 hasta 20 a\u00f1os, todas dentro de las escalas legales y conforme a la participaci\u00f3n de los imputados, por lo que no tenemos ninguna duda de que este tribunal dar\u00e1 a cada imputado las penas solicitadas por el Ministerio P\u00fablico por ser justas y ajustarse en todo momento a los par\u00e1metros legales\u201d, precis\u00f3 la titular de la Pepca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ORGANISMOS DONDE FUE COMETIDO EL FRAUDE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los RD$4,500 millones habr\u00edan sido sustra\u00eddos del Cuerpo de Seguridad Presidencial (Cusep), del Cuerpo de Seguridad Tur\u00edstica (Cestur) y del Consejo Nacional para la Ni\u00f1ez y Adolescencia (Conani).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ad\u00e1n C\u00e1ceres fue jefe del Cuerpo Especializado de Seguridad Presidencial (CUSEP) durante los gobiernos de Medina, de cuya protecci\u00f3n estuvo encargado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tribunal fij\u00f3 la continuaci\u00f3n de la audiencia para el pr\u00f3ximo martes 10 del mes en curso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su pedimiento, el Ministerio P\u00fablico, representado por Ortiz junto a los fiscales Jonathan P\u00e9rez Fulcar, Emmanuel Ram\u00edrez, Arolin Lemos, Miguel Collado y Melbin Romero, solicita la clausura, suspensi\u00f3n de operaciones y disoluci\u00f3n de la entidad Iglesia Bautista Vida Eterna y la imposici\u00f3n de una multa de 200 salarios m\u00ednimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, para las compa\u00f1\u00edas Hacienda Kelman SRL, R&amp;F Agroindustrial, Aldom Glass Aluminium, SRL, Randa Internacional Company y CSNA Universo Empresarial S.R.L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la disoluci\u00f3n e imposici\u00f3n de una multa de 10 millones de pesos de la raz\u00f3n social Rawel Importadores S.R.L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DECOMISO DE BIENES INCAUTADOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico tambi\u00e9n solicit\u00f3 el decomiso de los bienes incautados, entre los cuales se incluyen villas, casas y veh\u00edculos de lujo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RECONOCEN \u201cCOOPERACI\u00d3N\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al imputado Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez, en base a la cooperaci\u00f3n efectiva que ha realizado con el Ministerio P\u00fablico, el \u00f3rgano persecutor solicit\u00f3 a las juezas del Primer Tribunal Colegiado, Giselle M\u00e9ndez (presidenta), Jissel Naranjo y Tania Yunes, tomar en consideraci\u00f3n el tiempo que lleva el imputado guardando prisi\u00f3n conforme al arresto domiciliario para que esta pena sea computada como cumplida y lo restante sea de manera suspendida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello, piden que la pena se cumpla bajo la regla de recibir en un domicilio fijo aportado a este tribunal, abstenerse del porte y tenencia de armas de fuego y presentarse una vez al mes ante el juez de ejecuci\u00f3n de la pena para dar fe del cumplimiento de las medidas requeridas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRUEBAS PRESENTADAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las pruebas presentadas por el Ministerio P\u00fablico durante el proceso judicial se incluyen 2,201 pruebas documentales, 141 peritajes, 282 declaraciones de testigos y peritos, 184 pruebas procesales y 104 pruebas materiales, como armas de fuego, relojes de lujo, equipos electr\u00f3nicos, inmuebles, veh\u00edculos y dinero en efectivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se identificaron 214 inmuebles en distintas provincias, 86 veh\u00edculos de alto cilindraje y m\u00e1s de RD$28 millones y US$55 mil en efectivo, todos solicitados en decomiso. Los bienes incautados han generado ingresos por concepto de alquileres y producci\u00f3n agr\u00edcola que ascienden a m\u00e1s de RD$86 millones, tambi\u00e9n reclamados a favor del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>30 PERSONAS F\u00cdSICAS Y 18 JUR\u00cdDICAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico acusa a C\u00e1ceres Silvestre de encabezar la red compuesta por 30 personas f\u00edsicas y 18 jur\u00eddicas, que oper\u00f3 entre 2012 y 2020, desviando fondos p\u00fablicos del Cuerpo de Seguridad Presidencial (Cusep) y del Cuerpo Especializado de Seguridad Tur\u00edstica (Cestur), as\u00ed como del Consejo Nacional para la Ni\u00f1ez y la Adolescencia (Conani).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO (Rep\u00fablica Dominicana).-&nbsp;El Ministerio P\u00fablico solicit\u00f3 este jueves al Primer Tribunal Colegiado del Distrito Nacional penas de 20 a\u00f1os de prisi\u00f3n y multas de 400 salarios m\u00ednimos a&nbsp;los generales Ad\u00e1n Benoni C\u00e1ceres Silvestre, Juan Carlos Torres Robiou y Julio Camilo De los Santos Viola,&nbsp;procesados por un entramado de corrupci\u00f3n que supuestamente defraud\u00f3 al Estado con m\u00e1s de RD$4,500 millones durante el pasado gobierno de Danilo Medina. Los fiscales, encabezados por la procuradora de corte Mirna Ortiz, titular de la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (Pepca), solicitaron la misma pena para los acusados&nbsp;coronel Rafael N\u00fa\u00f1ez de Aza, general Boanerges Reyes Batista y capit\u00e1n Franklin Antonio Mata Flores. 15 A\u00d1OS PARA LA \u201cPASTORA\u201d y OTROS DOS &nbsp; Tambi\u00e9n solicitaron 15 a\u00f1os de prisi\u00f3n y el pago de 300 salarios m\u00ednimos para la procesada Rossy Maybelline Guzm\u00e1n S\u00e1nchez (la Pastora), Kelman Santana Mart\u00ednez y Pedro Roberto Castillo Nolasco. DIEZ Y 5 A\u00d1OS PARA EL RESTO El Ministerio P\u00fablico solicit\u00f3, asimismo, la imposici\u00f3n de&nbsp; diez a\u00f1os de prisi\u00f3n y multas de 200 salarios para Yehudy Blandesmil Guzm\u00e1n Alc\u00e1ntara, para el cabo policial Tanner Antonio Flete Guzm\u00e1n, Erasmo Roger P\u00e9rez N\u00fa\u00f1ez, Jos\u00e9 Manuel Rosario Pir\u00f3n, Jehohanan Luc\u00eda Rodr\u00edguez Jim\u00e9nez, Guillermo de Jes\u00fas Torres Robiou, Esmeralda Ortega Polanco, al sargento Alejandro Jos\u00e9 Montero Cruz, Epifanio Pe\u00f1a Lebr\u00f3n, Luc\u00eda De los Santos Viola, Manuel de Jes\u00fas Alba Solano, Elida Mar\u00eda Trinidad Santiago, Enmanuel Antonio Alba Trinidad, Raymel Pastor del Rosario Viola, Onoris Beatriz Soto De los Santos y Eric Daniel Pereyra N\u00fa\u00f1ez. Adem\u00e1s, 5 a\u00f1os de prisi\u00f3n para el mayor Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez (multa de 200 salarios m\u00ednimos), Carlos Augusto Lantigua Cruz (multa de 500 mil pesos) y Miguel Ventura (multa de RD$500 mil). \u201cHemos tenido largas jornadas en este tribunal y, tal y como le dijimos a las juzgadoras desde el primer d\u00eda que demostrar\u00edamos cada una de las imputaciones, as\u00ed lo hemos hecho\u201d, dijo Ortiz, al responder a la prensa a su salida de la audiencia celebrada en el Palacio de Justicia de Ciudad Nueva. \u201cCon cada elemento probatorio, con cada testimonio, con cada documento, con cada pericia, hemos demostrado todos los puntos de nuestra acusaci\u00f3n\u201d, a\u00f1adi\u00f3\u201d. \u201cEn esa virtud hemos solicitado las condenas, condenas que van desde 5 hasta 20 a\u00f1os, todas dentro de las escalas legales y conforme a la participaci\u00f3n de los imputados, por lo que no tenemos ninguna duda de que este tribunal dar\u00e1 a cada imputado las penas solicitadas por el Ministerio P\u00fablico por ser justas y ajustarse en todo momento a los par\u00e1metros legales\u201d, precis\u00f3 la titular de la Pepca. ORGANISMOS DONDE FUE COMETIDO EL FRAUDE Los RD$4,500 millones habr\u00edan sido sustra\u00eddos del Cuerpo de Seguridad Presidencial (Cusep), del Cuerpo de Seguridad Tur\u00edstica (Cestur) y del Consejo Nacional para la Ni\u00f1ez y Adolescencia (Conani). Ad\u00e1n C\u00e1ceres fue jefe del Cuerpo Especializado de Seguridad Presidencial (CUSEP) durante los gobiernos de Medina, de cuya protecci\u00f3n estuvo encargado. El tribunal fij\u00f3 la continuaci\u00f3n de la audiencia para el pr\u00f3ximo martes 10 del mes en curso. En su pedimiento, el Ministerio P\u00fablico, representado por Ortiz junto a los fiscales Jonathan P\u00e9rez Fulcar, Emmanuel Ram\u00edrez, Arolin Lemos, Miguel Collado y Melbin Romero, solicita la clausura, suspensi\u00f3n de operaciones y disoluci\u00f3n de la entidad Iglesia Bautista Vida Eterna y la imposici\u00f3n de una multa de 200 salarios m\u00ednimos. Tambi\u00e9n, para las compa\u00f1\u00edas Hacienda Kelman SRL, R&amp;F Agroindustrial, Aldom Glass Aluminium, SRL, Randa Internacional Company y CSNA Universo Empresarial S.R.L. Asimismo, la disoluci\u00f3n e imposici\u00f3n de una multa de 10 millones de pesos de la raz\u00f3n social Rawel Importadores S.R.L. DECOMISO DE BIENES INCAUTADOS El Ministerio P\u00fablico tambi\u00e9n solicit\u00f3 el decomiso de los bienes incautados, entre los cuales se incluyen villas, casas y veh\u00edculos de lujo. RECONOCEN \u201cCOOPERACI\u00d3N\u201d En cuanto al imputado Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez, en base a la cooperaci\u00f3n efectiva que ha realizado con el Ministerio P\u00fablico, el \u00f3rgano persecutor solicit\u00f3 a las juezas del Primer Tribunal Colegiado, Giselle M\u00e9ndez (presidenta), Jissel Naranjo y Tania Yunes, tomar en consideraci\u00f3n el tiempo que lleva el imputado guardando prisi\u00f3n conforme al arresto domiciliario para que esta pena sea computada como cumplida y lo restante sea de manera suspendida. Para ello, piden que la pena se cumpla bajo la regla de recibir en un domicilio fijo aportado a este tribunal, abstenerse del porte y tenencia de armas de fuego y presentarse una vez al mes ante el juez de ejecuci\u00f3n de la pena para dar fe del cumplimiento de las medidas requeridas. PRUEBAS PRESENTADAS Entre las pruebas presentadas por el Ministerio P\u00fablico durante el proceso judicial se incluyen 2,201 pruebas documentales, 141 peritajes, 282 declaraciones de testigos y peritos, 184 pruebas procesales y 104 pruebas materiales, como armas de fuego, relojes de lujo, equipos electr\u00f3nicos, inmuebles, veh\u00edculos y dinero en efectivo. Adem\u00e1s, se identificaron 214 inmuebles en distintas provincias, 86 veh\u00edculos de alto cilindraje y m\u00e1s de RD$28 millones y US$55 mil en efectivo, todos solicitados en decomiso. Los bienes incautados han generado ingresos por concepto de alquileres y producci\u00f3n agr\u00edcola que ascienden a m\u00e1s de RD$86 millones, tambi\u00e9n reclamados a favor del Estado. 30 PERSONAS F\u00cdSICAS Y 18 JUR\u00cdDICAS El Ministerio P\u00fablico acusa a C\u00e1ceres Silvestre de encabezar la red compuesta por 30 personas f\u00edsicas y 18 jur\u00eddicas, que oper\u00f3 entre 2012 y 2020, desviando fondos p\u00fablicos del Cuerpo de Seguridad Presidencial (Cusep) y del Cuerpo Especializado de Seguridad Tur\u00edstica (Cestur), as\u00ed como del Consejo Nacional para la Ni\u00f1ez y la Adolescencia (Conani).<\/p>\n","protected":false},"author":9,"featured_media":110029,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-110028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=110028"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110028\/revisions"}],"predecessor-version":[{"id":110030,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110028\/revisions\/110030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/110029"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=110028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=110028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=110028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}