{"id":110149,"date":"2026-02-14T06:44:16","date_gmt":"2026-02-14T10:44:16","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=110149"},"modified":"2026-02-14T06:44:19","modified_gmt":"2026-02-14T10:44:19","slug":"juan-soto-volvera-a-defender-el-jardin-izquierdo-con-los-mets","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/juan-soto-volvera-a-defender-el-jardin-izquierdo-con-los-mets\/","title":{"rendered":"Juan Soto volver\u00e1 a defender el jard\u00edn izquierdo con los Mets"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/02\/juan-soto-300x169-1.jpeg\" alt=\"\" class=\"wp-image-110150\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">NUEVA YORK.- El dominicano Juan Soto jugar\u00e1 en el jard\u00edn izquierdo con los Mets esta pr\u00f3xima temporada, inform\u00f3 el martes el presidente de operaciones de b\u00e9isbol, David Stearns, en la apertura de los campamentos del club.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soto ha sido principalmente patrullero derecho desde el 2021, aunque tiene experiencia en la otra esquina de los jardines. El ca\u00f1onero fue titular en 112 juegos en el bosque izquierdo para los Nacionales en el 2018 y 150 en el 2019, a\u00f1o en que Washington gan\u00f3 la primera Serie Mundial de la franquicia. Para el 2021, hizo la transici\u00f3n a la derecha, iniciando 144 encuentros all\u00ed esa campa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde ese a\u00f1o, Soto ha sido casi exclusivamente guardabosque derecho, salvo por una temporada con los Padres en el 2023, cuando disput\u00f3 154 partidos en la pradera izquierda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soto registr\u00f3 -12 Outs Por Encima del Promedio (OAA) en el jard\u00edn derecho con los Mets la temporada pasada y se ubic\u00f3 en el percentil 66 en fuerza del brazo. Su mejor campa\u00f1a defensiva lleg\u00f3 en el 2019, cuando registr\u00f3 +5 OAA como jardinero izquierdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con Soto en el izquierdo, los Mets probablemente utilizar\u00e1n a Tyrone Taylor o al prospecto Carson Benge en el jard\u00edn derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">of-am<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUEVA YORK.- El dominicano Juan Soto jugar\u00e1 en el jard\u00edn izquierdo con los Mets esta pr\u00f3xima temporada, inform\u00f3 el martes el presidente de operaciones de b\u00e9isbol, David Stearns, en la apertura de los campamentos del club. Soto ha sido principalmente patrullero derecho desde el 2021, aunque tiene experiencia en la otra esquina de los jardines. El ca\u00f1onero fue titular en 112 juegos en el bosque izquierdo para los Nacionales en el 2018 y 150 en el 2019, a\u00f1o en que Washington gan\u00f3 la primera Serie Mundial de la franquicia. Para el 2021, hizo la transici\u00f3n a la derecha, iniciando 144 encuentros all\u00ed esa campa\u00f1a. Desde ese a\u00f1o, Soto ha sido casi exclusivamente guardabosque derecho, salvo por una temporada con los Padres en el 2023, cuando disput\u00f3 154 partidos en la pradera izquierda. Soto registr\u00f3 -12 Outs Por Encima del Promedio (OAA) en el jard\u00edn derecho con los Mets la temporada pasada y se ubic\u00f3 en el percentil 66 en fuerza del brazo. Su mejor campa\u00f1a defensiva lleg\u00f3 en el 2019, cuando registr\u00f3 +5 OAA como jardinero izquierdo. Con Soto en el izquierdo, los Mets probablemente utilizar\u00e1n a Tyrone Taylor o al prospecto Carson Benge en el jard\u00edn derecho. of-am<\/p>\n","protected":false},"author":9,"featured_media":110150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-110149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=110149"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110149\/revisions"}],"predecessor-version":[{"id":110151,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110149\/revisions\/110151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/110150"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=110149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=110149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=110149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}