{"id":110158,"date":"2026-02-15T06:56:06","date_gmt":"2026-02-15T10:56:06","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=110158"},"modified":"2026-02-15T06:56:08","modified_gmt":"2026-02-15T10:56:08","slug":"el-sistema-judicial-dominicano-colapso-segun-presidente-scj","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-sistema-judicial-dominicano-colapso-segun-presidente-scj\/","title":{"rendered":"El sistema judicial dominicano colaps\u00f3, seg\u00fan Presidente SCJ"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"896\" height=\"504\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/02\/27012026-amchamdr-12-9c2cfef5-focus-min0.08-0.69-896-504.jpg\" alt=\"\" class=\"wp-image-110159\" style=\"width:289px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/02\/27012026-amchamdr-12-9c2cfef5-focus-min0.08-0.69-896-504.jpg 896w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/02\/27012026-amchamdr-12-9c2cfef5-focus-min0.08-0.69-896-504-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/02\/27012026-amchamdr-12-9c2cfef5-focus-min0.08-0.69-896-504-768x432.jpg 768w\" sizes=\"auto, (max-width: 896px) 100vw, 896px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El presidente de la Suprema Corte de Justicia (SCJ), Luis Henry Molina, consider\u00f3 necesario que se produzca un cambio en el sistema judicial dominicano, en el cual prevalece, seg\u00fan afirm\u00f3, una saturaci\u00f3n de casos pendientes de resolver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al encabezar un di\u00e1logo con representantes de distintos sectores en la Ciudad Judicial de Santo Domingo Este (SDE), Molina sugiri\u00f3 que se acoja la modalidad de los convenios, para poner fin a conflictosc penales, y que se desechen los juicios de fondo, como se hace en pa\u00edses desarrollados, entre ellos Estados Unidos, donde \u201cel 98% de los casos se resuelven con acuerdos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m45225-45224-45226\">\u201cNo es posible resolver los casos penales de la Rep\u00fablica Dominicana con juicios de fondo. Si no se producen los acuerdos\u2026 el sistema no va a colapsar, ya colaps\u00f3\u201d, declar\u00f3 el magistrado, cuyas declaraciones han sido recogidas por el peri\u00f3dico List\u00edn Diario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m45235-45234-45236\">\u201cNo tiene que ver con tecnolog\u00eda, infraestructura, es el cambio de una cultura organizacional, de procedimiento, de \u00e9tica de los actores procesales, ese es el camino y la soluci\u00f3n\u201d, resalt\u00f3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LA META DE LA SCJ: UN A\u00d1O<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Molina destac\u00f3 que la metas de la SCJ es que los casos penales en el pa\u00eds no se prolonguen durante m\u00e1s de un a\u00f1o para ser resueltos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m45265-45264-45266\">\u201cTodo ese tipo de casos se resuelven por acuerdos, no hay posibilidad de que todos los casos lleguen a los tribunales y se arme un juicio. Es como si usted me pidiera que todo el sistema de salud se resuelva en un quir\u00f3fano, es imposible\u201d, destac\u00f3, seg\u00fan lo publicado por el citado medido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m45295-45294-45296\">El di\u00e1logo en la Ciudad Judicial de SDE es el primero de un ciclo de encuentros regionales que ser\u00e1n celebrados con el fin de&nbsp; comunicar, reconocer y consolidar alianzas estrat\u00e9gicas y fortalecer la legitimidad y el respaldo nacional al \u00abPlan Justicia del Futuro 2034\u00bb, elaborado por la Suprema Corte de Justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">sp-am<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El presidente de la Suprema Corte de Justicia (SCJ), Luis Henry Molina, consider\u00f3 necesario que se produzca un cambio en el sistema judicial dominicano, en el cual prevalece, seg\u00fan afirm\u00f3, una saturaci\u00f3n de casos pendientes de resolver. Al encabezar un di\u00e1logo con representantes de distintos sectores en la Ciudad Judicial de Santo Domingo Este (SDE), Molina sugiri\u00f3 que se acoja la modalidad de los convenios, para poner fin a conflictosc penales, y que se desechen los juicios de fondo, como se hace en pa\u00edses desarrollados, entre ellos Estados Unidos, donde \u201cel 98% de los casos se resuelven con acuerdos\u201d. \u201cNo es posible resolver los casos penales de la Rep\u00fablica Dominicana con juicios de fondo. Si no se producen los acuerdos\u2026 el sistema no va a colapsar, ya colaps\u00f3\u201d, declar\u00f3 el magistrado, cuyas declaraciones han sido recogidas por el peri\u00f3dico List\u00edn Diario. \u201cNo tiene que ver con tecnolog\u00eda, infraestructura, es el cambio de una cultura organizacional, de procedimiento, de \u00e9tica de los actores procesales, ese es el camino y la soluci\u00f3n\u201d, resalt\u00f3. LA META DE LA SCJ: UN A\u00d1O Molina destac\u00f3 que la metas de la SCJ es que los casos penales en el pa\u00eds no se prolonguen durante m\u00e1s de un a\u00f1o para ser resueltos. \u201cTodo ese tipo de casos se resuelven por acuerdos, no hay posibilidad de que todos los casos lleguen a los tribunales y se arme un juicio. Es como si usted me pidiera que todo el sistema de salud se resuelva en un quir\u00f3fano, es imposible\u201d, destac\u00f3, seg\u00fan lo publicado por el citado medido. El di\u00e1logo en la Ciudad Judicial de SDE es el primero de un ciclo de encuentros regionales que ser\u00e1n celebrados con el fin de&nbsp; comunicar, reconocer y consolidar alianzas estrat\u00e9gicas y fortalecer la legitimidad y el respaldo nacional al \u00abPlan Justicia del Futuro 2034\u00bb, elaborado por la Suprema Corte de Justicia. sp-am<\/p>\n","protected":false},"author":9,"featured_media":110159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-110158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=110158"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110158\/revisions"}],"predecessor-version":[{"id":110160,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110158\/revisions\/110160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/110159"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=110158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=110158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=110158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}