{"id":110497,"date":"2026-03-08T19:38:29","date_gmt":"2026-03-08T23:38:29","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=110497"},"modified":"2026-03-08T19:38:32","modified_gmt":"2026-03-08T23:38:32","slug":"jonron-de-juan-soto-da-nocaut-a-paises-bajos-en-clasico-beisbol","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jonron-de-juan-soto-da-nocaut-a-paises-bajos-en-clasico-beisbol\/","title":{"rendered":"Jonr\u00f3n de Juan Soto da nocaut a Pa\u00edses Bajos en Cl\u00e1sico Beisbol"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/03\/juan-300x200-1.jpeg\" alt=\"\" class=\"wp-image-110498\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"m41071-41070-41072\">MIAMI.- Una peque\u00f1a banda march\u00f3 por el vest\u00edbulo del parque loanDepot poco antes del partido del domingo, poniendo a los aficionados de la Rep\u00fablica Dominicana&nbsp;de la espuma antes incluso de que se lanzara el primer lanzamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m41076-41075-41077\">La fiesta no par\u00f3 m\u00e1s de dos horas, ya que la formaci\u00f3n&nbsp;dominicana&nbsp;mantuvo ocupados a los bater\u00edas toda la tarde, conectando cuatro jonrones en el camino hacia una victoria por 12-1 sobre los&nbsp;Pa\u00edses Bajos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m41081-41080-41082\">El jonr\u00f3n de&nbsp;Juan Soto&nbsp;en la s\u00e9ptima entrada result\u00f3 ser el decisivo, ya que el partido termin\u00f3 gracias a la regla de misericordia del&nbsp;Cl\u00e1sico Mundial de B\u00e9isbol, que termina el partido en el tiempo reglamentario durante la fase de grupos si un equipo va ganando por 15 o m\u00e1s carreras tras la quinta entrada o por m\u00e1s de 10 carreras despu\u00e9s de la s\u00e9ptima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">of-m<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIAMI.- Una peque\u00f1a banda march\u00f3 por el vest\u00edbulo del parque loanDepot poco antes del partido del domingo, poniendo a los aficionados de la Rep\u00fablica Dominicana&nbsp;de la espuma antes incluso de que se lanzara el primer lanzamiento. La fiesta no par\u00f3 m\u00e1s de dos horas, ya que la formaci\u00f3n&nbsp;dominicana&nbsp;mantuvo ocupados a los bater\u00edas toda la tarde, conectando cuatro jonrones en el camino hacia una victoria por 12-1 sobre los&nbsp;Pa\u00edses Bajos. El jonr\u00f3n de&nbsp;Juan Soto&nbsp;en la s\u00e9ptima entrada result\u00f3 ser el decisivo, ya que el partido termin\u00f3 gracias a la regla de misericordia del&nbsp;Cl\u00e1sico Mundial de B\u00e9isbol, que termina el partido en el tiempo reglamentario durante la fase de grupos si un equipo va ganando por 15 o m\u00e1s carreras tras la quinta entrada o por m\u00e1s de 10 carreras despu\u00e9s de la s\u00e9ptima. of-m<\/p>\n","protected":false},"author":9,"featured_media":110498,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-110497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=110497"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110497\/revisions"}],"predecessor-version":[{"id":110499,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110497\/revisions\/110499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/110498"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=110497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=110497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=110497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}