{"id":110744,"date":"2026-03-22T08:31:14","date_gmt":"2026-03-22T12:31:14","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=110744"},"modified":"2026-03-22T08:31:14","modified_gmt":"2026-03-22T12:31:14","slug":"ronny-mauricio-llega-a-los-entrenamientos-de-los-mets-ny","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ronny-mauricio-llega-a-los-entrenamientos-de-los-mets-ny\/","title":{"rendered":"Ronny Mauricio llega a los entrenamientos de los Mets NY"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"110745\" data-permalink=\"https:\/\/sosuaonline.net\/inicio\/ronny-mauricio-llega-a-los-entrenamientos-de-los-mets-ny\/ronny-300x169\/\" data-orig-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/03\/ronny-300x169-1.jpg\" data-orig-size=\"300,169\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ronny-300&amp;#215;169\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/03\/ronny-300x169-1.jpg\" data-large-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/03\/ronny-300x169-1.jpg\" class=\"size-full wp-image-110745 alignleft\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/03\/ronny-300x169-1.jpg\" alt=\"\" width=\"300\" height=\"169\" \/>PORT ST. LUCIE, Florida (Licey.com).- Por primera vez desde 2023, Ronny Mauricio lleg\u00f3 a los entrenamientos primaverales de los Mets de Nueva York en plenitud f\u00edsica. El MVP de los Tigres del Licey en la temporada 2022-23 arriba con grandes expectativas para la campa\u00f1a de 2026.<\/p>\n<p>\u00abLlegu\u00e9 ready, al cien por ciento f\u00edsicamente, que era lo que desde hace rato quer\u00eda. Tengo buenas expectativas: seguir positivo y estar listo para lo que necesite el equipo\u00bb, expres\u00f3.<\/p>\n<p>Mauricio, quien bate\u00f3 .319 con un jonr\u00f3n, cinco remolcadas y un OPS de .920 en 32 turnos oficiales durante el spring training, comenzar\u00e1 el a\u00f1o en ligas menores. Sin embargo, el antesalista dominicano se mantiene en el roster de 40 y es una pieza de profundidad que puede aportar a la causa de los Mets, que presentan un n\u00facleo fortalecido con las integraciones de Freddy Peralta, Marcus Semien, Luis Robert Jr. y Devin Williams.<\/p>\n<p>\u00abQueremos un campeonato, y si se quiere ganar, hay que tener a los mejores jugadores. El equipo se ve mejor, se siente bien la vibra y estamos muy bien conectados\u00bb, resalt\u00f3 Ronny.<\/p>\n<p>Durante los entrenamientos, Mauricio ha podido trabajar de cerca con el dirigente azul, Gilbert G\u00f3mez, quien fue nombrado coach de Grandes Ligas por los Mets.<\/p>\n<p>\u00abYa tenemos una muy buena relaci\u00f3n y esto nos ayudar\u00e1 a seguir conect\u00e1ndonos mejor. Estar\u00e1 como coach de primera base y podr\u00e9 trabajar con \u00e9l para mejorar mi corrido de bases y otras cosas\u00bb, se\u00f1al\u00f3.<\/p>\n<p>Mauricio se uniform\u00f3 con los Tigres del Licey por cuarta vez en su carrera la temporada pasada. Conect\u00f3 dos jonrones y remolc\u00f3 diez carreras, incluyendo un cuadrangular para dejar en el terreno al rival, a pesar de que el equipo no logr\u00f3 clasificar por primera vez desde la temporada 2020-21.<\/p>\n<p>\u00abJugar para el Licey me enorgullece. Portar esa camiseta y dar el cien por ciento en ese terreno en Dominicana es especial. No fue nuestra mejor temporada, pero peleamos y siempre se aprende de los momentos malos. Adem\u00e1s, siempre hay un nuevo octubre; estaremos ready cuando lleguemos ah\u00ed de nuevo\u00bb, se\u00f1al\u00f3.<\/p>\n<p>El jugador de 26 a\u00f1os finaliz\u00f3 con un mensaje claro para todos los fan\u00e1ticos de los Tigres del Licey:<\/p>\n<p>\u00abSiempre hay planes de estar en LIDOM. Cada vez que tenga la oportunidad, all\u00e1 estar\u00e9\u00bb, concluy\u00f3.<\/p>\n<p>of-am<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PORT ST. LUCIE, Florida (Licey.com).- Por primera vez desde 2023, Ronny Mauricio lleg\u00f3 a los entrenamientos primaverales de los Mets de Nueva York en plenitud f\u00edsica. El MVP de los Tigres del Licey en la temporada 2022-23 arriba con grandes expectativas para la campa\u00f1a de 2026. \u00abLlegu\u00e9 ready, al cien por ciento f\u00edsicamente, que era lo que desde hace rato quer\u00eda. Tengo buenas expectativas: seguir positivo y estar listo para lo que necesite el equipo\u00bb, expres\u00f3. Mauricio, quien bate\u00f3 .319 con un jonr\u00f3n, cinco remolcadas y un OPS de .920 en 32 turnos oficiales durante el spring training, comenzar\u00e1 el a\u00f1o en ligas menores. Sin embargo, el antesalista dominicano se mantiene en el roster de 40 y es una pieza de profundidad que puede aportar a la causa de los Mets, que presentan un n\u00facleo fortalecido con las integraciones de Freddy Peralta, Marcus Semien, Luis Robert Jr. y Devin Williams. \u00abQueremos un campeonato, y si se quiere ganar, hay que tener a los mejores jugadores. El equipo se ve mejor, se siente bien la vibra y estamos muy bien conectados\u00bb, resalt\u00f3 Ronny. Durante los entrenamientos, Mauricio ha podido trabajar de cerca con el dirigente azul, Gilbert G\u00f3mez, quien fue nombrado coach de Grandes Ligas por los Mets. \u00abYa tenemos una muy buena relaci\u00f3n y esto nos ayudar\u00e1 a seguir conect\u00e1ndonos mejor. Estar\u00e1 como coach de primera base y podr\u00e9 trabajar con \u00e9l para mejorar mi corrido de bases y otras cosas\u00bb, se\u00f1al\u00f3. Mauricio se uniform\u00f3 con los Tigres del Licey por cuarta vez en su carrera la temporada pasada. Conect\u00f3 dos jonrones y remolc\u00f3 diez carreras, incluyendo un cuadrangular para dejar en el terreno al rival, a pesar de que el equipo no logr\u00f3 clasificar por primera vez desde la temporada 2020-21. \u00abJugar para el Licey me enorgullece. Portar esa camiseta y dar el cien por ciento en ese terreno en Dominicana es especial. No fue nuestra mejor temporada, pero peleamos y siempre se aprende de los momentos malos. Adem\u00e1s, siempre hay un nuevo octubre; estaremos ready cuando lleguemos ah\u00ed de nuevo\u00bb, se\u00f1al\u00f3. El jugador de 26 a\u00f1os finaliz\u00f3 con un mensaje claro para todos los fan\u00e1ticos de los Tigres del Licey: \u00abSiempre hay planes de estar en LIDOM. Cada vez que tenga la oportunidad, all\u00e1 estar\u00e9\u00bb, concluy\u00f3. of-am<\/p>\n","protected":false},"author":9,"featured_media":110745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-110744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/03\/ronny-300x169-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=110744"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110744\/revisions"}],"predecessor-version":[{"id":110746,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/110744\/revisions\/110746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/110745"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=110744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=110744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=110744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}