{"id":11078,"date":"2014-11-27T14:35:49","date_gmt":"2014-11-27T18:35:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=11078"},"modified":"2014-11-27T14:35:49","modified_gmt":"2014-11-27T18:35:49","slug":"vacuna-experimental-contra-ebola-supera-con-exito-primer-test-en-humanos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/vacuna-experimental-contra-ebola-supera-con-exito-primer-test-en-humanos\/","title":{"rendered":"Vacuna experimental contra \u00e9bola supera con \u00e9xito primer test en humanos"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/EBOLA2-441x441.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11079 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/EBOLA2-441x441-300x300.jpg\" alt=\"EBOLA2-441x441\" width=\"300\" height=\"300\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/EBOLA2-441x441-300x300.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/EBOLA2-441x441-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/EBOLA2-441x441-120x120.jpg 120w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/EBOLA2-441x441.jpg 441w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Washington.<\/strong> Una vacuna experimental contra el \u00e9bola desarrollada en EE.UU. ha superado con \u00e9xito el primer test en humanos, generando una respuesta inmune a la enfermedad sin efectos secundarios graves en los 20 voluntarios que la recibieron, seg\u00fan un estudio publicado en la revista New England Journal of Medicine. \u00a0 El ensayo cl\u00ednico comenz\u00f3 en septiembre en los Institutos Nacionales de Salud (NIH) y sus resultados son lo suficientemente prometedores como para llevar a cabo un estudio mayor con miles de participantes en \u00c1frica Occidental, donde comenz\u00f3 y contin\u00faa haciendo estragos el actual brote de \u00e9bola.<!--more--><\/p>\n<p>La respuesta de los 20 voluntarios que recibieron la vacuna \u201ces muy comparable\u201d a la que protege a los animales del virus, seg\u00fan el doctor Anthony Fauci, director del Instituto Nacional de Alergias y Enfermedades Infecciosas de EE.UU., entidad que colabor\u00f3 en el ensayo cl\u00ednico llevado a cabo en un centro del NIH en Bethesda (Maryland). \u00a0 La vacuna, desarrollada por el fabricante GlaxoSmithKline, usa un virus del resfriado com\u00fan llamado adenovirus, que normalmente infecta a los chimpanc\u00e9s, manipulado gen\u00e9ticamente con peque\u00f1as trazas de \u00e9bola.<\/p>\n<p>Los 20 voluntarios vacunados en el ensayo cl\u00ednico generaron anticuerpos contra el \u00e9bola y \u00fanicamente dos de los que recibieron la dosis m\u00e1s alta tuvieron fiebre de corta duraci\u00f3n. \u00a0 Las personas que recibieron la dosis m\u00e1s alta desarrollaron una respuesta inmune m\u00e1s fuerte. \u00a0 Esto \u00faltimo puede ser un problema, ya que cuanto mayor sea la dosis necesaria para generar la inmunidad, m\u00e1s dif\u00edcil y costoso ser\u00e1 producir la vacuna en cantidades necesarias para enfrentar el brote en \u00c1frica Occidental y frenar su avance.<\/p>\n<p>El presidente de EE.UU., Barack Obama, prev\u00e9 visitar el pr\u00f3ximo martes el centro del NIH donde se realiz\u00f3 el ensayo cl\u00ednico para felicitar a sus trabajadores y volver a urgir al Congreso a aprobar antes de final de a\u00f1o los 6.180 millones de d\u00f3lares solicitados por su Gobierno para contener la expansi\u00f3n del virus. \u00a0 Desde marzo pasado se han detectado 15.351 casos de infecciones por \u00e9bola, de los que 5.459 resultaron mortales, seg\u00fan los \u00faltimos datos de la Organizaci\u00f3n Mundial de la Salud (OMS). \u00a0 Los pa\u00edses m\u00e1s afectados por la epidemia son Liberia, Sierra Leona y Guinea.<\/p>\n<p><a href=\"http:\/\/hoy.com.do\/vacuna-experimental-contra-ebola-supera-con-exito-primer-test-en-humanos\/\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington. Una vacuna experimental contra el \u00e9bola desarrollada en EE.UU. ha superado con \u00e9xito el primer test en humanos, generando una respuesta inmune a la enfermedad sin efectos secundarios graves en los 20 voluntarios que la recibieron, seg\u00fan un estudio publicado en la revista New England Journal of Medicine. \u00a0 El ensayo cl\u00ednico comenz\u00f3 en septiembre en los Institutos Nacionales de Salud (NIH) y sus resultados son lo suficientemente prometedores como para llevar a cabo un estudio mayor con miles de participantes en \u00c1frica Occidental, donde comenz\u00f3 y contin\u00faa haciendo estragos el actual brote de \u00e9bola.<\/p>\n","protected":false},"author":3,"featured_media":11079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-11078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11078"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11078\/revisions"}],"predecessor-version":[{"id":11080,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11078\/revisions\/11080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/11079"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}