{"id":11090,"date":"2014-11-27T14:59:26","date_gmt":"2014-11-27T18:59:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=11090"},"modified":"2014-11-27T14:59:26","modified_gmt":"2014-11-27T18:59:26","slug":"los-adolescentes-se-aburren-de-facebook","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-adolescentes-se-aburren-de-facebook\/","title":{"rendered":"Los adolescentes se aburren de Facebook"},"content":{"rendered":"<p><label><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/jks.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11091 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/jks-300x200.jpg\" alt=\"jks\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/jks-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/jks.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Facebook<\/label> es la red social m\u00e1s grande del mundo. Su cantidad de <label>usuarios<\/label> mensuales activos es casi tan grande como toda la poblaci\u00f3n <label>China<\/label>, y supera con creces a las personas que habitan en toda la Uni\u00f3n Europea. Facebook, con 1.350 millones de usuarios activos (que se han conectado a la red en el \u00faltimo mes, seg\u00fan las \u00faltimas cifras de la empresa), sin embargo, no est\u00e1 generando tanto inter\u00e9s en su p\u00fablico.<!--more--><\/p>\n<p>Esto es lo que se desprende del \u00faltimo informe GWI Social de Global <label>Web<\/label> Index, realizado entre usuarios de Facebook 19 y 64 a\u00f1os con residencia en Estados Unidos y Reino Unido.<\/p>\n<p>Seg\u00fan esta investigaci\u00f3n, un 50% de los usuarios consultados reconocen que usan con menos <label>frecuencia<\/label> la Red social creada por Mark Zuckerberg. El porcentaje es mucho mayor si se pone la lupa s\u00f3lo en los m\u00e1s j\u00f3venes (16-19 a\u00f1os). Un 64% de los adolescentes se\u00f1ala que ha dejado de usar dicha red social con la misma frecuencia que antes.<\/p>\n<p>Un 50% de los adolescentes encuestados se\u00f1al\u00f3 que han abandonado su uso porque les parece aburrido y un 27% apunt\u00f3 que la red social ya no es tan \u00abcool\u00bb como antes. El porcentaje es menor si se toma en referencia toda la poblaci\u00f3n consultada. Un 37% de la poblaci\u00f3n total encuestada tambi\u00e9n se\u00f1ala que Facebook se ha tornado aburrido.<\/p>\n<p>Un 29% de los j\u00f3venes se\u00f1ala que usa con menos frecuencia dicha red social porque \u00absus amigos no la utilizan tanto como antes\u00bb. Un 18% de los adolescentes se\u00f1ala que prefiere otros servicios, por ejemplo Instagram, para compartir fotograf\u00edas.<\/p>\n<p>La privacidad tambi\u00e9n ha sido una de las razones por las que las personas, dicen, han dejado de usar Facebook con frecuencia. Un 28% de todas las personas encuestadas cree que la red de Zuckerberg no es lo suficientemente segura o privada.<\/p>\n<p>Global Web Index se\u00f1ala que Facebook, seg\u00fan su an\u00e1lisis, ha sido la \u00fanica red en la que se ha visto un descenso de usuarios activos entre 16 y 24 a\u00f1os durante este 2014. S\u00f3lo ha ca\u00eddo un 0.5%, pero se\u00f1alan que es un dato que debe mirarse en contexto.<\/p>\n<p>El estudio apunta que desde 2013 Facebook se usa de forma m\u00e1s pasiva. Se\u00f1alan que el uso de esta plataforma para compartir fotograf\u00edas \u00f3 intercambiar mensajes con amigos descendi\u00f3 un 20%.<\/p>\n<p>Sin embargo, Facebook sigue siendo la red social m\u00e1s grande y conserva cifras de uso importante. Cuatro de cinco usuarios de internet fuera de China tienen una cuenta en Facebook.<\/p>\n<p>En Latinoam\u00e9rica su adopci\u00f3n llega al 93%, y uno de cada dos usuarios ha usado Facebook de forma activa cada mes. Por esto, esta red social tiene m\u00e1s del doble de usuarios activos que los que re\u00fanen los tres sites que pelean por el segundo lugar en el ranking (Twitter, YouTube and Google+). Global Web Index ha consultado a 12.399 miembros de Facebook en Reino Unidos y Estados Unidos para esta investigaci\u00f3n.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.abc.es\/tecnologia\/redes\/20141127\/abci-facebook-adolescentes-pierden-interes-201411262041.html\" target=\"_blank\">ABC<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facebook es la red social m\u00e1s grande del mundo. Su cantidad de usuarios mensuales activos es casi tan grande como toda la poblaci\u00f3n China, y supera con creces a las personas que habitan en toda la Uni\u00f3n Europea. Facebook, con 1.350 millones de usuarios activos (que se han conectado a la red en el \u00faltimo mes, seg\u00fan las \u00faltimas cifras de la empresa), sin embargo, no est\u00e1 generando tanto inter\u00e9s en su p\u00fablico.<\/p>\n","protected":false},"author":3,"featured_media":11091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-11090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11090"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11090\/revisions"}],"predecessor-version":[{"id":11092,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11090\/revisions\/11092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/11091"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}