{"id":111391,"date":"2026-04-15T20:46:51","date_gmt":"2026-04-16T00:46:51","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=111391"},"modified":"2026-04-15T20:46:51","modified_gmt":"2026-04-16T00:46:51","slug":"importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua\/","title":{"rendered":"IMPORTANTE QUE SEPAS: Datos para estos tiempos de emergencia (Gracias a Defensa Civil Sos\u00faa)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"111393\" data-permalink=\"https:\/\/sosuaonline.net\/inicio\/importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua\/alertas\/\" data-orig-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS.jpg\" data-orig-size=\"1093,354\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Anderson Martinez&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1776285174&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ALERTAS\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS-300x97.jpg\" data-large-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS-1024x332.jpg\" class=\"aligncenter size-full wp-image-111393\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS.jpg\" alt=\"\" width=\"1093\" height=\"354\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS.jpg 1093w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS-300x97.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS-1024x332.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS-768x249.jpg 768w\" sizes=\"auto, (max-width: 1093px) 100vw, 1093px\" \/><\/a><br \/>\nDespu\u00e9s de todos los problemas causados \u200b\u200bpor las inundaciones de la semana pasada, especialmente en <strong>Montellano<\/strong> y sus alrededores, la Defensa Civil de Sos\u00faa consider\u00f3 importante que todos est\u00e9n preparados para tales calamidades. La Rep\u00fablica Dominicana opera con niveles de alerta. La Defensa Civil siempre informar\u00e1 a la poblaci\u00f3n cuando haya una situaci\u00f3n de alerta.<\/p>\n<p style=\"text-align: center;\">\n<a href=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-VERDE.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"111396\" data-permalink=\"https:\/\/sosuaonline.net\/inicio\/importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua\/alerta-verde\/\" data-orig-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-VERDE.jpg\" data-orig-size=\"337,630\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Anderson Martinez&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1776285039&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ALERTA VERDE\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-VERDE-160x300.jpg\" data-large-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-VERDE.jpg\" class=\"wp-image-111396 aligncenter\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-VERDE.jpg\" alt=\"\" width=\"282\" height=\"527\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-VERDE.jpg 337w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-VERDE-160x300.jpg 160w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><\/a><br \/>\n<strong>Alerta verde:<br \/>\n<\/strong>Riesgo bajo. Mant\u00e9ngase alerta e informado de cualquier cambio.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-AMARILLA.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"111395\" data-permalink=\"https:\/\/sosuaonline.net\/inicio\/importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua\/alerta-amarilla\/\" data-orig-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-AMARILLA.jpg\" data-orig-size=\"326,554\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Anderson Martinez&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1776285074&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ALERTA AMARILLA\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-AMARILLA-177x300.jpg\" data-large-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-AMARILLA.jpg\" class=\"aligncenter  wp-image-111395\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-AMARILLA.jpg\" alt=\"\" width=\"274\" height=\"466\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-AMARILLA.jpg 326w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-AMARILLA-177x300.jpg 177w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" \/><\/a><strong>Alerta amarilla:<br \/>\n<\/strong>Riesgo moderado. S\u00edntomas de desarrollo. Tome medidas preventivas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-ROJA.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"111394\" data-permalink=\"https:\/\/sosuaonline.net\/inicio\/importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua\/alerta-roja\/\" data-orig-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-ROJA.jpg\" data-orig-size=\"318,557\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Anderson Martinez&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1776285097&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ALERTA ROJA\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-ROJA-171x300.jpg\" data-large-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-ROJA.jpg\" class=\"aligncenter  wp-image-111394\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-ROJA.jpg\" alt=\"\" width=\"276\" height=\"483\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-ROJA.jpg 318w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTA-ROJA-171x300.jpg 171w\" sizes=\"auto, (max-width: 276px) 100vw, 276px\" \/><\/a>Alerta roja:<br \/>\nRiesgo alto. Situaci\u00f3n peligrosa. Act\u00fae de inmediato y siga las instrucciones de los servicios de emergencia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"111397\" data-permalink=\"https:\/\/sosuaonline.net\/inicio\/importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua\/numeros-de-emergencias-en-sosua\/\" data-orig-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA.jpg\" data-orig-size=\"810,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"numeros de emergencias en SOSUA\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA-225x300.jpg\" data-large-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA-768x1024.jpg\" class=\"aligncenter size-full wp-image-111397\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA.jpg\" alt=\"\" width=\"810\" height=\"1080\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA.jpg 810w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA-225x300.jpg 225w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/numeros-de-emergencias-en-SOSUA-768x1024.jpg 768w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><strong>N\u00fameros de emergencia de Sos\u00faa<\/strong><br \/>\nSu seguridad y la de sus seres queridos es la m\u00e1xima prioridad de la Defensa Civil. Guarde estos n\u00fameros y comp\u00e1rtalos para que pueda actuar r\u00e1pidamente en cualquier situaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"111398\" data-permalink=\"https:\/\/sosuaonline.net\/inicio\/importante-que-sepas-datos-para-estos-tiempos-de-emergencia-gracias-a-defensa-civil-sosua\/kit-de-emergencia\/\" data-orig-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia.jpg\" data-orig-size=\"810,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"kit de emergencia\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia-225x300.jpg\" data-large-file=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia-768x1024.jpg\" class=\"aligncenter size-full wp-image-111398\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia.jpg\" alt=\"\" width=\"810\" height=\"1080\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia.jpg 810w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia-225x300.jpg 225w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/kit-de-emergencia-768x1024.jpg 768w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p>Un kit de emergencia puede marcar la diferencia en momentos cr\u00edticos. No espere a que surja una situaci\u00f3n cr\u00edtica para actuar. Defensa Civil recomienda incluir lo siguiente en su kit de emergencia:<\/p>\n<ul>\n<li>Agua Potable,<\/li>\n<li>Linterna Y Pilas,<\/li>\n<li>Documentos Importantes Protegidos Y,<\/li>\n<li>Botiqu\u00edn De Primeros Auxilios.<\/li>\n<\/ul>\n<p>Estar preparado significa cuidar de usted y de sus seres queridos. Defensa Civil de Sos\u00faa trabaja por su seguridad, pero tambi\u00e9n necesita la cooperaci\u00f3n de todos los ciudadanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Despu\u00e9s de todos los problemas causados \u200b\u200bpor las inundaciones de la semana pasada, especialmente en Montellano y sus alrededores, la Defensa Civil de Sos\u00faa consider\u00f3 importante que todos est\u00e9n preparados para tales calamidades. La Rep\u00fablica Dominicana opera con niveles de alerta. La Defensa Civil siempre informar\u00e1 a la poblaci\u00f3n cuando haya una situaci\u00f3n de alerta. Alerta verde: Riesgo bajo. Mant\u00e9ngase alerta e informado de cualquier cambio. &nbsp; Alerta amarilla: Riesgo moderado. S\u00edntomas de desarrollo. Tome medidas preventivas. &nbsp; Alerta roja: Riesgo alto. Situaci\u00f3n peligrosa. Act\u00fae de inmediato y siga las instrucciones de los servicios de emergencia. &nbsp; N\u00fameros de emergencia de Sos\u00faa Su seguridad y la de sus seres queridos es la m\u00e1xima prioridad de la Defensa Civil. Guarde estos n\u00fameros y comp\u00e1rtalos para que pueda actuar r\u00e1pidamente en cualquier situaci\u00f3n. &nbsp; Un kit de emergencia puede marcar la diferencia en momentos cr\u00edticos. No espere a que surja una situaci\u00f3n cr\u00edtica para actuar. Defensa Civil recomienda incluir lo siguiente en su kit de emergencia: Agua Potable, Linterna Y Pilas, Documentos Importantes Protegidos Y, Botiqu\u00edn De Primeros Auxilios. Estar preparado significa cuidar de usted y de sus seres queridos. Defensa Civil de Sos\u00faa trabaja por su seguridad, pero tambi\u00e9n necesita la cooperaci\u00f3n de todos los ciudadanos.<\/p>\n","protected":false},"author":12,"featured_media":111393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-111391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2026\/04\/ALERTAS.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/111391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=111391"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/111391\/revisions"}],"predecessor-version":[{"id":111399,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/111391\/revisions\/111399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/111393"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=111391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=111391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=111391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}