{"id":11236,"date":"2014-02-26T15:10:44","date_gmt":"2014-02-26T19:10:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=11236"},"modified":"2014-11-30T15:11:52","modified_gmt":"2014-11-30T19:11:52","slug":"entrega-de-donaciones-y-compartir-deportivo-de-la-delegacion-del-equipo-de-ancaste-canada-ver-fotos-y-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/entrega-de-donaciones-y-compartir-deportivo-de-la-delegacion-del-equipo-de-ancaste-canada-ver-fotos-y-video\/","title":{"rendered":"Entrega de donaciones y compartir deportivo de la delegaci\u00f3n del equipo de Ancaste, Canad\u00e1 (VER FOTOS Y VIDEO)"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/delegacionde_desde_canada_ancaster_200_200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11238 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/delegacionde_desde_canada_ancaster_200_200.jpg\" alt=\"delegacionde_desde_canada_ancaster_200_200\" width=\"200\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/delegacionde_desde_canada_ancaster_200_200.jpg 200w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/delegacionde_desde_canada_ancaster_200_200-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/delegacionde_desde_canada_ancaster_200_200-120x120.jpg 120w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Sos\u00faa.- Por segundo a\u00f1o consecutivo recibimos la visita del equipo de Ancaster (Canad\u00e1), quienes adem\u00e1s de venir a jugar softball, traen una mano amiga de ayuda a nuestra gente. Se ha hecho una tradici\u00f3n que durante su estad\u00eda se enfrenten a equipos de distintos sectores de Sos\u00faa y en cada lugar dejan sus donaciones de ropa y equipos deportivos para jugadores y personas de escasos recursos.<!--more--><\/p>\n<p>Al final de la jornada de juegos en Sos\u00faa, Rep\u00fablica Dominicana, los jugadores de Ancaster, Canad\u00e1, donaron sus camisetas a sus nuevos amigos sosuenses.\u00a0Esta es la segunda vez y planifican una tercera, con la esperanza de hacer una tradici\u00f3n de estos compartir deportivo entre dos naciones que se hacen hermanas, gracias a dos comunidades (Ancaster &amp; Sos\u00faa)\u00a0 que alojan a los jugadores de softball y convierte esta actividad en un verdadero compartir, porque traen desde Canad\u00e1 donaciones de \u00a0ayuda para ni\u00f1os, j\u00f3venes y adultos (familias completas), logrando hacer felices a muchos con su obra de deporte y amor.<\/p>\n<p>Agradecemos a la comunidad de Ancaster por tenernos presente y por seguir uniendo cada d\u00eda m\u00e1s la comunicaci\u00f3n de dos pueblos. Queremos tambi\u00e9n agradecer a nuestro hermano Sosuense residente en exterior, Kiko Acevedo, por ayudar a que sea posible estos lazos deportivos, culturales y de confraternidad entre Ancaster-Sos\u00faa; Canad\u00e1-Rep\u00fablica Dominicana.<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/files.slidemypics.com\/app\/js\/iframe.html?bg_color=1f1f1f&amp;hash=2349e698a2b362b295daa180a1339709&amp;r=0.6345252555329353\" width=\"600\" height=\"450\" frameborder=\"0\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/ZRIu2-XlLvg?feature=player_detailpage\" width=\"600\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Por segundo a\u00f1o consecutivo recibimos la visita del equipo de Ancaster (Canad\u00e1), quienes adem\u00e1s de venir a jugar softball, traen una mano amiga de ayuda a nuestra gente. Se ha hecho una tradici\u00f3n que durante su estad\u00eda se enfrenten a equipos de distintos sectores de Sos\u00faa y en cada lugar dejan sus donaciones de ropa y equipos deportivos para jugadores y personas de escasos recursos.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11236","post","type-post","status-publish","format-standard","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11236"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11236\/revisions"}],"predecessor-version":[{"id":11239,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11236\/revisions\/11239"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}