{"id":11627,"date":"2011-05-04T04:00:00","date_gmt":"2011-05-04T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/astronomos-crearon-el-mapa-mas-grande-del-universo-en-3d\/"},"modified":"2011-05-04T04:00:00","modified_gmt":"2011-05-04T08:00:00","slug":"astronomos-crearon-el-mapa-mas-grande-del-universo-en-3d","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/astronomos-crearon-el-mapa-mas-grande-del-universo-en-3d\/","title":{"rendered":"Astr\u00f3nomos crearon el mapa m\u00e1s grande del universo en 3D"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Planetas a la Deriva\" alt=\"sloan-big-map-300x2292\" src=\"images\/stories\/sosua_images\/sloan-big-map-300x2292.jpg\" height=\"229\" width=\"300\" \/>Un grupo de astr\u00f3nomos recolect\u00f3 los datos para el mapa m\u00e1s extenso y detallado en 3D del universo. Anteriores versiones alcanzaban a marcar galaxias a 7.000 millones de a\u00f1os luz, en cambio, la nueva versi\u00f3n alcanza a trazar nubes de hidr\u00f3geno que est\u00e1n hasta entre 10.000 y 12.000 millones de a\u00f1os luz de distancia, lo m\u00e1s lejos que se ha alcanzado en un mapa hasta la fecha.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u201cEstamos buscando una \u2018protuberancia\u2019 en los datos que nos pueda decir cu\u00e1n r\u00e1pido se est\u00e1 expandiendo el universo\u201d, se\u00f1al\u00f3 el investigador <span style=\"color: #0066cc;\" color=\"#0066cc\">An\u017ee Slosar<\/span>, del Brookhaven National Laboratory en Estados Unidos. \u201cTodav\u00eda no tenemos suficientes datos para ver esa protuberancia, pero esperamos tenerlos en algunos a\u00f1os\u201d, indic\u00f3.<\/p>\n<p>Para crear el mapa, se usaron como gu\u00eda a 14.000 <span style=\"color: #0066cc;\" color=\"#0066cc\">qu\u00e1sars<\/span>, que son n\u00facleos de galaxias y algunos de los cuerpos celestes m\u00e1s brillantes del universo, y que permiten iluminar regiones de nubes de gas a 11.000 millones de a\u00f1os luz de distancia. Es la primera vez que se usa la interacci\u00f3n entre el gas y los qu\u00e1sars como puntos de referencia para el mapa, en lugar de la luz de las galaxias.<\/p>\n<p>Para 2014, los investigadores esperan tener analizadas entre 50.000 y 60.000 partes de los qu\u00e1sars, que quiz\u00e1s sean suficientes datos para conocer un poco m\u00e1s sobre el universo y su expansi\u00f3n. Los astr\u00f3nomos esperan tener un mapa 3D completo para ese entonces, lo que seguro ser\u00e1 de utilidad para cuando necesitemos viajar por las estrellas. O al menos mandar robots por ah\u00ed. Mientras tanto, el mapa permitir\u00e1 a los cient\u00edficos conocer un poco m\u00e1s la naturaleza de nuestro universo, y observar c\u00f3mo ha cambiado en el tiempo y las fuerzas que han influenciado esos cambios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de astr\u00f3nomos recolect\u00f3 los datos para el mapa m\u00e1s extenso y detallado en 3D del universo. Anteriores versiones alcanzaban a marcar galaxias a 7.000 millones de a\u00f1os luz, en cambio, la nueva versi\u00f3n alcanza a trazar nubes de hidr\u00f3geno que est\u00e1n hasta entre 10.000 y 12.000 millones de a\u00f1os luz de distancia, lo m\u00e1s lejos que se ha alcanzado en un mapa hasta la fecha.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11627","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11627"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11627\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}