{"id":11636,"date":"2011-05-22T00:41:29","date_gmt":"2011-05-22T04:41:29","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/niegan-uso-esteroide-cirugia-practicada-lanzador-puertoplateno-bartolo-colon\/"},"modified":"2011-05-22T00:41:29","modified_gmt":"2011-05-22T04:41:29","slug":"niegan-uso-esteroide-cirugia-practicada-lanzador-puertoplateno-bartolo-colon","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/niegan-uso-esteroide-cirugia-practicada-lanzador-puertoplateno-bartolo-colon\/","title":{"rendered":"Niegan Uso Esteroide Cirug\u00eda Practicada Lanzador Puertoplate\u00f1o Bartolo Col\u00f3n"},"content":{"rendered":"<p><span face=\"Times New Roman\" size=\"3\"><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Bartolo Col\u00f3n\" alt=\"Bartolo-Colon-26\" src=\"images\/stories\/sosua_images\/Bartolo-Colon-26.jpg\" width=\"480\" height=\"380\" \/>New York.- Liriano explic\u00f3 que Col\u00f3n, de 37 a\u00f1os de edad, fue operado en abril de 2010 y se utilizaron c\u00e9lulas madres para regenerar el hombro y codo.<\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">La cirug\u00eda fue en la ciudad de Santiago, a unos 150 kil\u00f3metros al norte de Santo Domingo.<\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">Uno de los m\u00e9dicos que operaron el a\u00f1o pasado al pitcher Bartolo Col\u00f3n, una cirug\u00eda que ahora es investigada por el b\u00e9isbol de Grandes Ligas, asegur\u00f3 el jueves que no se utilizaron hormonas de crecimiento humano ni otras sustancias reguladas por las mayores. <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">\u00abCon Bartolo no usamos hormonas de crecimiento (HGH) ni ninguna otra sustancia regulada\u00bb, dijo el doctor Leonel Liriano en una entrevista telef\u00f3nica con la AP en Santo Domingo. <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">Liriano explic\u00f3 que Col\u00f3n, de 37 a\u00f1os, fue operado en abril de 2010 y se utilizaron c\u00e9lulas madres para regenerar el hombro y codo. La cirug\u00eda fue en la ciudad de Santiago, a unos 150 kil\u00f3metros al norte de Santo Domingo. <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">El diario New York Times report\u00f3 que Grandes Ligas est\u00e1 investigando el proceso al que fue sometido el lanzador dominicano, que tiene foja de 2-1 y 3.81 de efectividad esta temporada con los Yanquis de Nueva York. <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">\u00abLos Yanquis nos notificaron sobre la situaci\u00f3n y estamos investigando el caso\u00bb, dijo al Times el vocero de Grandes Ligas, Pat Courney. <\/p>\n<p>C<\/span><span face=\"Times New Roman\" size=\"3\">ol\u00f3n no lanzaba en las mayores desde el 2009, pero en la actualidad es uno de los pitchers m\u00e1s confiables de los Yanquis con una recta que frecuentemente alcanza las 96 millas por hora, y asumi\u00f3 el puesto de abridor del lesionado Phil Hughes. <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">\u00abAntes de someter a Bartolo al proceso hablamos con gente de Grandes Ligas, con su agente y con abogados de Nueva York para aclarar cualquier duda\u00bb, se\u00f1al\u00f3 el galeno. <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">Liriano, que trabaj\u00f3 en la cirug\u00eda junto con el m\u00e9dico estadounidense Joseph Purita, dijo que al lanzador se le extrajo parte de la m\u00e9dula \u00f3sea y tejido adiposo (grasa). <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">\u00abFue un proceso totalmente limpio en el que no se us\u00f3 nada fuera de lugar o regulado por las Grandes Ligas\u00bb, afirm\u00f3. <\/p>\n<p><\/span><span face=\"Times New Roman\" size=\"3\">Liriano es un m\u00e9dico internista y director en Rep\u00fablica Dominicana de la compa\u00f1\u00eda estadounidense Regenocyte, que se especializa en terapia regenerativa con c\u00e9lulas madre. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>New York.- Liriano explic\u00f3 que Col\u00f3n, de 37 a\u00f1os de edad, fue operado en abril de 2010 y se utilizaron c\u00e9lulas madres para regenerar el hombro y codo. La cirug\u00eda fue en la ciudad de Santiago, a unos 150 kil\u00f3metros al norte de Santo Domingo. Uno de los m\u00e9dicos que operaron el a\u00f1o pasado al pitcher Bartolo Col\u00f3n, una cirug\u00eda que ahora es investigada por el b\u00e9isbol de Grandes Ligas, asegur\u00f3 el jueves que no se utilizaron hormonas de crecimiento humano ni otras sustancias reguladas por las mayores. \u00abCon Bartolo no usamos hormonas de crecimiento (HGH) ni ninguna otra sustancia regulada\u00bb, dijo el doctor Leonel Liriano en una entrevista telef\u00f3nica con la AP en Santo Domingo. Liriano explic\u00f3 que Col\u00f3n, de 37 a\u00f1os, fue operado en abril de 2010 y se utilizaron c\u00e9lulas madres para regenerar el hombro y codo. La cirug\u00eda fue en la ciudad de Santiago, a unos 150 kil\u00f3metros al norte de Santo Domingo. El diario New York Times report\u00f3 que Grandes Ligas est\u00e1 investigando el proceso al que fue sometido el lanzador dominicano, que tiene foja de 2-1 y 3.81 de efectividad esta temporada con los Yanquis de Nueva York. \u00abLos Yanquis nos notificaron sobre la situaci\u00f3n y estamos investigando el caso\u00bb, dijo al Times el vocero de Grandes Ligas, Pat Courney. Col\u00f3n no lanzaba en las mayores desde el 2009, pero en la actualidad es uno de los pitchers m\u00e1s confiables de los Yanquis con una recta que frecuentemente alcanza las 96 millas por hora, y asumi\u00f3 el puesto de abridor del lesionado Phil Hughes. \u00abAntes de someter a Bartolo al proceso hablamos con gente de Grandes Ligas, con su agente y con abogados de Nueva York para aclarar cualquier duda\u00bb, se\u00f1al\u00f3 el galeno. Liriano, que trabaj\u00f3 en la cirug\u00eda junto con el m\u00e9dico estadounidense Joseph Purita, dijo que al lanzador se le extrajo parte de la m\u00e9dula \u00f3sea y tejido adiposo (grasa). \u00abFue un proceso totalmente limpio en el que no se us\u00f3 nada fuera de lugar o regulado por las Grandes Ligas\u00bb, afirm\u00f3. Liriano es un m\u00e9dico internista y director en Rep\u00fablica Dominicana de la compa\u00f1\u00eda estadounidense Regenocyte, que se especializa en terapia regenerativa con c\u00e9lulas madre.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11636","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11636"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11636\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}