{"id":11742,"date":"2011-06-14T04:00:00","date_gmt":"2011-06-14T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-calor-podria-disminuir-por-el-paso-de-onda-tropical\/"},"modified":"2011-06-14T04:00:00","modified_gmt":"2011-06-14T08:00:00","slug":"el-calor-podria-disminuir-por-el-paso-de-onda-tropical","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-calor-podria-disminuir-por-el-paso-de-onda-tropical\/","title":{"rendered":"El Calor Podr\u00eda Disminuir Por El Paso De Onda Tropical."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"Caption\" title=\"Que Calor\" alt=\"421b287b3e8114bde81456b00acdd824-300x225\" src=\"images\/stories\/sosua_images\/421b287b3e8114bde81456b00acdd824-300x225.jpg\" height=\"225\" width=\"300\" \/>El calor que afecta a los dominicanos podr\u00eda disminuir de forma considerable debido a que la actividad de aguaceros se incrementar\u00e1 entre el mi\u00e9rcoles y jueves de esta semana cuando una onda tropical est\u00e9 pasando sobre la costa Sur y el Mar Caribe, inform\u00f3 la Oficina Nacional de Meteorolog\u00eda (Onamet).<\/p>\n<p>  <!--more-->  <\/p>\n<p>Para este martes se esperan aguaceros dispersos con tormentas el\u00e9ctricas y aisladas r\u00e1fagas de vientos hacia las regiones Norte, Noreste, Sureste, Cordillera Central y zona fronteriza producto de los efectos locales y al viento de componente Sureste que arrastra humedad hacia el pa\u00eds.<\/p>\n<p>Ante las altas temperaturas, Meteorolog\u00eda mantiene su recomendaci\u00f3n a la ciudadan\u00eda ingerir l\u00edquidos, vestir ropas ligeras, preferiblemente de colores claros y evitar la exposici\u00f3n al sol durante las horas de mayor insolaci\u00f3n.<\/p>\n<p>Hoy martes, el d\u00eda estar\u00e1 medio nublado, siendo nublado en ocasiones y aguaceros dispersos con tormentas el\u00e9ctricas y aisladas r\u00e1fagas de vientos principalmente hacia las provincias La Altagracia, Hato Mayor, El Seibo, San Pedro de Macor\u00eds, Monte Plata, Duarte, S\u00e1nchez Ram\u00edrez, y Salcedo.<\/p>\n<p>Las lluvias afectar\u00e1n tambi\u00e9n a La Vega, Monse\u00f1or Nouel, Espaillat, Dajab\u00f3n, Valverde, Santiago Rodr\u00edguez, Santiago, Puerto Plata, El\u00edas Pi\u00f1a, San Juan de la Maguana, Barahona, Peravia y Azua.<\/p>\n<p>Santo Domingo y Distrito Nacional, medio nublado, siendo nublado en ocasiones con aguaceros dispersos y tronadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El calor que afecta a los dominicanos podr\u00eda disminuir de forma considerable debido a que la actividad de aguaceros se incrementar\u00e1 entre el mi\u00e9rcoles y jueves de esta semana cuando una onda tropical est\u00e9 pasando sobre la costa Sur y el Mar Caribe, inform\u00f3 la Oficina Nacional de Meteorolog\u00eda (Onamet).<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11742","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11742"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11742\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}