{"id":11798,"date":"2011-06-27T04:00:00","date_gmt":"2011-06-27T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/twitter-va-a-eliminar-su-version-antigua-muy-pronto-tweets-publicitarios-apareceran-en-el-timeline\/"},"modified":"2011-06-27T04:00:00","modified_gmt":"2011-06-27T08:00:00","slug":"twitter-va-a-eliminar-su-version-antigua-muy-pronto-tweets-publicitarios-apareceran-en-el-timeline","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/twitter-va-a-eliminar-su-version-antigua-muy-pronto-tweets-publicitarios-apareceran-en-el-timeline\/","title":{"rendered":"Twitter va a eliminar su versi\u00f3n antigua \u201cmuy pronto\u201d; tweets publicitarios aparecer\u00e1n en el timeline"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"version anterior\" alt=\"oldtwitter-595x208-300x104\" src=\"images\/stories\/sosua_images\/oldtwitter-595x208-300x104.jpg\" height=\"104\" width=\"300\" \/>Twitter sigue creciendo. Ya cuenta con m\u00e1s de 100 millones de usuarios registrados, ahora viene la pr\u00f3xima etapa: la evoluci\u00f3n de la herramienta y empezar a generar dinero.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La primera parte ya est\u00e1 medianamente hecha. El a\u00f1o pasado lanzaron el \u201cNuevo Twitter\u201d, el redise\u00f1o del sitio que incluy\u00f3 el uso de dos columnas y la integraci\u00f3n de contenido subido a sitios externos como YouTube y TwitPic. Si bien el cambio fue lanzado hace m\u00e1s de nueve meses, los usuarios todav\u00eda pueden volver a usar el sitio viejo. Pero de eso queda poco: aquellos que todav\u00eda usan el dise\u00f1o anterior podr\u00e1n notar que ahora les aparece una nueva advertencia que dice que el upgrade a la nueva versi\u00f3n ser\u00e1 hecho autom\u00e1ticamente y se har\u00e1 \u201cmuy, muy pronto\u201d.<\/p>\n<p>\u00bfQu\u00e9 es muy, muy pronto? Nadie sabe.<\/p>\n<p>El otro punto para Twitter es generar ganancias. Hasta ahora, los analistas dicen que la empresa ganar\u00e1 US$ 100 millones este 2011, lo que es muy poco en comparaci\u00f3n con los US$ 3500 millones que ganar\u00e1 Facebook en publicidad.<\/p>\n<p>Por lo mismo, la red de Jack Dorsey est\u00e1 buscando nuevas maneras de generar ingresos y una de ellas son los tweets publicitarios. Hasta ahora, la red ha usado los \u201cPromoted trends\u201d, que son trending topics pagados que aparecen en las listas para que la gente hable de ellos. Los promoted tweets van a ser mentajes publicitarios, que saldr\u00e1n en el timeline de los usuarios, s\u00ed o s\u00ed.<\/p>\n<p>Pero para asegurarse que las gente los lea, se mostrar\u00e1n en una barra en la parte de arriba de la ventana del navegador y no desaparecer\u00e1n sin importar cu\u00e1nto bajes en la ventana. \u00bfLes suena conocido? Es el mismo sistema de la \u201cQuick Bar\u201d de la app de Twitter para iOS.<\/p>\n<p>Algunas fuentes afirmaron a Mashable que este nuevo sistema de publicidad empezar\u00e1 a funcionar dentro de las pr\u00f3ximas 8 semanas. Cabe la duda de c\u00f3mo se integrar\u00e1 este sistema a los clientes de Twitter, ya sea los oficiales o de terceros, que son usados por gran parte de la masa de usuarios.<\/p>\n<p><strong>Link: <\/strong><a href=\"http:\/\/mashable.com\/2011\/06\/23\/old-twitter-end\/\">Old Version of Twitter To Be Eliminated \u201cVery, Very Soon\u201d<\/a><em> (Mashable)<\/em><a href=\"http:\/\/mashable.com\/2011\/06\/23\/old-twitter-end\/\"><br \/> <\/a><\/p>\n<p><strong>Link: <\/strong><a href=\"http:\/\/mashable.com\/2011\/06\/23\/twitter-promoted-tweets-timeline-2\/\">Twitter To Put Promoted Tweets in Your Timeline in Next 2 Months<\/a><em> (Mashable)<\/em><a href=\"http:\/\/mashable.com\/2011\/06\/23\/twitter-promoted-tweets-timeline-2\/\"><br \/> <\/a><\/p>\n<p>Fuente: www.fayerwayer.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Twitter sigue creciendo. Ya cuenta con m\u00e1s de 100 millones de usuarios registrados, ahora viene la pr\u00f3xima etapa: la evoluci\u00f3n de la herramienta y empezar a generar dinero.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11798","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11798"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11798\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}