{"id":11849,"date":"2011-07-03T06:52:58","date_gmt":"2011-07-03T10:52:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/compran-la-cazadora-roja-de-thriller-por-18-millones-veredicto-el-rey-sigue-siendo-el-rey\/"},"modified":"2011-07-03T06:52:58","modified_gmt":"2011-07-03T10:52:58","slug":"compran-la-cazadora-roja-de-thriller-por-18-millones-veredicto-el-rey-sigue-siendo-el-rey","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/compran-la-cazadora-roja-de-thriller-por-18-millones-veredicto-el-rey-sigue-siendo-el-rey\/","title":{"rendered":"Compran la cazadora roja de \u201cThriller\u201d por $1,8 millones. [Veredicto: el Rey sigue siendo el rey]"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Chaqueta usada en Thriller\" alt=\"086_thriller-jacket2\" src=\"images\/stories\/sosua_images\/086_thriller-jacket2.jpg\" width=\"500\" height=\"337\" \/>Hab\u00eda una vez un MJ que vest\u00eda de rojo y que era el rey de las pistas, que impon\u00eda su dictadura sobre el mundo baloncest\u00edstico con mano de hierro mientras surcaba los aires ense\u00f1ando medio palmo de lengua al p\u00fablico. Ese MJ, Michael Jordan, es para muchos el mejor deportista (no ya s\u00f3lo jugador de baloncesto) que ha existido nunca.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Y hay otro MJ, que hace ya un tiempo nos dej\u00f3, que una vez tambi\u00e9n visti\u00f3 de rojo para reventar todas las listas de ventas y dejar patidifusa la industria musical. Este MJ, Michael Jackson, es para otros muchos el icono de la m\u00fasica moderna por excelencia, el Rey del Pop, el rey de los escenarios y de los conciertos espectaculares. Y aunque hayan pasado ya dos a\u00f1os desde su muerte esto ha quedado de nuevo demostrado en la \u00faltima subasta realizada en Los \u00c1ngeles, en la que la m\u00edtica chaqueta roja del tema \u201cThriller\u201d fue vendida por la cifra r\u00e9cord de $1,8 millones. Y a\u00fan hay m\u00e1s.<\/p>\n<p>A pesar de que en la subasta tambi\u00e9n hab\u00eda objetos de Elvis Presley, Frank Sinatra, Paul McCartney, etc. nada era tan esperado como la chaqueta roja que Michael Jackson inmortaliz\u00f3 en el famoso videoclip de Thriller. Y la verdad es que no defraud\u00f3, pues la puja ganadora (esos $1,8 millones) sobrepas\u00f3 en mucho la mejor estimaci\u00f3n que hab\u00eda hecho la casa de subastas de Beverly Hills, que era de $200.000 a $400.000.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"margin-right: auto; margin-left: auto; display: block;\" alt=\"086_thriller-jacket\" src=\"images\/stories\/sosua_images\/086_thriller-jacket.jpg\" width=\"500\" height=\"292\" \/><\/p>\n<p>Tompkins Dennis y Michael Bush, durante muchos a\u00f1os dise\u00f1adores de confianza de Jackson, fueron quienes aportaron esta pieza a la subasta (desconozco que parte negociaron, pero seguro que les dar\u00e1 para alg\u00fan capricho), y era la pieza b\u00e1sica que Jackson us\u00f3 en toda la gira de conciertos de \u201cThriller\u201d. Se sabe que parte de lo recaudado se destinar\u00e1 a los fondos de la Reserva de animales de Shambala, en la que dos tigres de Bengala de Jackson, Thriller y Sabu, han estado viviendo los \u00faltimos cinco a\u00f1os.<\/p>\n<p>Un aut\u00e9ntico pelotazo de venta que har\u00e1 que Michael Jackson se remueva en su tumba (se rumoreaba que los problemas econ\u00f3micos le atosigaron en sus \u00faltimos d\u00edas). No s\u00e9, igual le da por volver a lo Walking Dead para reclamar su traje m\u00e1s preciado que le quedar\u00eda ahora, y ya sin necesidad de pasar por maquillaje, de nuevo perfecto. \u2500 [CNN]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hab\u00eda una vez un MJ que vest\u00eda de rojo y que era el rey de las pistas, que impon\u00eda su dictadura sobre el mundo baloncest\u00edstico con mano de hierro mientras surcaba los aires ense\u00f1ando medio palmo de lengua al p\u00fablico. Ese MJ, Michael Jordan, es para muchos el mejor deportista (no ya s\u00f3lo jugador de baloncesto) que ha existido nunca.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11849","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11849"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11849\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}