{"id":11879,"date":"2011-07-06T03:14:58","date_gmt":"2011-07-06T07:14:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/anteojos-led-para-orientar-a-las-personas-ciegas\/"},"modified":"2011-07-06T03:14:58","modified_gmt":"2011-07-06T07:14:58","slug":"anteojos-led-para-orientar-a-las-personas-ciegas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/anteojos-led-para-orientar-a-las-personas-ciegas\/","title":{"rendered":"Anteojos LED para orientar a las personas ciegas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Anteojos Para Ciegos\" alt=\"size2_16671_ante\" src=\"images\/stories\/sosua_images\/size2_16671_ante.jpg\" width=\"270\" height=\"269\" \/>Los investigadores de la Universidad de Oxford est\u00e1n desarrollando unas gafas que pueden ayudar a las personas ciegas a percibir los objetos a su alrededor.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Con c\u00e1maras diminutas, tecnolog\u00eda LED y un ordenador de bolsillo, el sistema alerta a la persona sobre los objetos y personas que hay por delante.<\/p>\n<p>As\u00ed, ser\u00e1 m\u00e1s f\u00e1cil para los ciegos desplazarse en centros comerciales e incluso \u2019leer\u2019 algunos n\u00fameros, por ejemplo en el autobus o los cajeros autom\u00e1ticos.<\/p>\n<p>Los anteojos tendr\u00e1n un costo de unos 1.500 d\u00f3lares, y se espera que puedan salir a la venta en 2014.<\/p>\n<p>El Dr. Stephen Hicks, un investigador de neurolog\u00eda cl\u00ednica que lidera el proyecto, se\u00f1ala que ya se ha completado la investigaci\u00f3n b\u00e1sica, y ahora se trabaja con prototipos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los investigadores de la Universidad de Oxford est\u00e1n desarrollando unas gafas que pueden ayudar a las personas ciegas a percibir los objetos a su alrededor.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11879","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11879"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11879\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}