{"id":11891,"date":"2011-07-07T18:12:32","date_gmt":"2011-07-07T22:12:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-hamburguesa-mas-grande-del-mundo-pesa-352-kg-ise-te-antoja\/"},"modified":"2011-07-07T18:12:32","modified_gmt":"2011-07-07T22:12:32","slug":"la-hamburguesa-mas-grande-del-mundo-pesa-352-kg-ise-te-antoja","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-hamburguesa-mas-grande-del-mundo-pesa-352-kg-ise-te-antoja\/","title":{"rendered":"La hamburguesa m\u00e1s grande del mundo pesa 352 kg; \u00bfse te antoja?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"hamburguesa mas grande del mundo segun el libro guiness\" alt=\"hamburguesa-grande-guiness-mundo-352\" src=\"images\/stories\/sosua_images\/hamburguesa-grande-guiness-mundo-352.jpg\" height=\"443\" width=\"601\" \/>Cocineros estadounidenses celebraron al terminar de preparar la que se ha convertido en la hamburguesa m\u00e1s grande del mundo. El gigantesco s\u00e1nguche pes\u00f3 352 kilos y demor\u00f3 13 horas en prepararse.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El nuevo r\u00e9cord se registr\u00f3 en una localidad de San Diego, California, en el marco de la denominada Feria de Alameda en Pleasanton. La marca supera en 85 kilos a la antecesora canadiense.<\/p>\n<p>Adem\u00e1s de la carne molida, la gigantesca hamburguesa llevaba una capa de 22 kilos de queso, 15 kilos de lechuga y cerca de diez kilos de cebollas.<\/p>\n<p>La hamburguesa tiene un mill\u00f3n 375 mil calor\u00edas, en su mayor\u00eda de grasas y podr\u00eda alimentar a una persona por dos a\u00f1os.<\/p>\n<p>Los cocineros decidieron vender porciones en 99 centavos de d\u00f3lar cada una para recaudar fondos para organizaciones caritativas de California.<\/p>\n<p>R\u00e9cord anteriores:<\/p>\n<p>\u2013 La anterior hamburgesa m\u00e1s grande del mundo pesaba 95,5 kilogramos, en 2010.<br \/>&#8211; Tambi\u00e9n exist\u00eda el record de una hamburguesa de 38 kilos, en 2007.<\/p>\n<p>Fuente: elcomercio.pe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cocineros estadounidenses celebraron al terminar de preparar la que se ha convertido en la hamburguesa m\u00e1s grande del mundo. El gigantesco s\u00e1nguche pes\u00f3 352 kilos y demor\u00f3 13 horas en prepararse.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-11891","post","type-post","status-publish","format-standard","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11891"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11891\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}