{"id":11921,"date":"2011-07-10T13:02:37","date_gmt":"2011-07-10T17:02:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/definen-como-irregular-desalojo-practicado-a-gomez-motor-raicing-en-cabarete\/"},"modified":"2011-07-10T13:02:37","modified_gmt":"2011-07-10T17:02:37","slug":"definen-como-irregular-desalojo-practicado-a-gomez-motor-raicing-en-cabarete","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/definen-como-irregular-desalojo-practicado-a-gomez-motor-raicing-en-cabarete\/","title":{"rendered":"Definen como irregular desalojo practicado a  G\u00f3mez Motor Raicing en Cabarete"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Peter Hernan Granicper \" alt=\"peter-300x191\" src=\"images\/stories\/sosua_images\/peter-300x191.jpg\" width=\"300\" height=\"191\" \/>Cabarete.- Un desalojo catalogado como irregular y abusivo por los esposos Rosaura G\u00f3mez y Peter Hernan Granicper, este ultimo inversionista de nacionalidad Suiza, fue ejecutado en el d\u00eda de hoy en este distrito municipal, el que seg\u00fan ellos constituye un duro golpe contra la inversi\u00f3n extranjera ya que en calidad de inquilinos llevan m\u00e1s de 6 a\u00f1os ocupando el local donde opera un taller de mec\u00e1nica para motores de carrera y una oficina de abogados.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Manifestaron que los bienes no eran embargables, adem\u00e1s de que se requer\u00edan la presencia del Juez de Paz. En tanto que apuntaron que lo peor del hecho es que ese conflicto se estaba ventilando en la justicia para lo que existe una audiencia fijada para el pr\u00f3ximo d\u00eda 9 del mes en curso lo que agrava seg\u00fan ellos la abusiva ejecuci\u00f3n.<\/p>\n<p>Al lugar se presentaron agentes policiales acompa\u00f1ados de un alguacil que seg\u00fan ellos act\u00fao de forma anormal a este tipo de procedimiento, por lo que aseguraron que se querellaran ante los testamento que sean necesarios, debido a la forma en que actuaron los agentes policiales convirti\u00e9ndose en juez y parte y sin presentar ning\u00fan tipo de orden judicial.<\/p>\n<p>Indicaron que el se\u00f1or Peter Hernan Granicper fue pr\u00e1cticamente arrestado y llevado por la fuerza en momentos en que este estaba afuera del negocio que hasta el momento estaba cerrada , lo que tildaron como un acto de secuestro y de violaci\u00f3n la libertad humana, un hecho execrable seg\u00fan ellos.<\/p>\n<p>Durante la ejecuci\u00f3n fueron destruidos decenas de trofeos obtenidos por el inversionista Suizo quien al igual que sus dos hijos son competidores de Motocr\u00f3s.<\/p>\n<p>Se conoci\u00f3 que en estos momentos el inversionista se encuentra traumatizado porque seg\u00fan \u00e9l fue arrestado a punto de pistola por un grupo de supuestos polic\u00edas acompa\u00f1ados del alguacil Jes\u00fas Castillo Polanco y un abogado de quien no pudimos obtener datos.<\/p>\n<\/p>\n<p>Visto En: Kabarete.net<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cabarete.- Un desalojo catalogado como irregular y abusivo por los esposos Rosaura G\u00f3mez y Peter Hernan Granicper, este ultimo inversionista de nacionalidad Suiza, fue ejecutado en el d\u00eda de hoy en este distrito municipal, el que seg\u00fan ellos constituye un duro golpe contra la inversi\u00f3n extranjera ya que en calidad de inquilinos llevan m\u00e1s de 6 a\u00f1os ocupando el local donde opera un taller de mec\u00e1nica para motores de carrera y una oficina de abogados.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11921","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11921"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11921\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}