{"id":11928,"date":"2011-07-11T11:52:28","date_gmt":"2011-07-11T15:52:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/foro-social-alternativo-aseguran-que-la-huelga-sera-pacifica-y-activa\/"},"modified":"2011-07-11T11:52:28","modified_gmt":"2011-07-11T15:52:28","slug":"foro-social-alternativo-aseguran-que-la-huelga-sera-pacifica-y-activa","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/foro-social-alternativo-aseguran-que-la-huelga-sera-pacifica-y-activa\/","title":{"rendered":"FORO SOCIAL ALTERNATIVO: Aseguran que la huelga ser\u00e1 \u201cpac\u00edfica y activa\u201d"},"content":{"rendered":"<div style=\"margin-top: 0px;\" id=\"ArticleSourceDiv\"><b><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Convocantes a Huelga\" alt=\"C6444C4A-FABF-43C8-B73D-3613B9413AFB_jpg__294__440__CROPz0x294y440\" src=\"images\/stories\/sosua_images\/C6444C4A-FABF-43C8-B73D-3613B9413AFB_jpg__294__440__CROPz0x294y440.jpeg\" width=\"294\" height=\"196\" \/>Santo Domingo.- <\/b>El Foro Social Alternativo afirm\u00f3 ayer que todo est\u00e1 listo para el paro convocado para este lunes a partir de las 6:00 de la ma\u00f1ana, el cual asegura que ser\u00e1 \u201cactivo y pac\u00edfico\u201d.<\/div>\n<p>  <!--more-->  <\/p>\n<p>As\u00ed lo inform\u00f3 ayer en la tarde la dirigente magisterial Mar\u00eda Teresa Cabrera, una de las voceras del Foro, quien dijo que los organizadores tienen programadas una serie de actividades que ser\u00e1n desarrolladas en distintos puntos del pa\u00eds, incluyendo, marchas, caceroleos, misas y otras manifestaciones religiosas y culturales.<\/p>\n<p>\u201cEse ser\u00e1 un paro activo, aqu\u00ed por ejemplo en el Parque Independencia estaremos realizando a partir de las 9:00 de la ma\u00f1ana un encuentro ecum\u00e9nico, donde estaremos desarrollando, por un espacio de m\u00e1s o menos dos horas, una jornada de reflexi\u00f3n sobre los temas que convocan a este paro\u201d, dijo.<\/p>\n<p>Igualmente, precis\u00f3 que en San Francisco de Macor\u00eds est\u00e1 programada una misa en el Parque Duarte, igual en La Vega en el parque Las Flores y en otras comunidades.<\/p>\n<p>\u201cHemos dicho que se trata de un paro activo, c\u00edvico, pac\u00edfico y ordenado y para eso estamos listos en el pa\u00eds para iniciar esa jornada a partir de ma\u00f1ana a las 6:00\u201d, puntualiz\u00f3.<\/p>\n<p>El paro es en reclamo de un aumento salarial de 30 por ciento para los empleados p\u00fablicos, incluidos polic\u00edas y militares, la rebaja de la tarifa el\u00e9ctrica y la modificaci\u00f3n a la ley de hidrocarburos, entre otras reivindicaciones.<\/p>\n<p><strong>CMD<\/strong> <br \/>El presidente del Colegio M\u00e9dico Dominicano, Sen\u00e9n Caba, llam\u00f3 a los miembros de ese gremio a atender las emergencias, unidades de c\u00f3lera y cuidados intensivos, y ratific\u00f3 que apoya el paro de este lunes, por considerar que la pol\u00edtica econ\u00f3mica aplicada por el Gobierno, no solamente empobrece a los sectores m\u00e1s vulnerables, sino que golpea seriamente a la clase media\u201d.<\/p>\n<p>Mientras, el ministro de Salud P\u00fablica, Bautista Rojas G\u00f3mez, estuvo ayer coordinando con los directores de los hospitales p\u00fablicos, a fin de que est\u00e9n preparados ante cualquier eventualidad que se presente con el llamado a paro de hoy. \u201cAnte cualquier contingencia que se presente tenemos que garantizar los cirujanos y los anestesi\u00f3logos\u201d, dijo.<\/p>\n<p><strong>(+) <\/strong><br \/><strong>DICE QUE PARALIZAR\u00c1N TRANSPORTE DE CARGA<\/strong> <br \/>La Central Nacional de Transportistas Unificados (CNTU) asegur\u00f3 ayer que m\u00e1s de 1,500 camiones que transportan productos agr\u00edcolas y vegetales a los mercados, incluyendo los de Dajab\u00f3n y El\u00edas Pi\u00f1a, no operar\u00e1n este lunes en apoyo al paro de labores.<\/p>\n<p>Ram\u00f3n P\u00e9rez Figuereo, presidente de la CNTU, asegur\u00f3 que la decisi\u00f3n fue tomada durante una reuni\u00f3n que sostuvo ese sindicato con afiliados a ese gremio, durante la cual fueron orientados de que se queden en sus casas durante el paro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El Foro Social Alternativo afirm\u00f3 ayer que todo est\u00e1 listo para el paro convocado para este lunes a partir de las 6:00 de la ma\u00f1ana, el cual asegura que ser\u00e1 \u201cactivo y pac\u00edfico\u201d.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11928","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11928"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11928\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}