{"id":11943,"date":"2011-07-12T04:00:00","date_gmt":"2011-07-12T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/apple-app-store-mas-15000-millones-de-descargas-en-tres-anos\/"},"modified":"2011-07-12T04:00:00","modified_gmt":"2011-07-12T08:00:00","slug":"apple-app-store-mas-15000-millones-de-descargas-en-tres-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/apple-app-store-mas-15000-millones-de-descargas-en-tres-anos\/","title":{"rendered":"Apple App Store: m\u00e1s 15.000 millones de descargas en tres a\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"apple store app\" alt=\"appstoredap\" src=\"images\/stories\/sosua_images\/appstoredap.jpg\" height=\"225\" width=\"300\" \/>Los n\u00fameros han sido en los \u00faltimos a\u00f1os la t\u00f3nica dominante al comienzo de cada una de las presentaciones de Apple. Y tambi\u00e9n cada vez que pueden hacer alarde de alg\u00fan hito, \u00e9stos salen a relucir con el firme prop\u00f3sito de poner tierra de por medio con sus m\u00e1s directos competidores y rivales.<\/p>\n<p>  <!--more-->  <\/p>\n<p>En este caso, es la tienda de aplicaciones App Storela que se lleva la palma, de donde hasta la fecha se han descargado m\u00e1s de 15.000 millones de aplicaciones en tan s\u00f3lo tres a\u00f1os de funcionamiento. <br \/>Sobre todo, considerando que fue el propio Steve Jobs el que anunciaba, durante la celebraci\u00f3n de la World Wide Developer Conference a principios del pasado mes de junio, haber sobrepasado la cantidad de los 14.000 millones de descargas. Con m\u00e1s de 200 millones de dispositivos iOS de circulaci\u00f3n, esto apunta a una media de 75 descargas por usuario, cifra que posiblemente no es dif\u00edcil alcanzar a tenor de los 425.000 programas que la App Store mantiene en cat\u00e1logo.<br \/>De las cuales, la nada despreciable cifra de 100.000 aplicaciones se ofrecen de forma exclusiva orientadas hacia el iPad, dispositivo sobre el que el comunicado de Apple hace especial hincapi\u00e9 en el hecho de que contin\u00fae siendo el tablet m\u00e1s popular, alej\u00e1ndose en gran medida de otras plataformas tales como Android, webOS o BlackBerry.<br \/>Phil Schiller aprovecho la ocasi\u00f3n para describir el cat\u00e1logo existente como el mejor en el panorama tecnol\u00f3gico m\u00f3vil actual, agradeciendo a todos los desarrolladores por su af\u00e1n en poner de manifiesto el potencial de la plataforma iOS, haciendo menci\u00f3n especial de Smule, Epic Games y Callaway Digital Arts por sus buenos resultados, omitiendo a grandes compa\u00f1\u00edas tales como EA Games y Rovio.<br \/>No obstante, los n\u00fameros son los n\u00fameros y los m\u00e1s interesantes son los que se derivan de todo esto para ambas partes en juego: una facturaci\u00f3n de 3.600 millones de d\u00f3lares (unos 2.500 millones de euros), de los cuales los propios desarrolladores se han embolsado poco m\u00e1s de 2.500 millones de d\u00f3lares (1.740 millones de euros). Visto lo visto, tendremos iOS para rato.<\/p>\n<p>v\u00eda: www.zonatechrd.blogspot.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los n\u00fameros han sido en los \u00faltimos a\u00f1os la t\u00f3nica dominante al comienzo de cada una de las presentaciones de Apple. Y tambi\u00e9n cada vez que pueden hacer alarde de alg\u00fan hito, \u00e9stos salen a relucir con el firme prop\u00f3sito de poner tierra de por medio con sus m\u00e1s directos competidores y rivales.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11943","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11943"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11943\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}