{"id":11999,"date":"2011-07-17T19:31:00","date_gmt":"2011-07-17T23:31:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/una-sustancia-recupera-la-voz-de-los-afonicos-permanentes\/"},"modified":"2011-07-17T19:31:00","modified_gmt":"2011-07-17T23:31:00","slug":"una-sustancia-recupera-la-voz-de-los-afonicos-permanentes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/una-sustancia-recupera-la-voz-de-los-afonicos-permanentes\/","title":{"rendered":"Una sustancia recupera la voz de los af\u00f3nicos permanentes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"afon\u00eda\" alt=\"afonia1_small\" src=\"images\/stories\/sosua_images\/afonia1_small.jpg\" width=\"367\" height=\"369\" \/>Constituye una patolog\u00eda silenciosa, ya que roba la voz a quienes la sufren. En Espa\u00f1a, hasta 20.000 personas pueden llegar a sufrir disfon\u00eda espasm\u00f3dica, una p\u00e9rdida permanente de la voz.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La mayor\u00eda derivada de la cicatrizaci\u00f3n de las cuerdas vocales que pueden conducir a la disminuci\u00f3n o incluso la p\u00e9rdida total de la capacidad de hablar. Pero tras los pocos tratamientos que existen -tan s\u00f3lo se soluciona de forma puntual con tox\u00edna botul\u00ednica-, ahora los cient\u00edficos se han propuesto dar voz a los sin voz. Un equipo de investigadores de Harvard y del MIT han desarrollado un material sint\u00e9tico inyectable que puede ser implantado en las cicatrices de las cuerdas vocales para restaurar su funci\u00f3n.<\/p>\n<p>En vez de enfocar el problema de forma fisiol\u00f3gico, observaron las cuerdas vocales como un problema mec\u00e1nico, es decir, que no atacan el tejido de la cicatriz en las cuerdas vocales.Fijan la sustancia conocida como polietilenglicol (PEG) en las mismas, ya est\u00e1 aprobado por la FDA para otras aplicaciones m\u00e9dicas.<br \/>\u00a0Al jugar con la estructura molecular del PEG, los investigadores fueron capaces de marcar en una variaci\u00f3n que imitaba la viscoelasticidad de los movimientos de las cuerdas vocales, ya que se comporta de forma similar a los tejidos naturales. Adem\u00e1s, puede restaurar la vibraci\u00f3n de las cuerdas vocales que se han endurecido debido a la cicatrizaci\u00f3n. De aprobarse de forma definitiva su uso se deber\u00eda inyectar en periodos semestrales.<\/p>\n<p>fuente: larazon.es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Constituye una patolog\u00eda silenciosa, ya que roba la voz a quienes la sufren. En Espa\u00f1a, hasta 20.000 personas pueden llegar a sufrir disfon\u00eda espasm\u00f3dica, una p\u00e9rdida permanente de la voz.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-11999","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=11999"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/11999\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=11999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=11999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=11999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}