{"id":12027,"date":"2011-07-20T05:03:37","date_gmt":"2011-07-20T09:03:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/yogurt-y-alimentos-con-fibras-ideales-para-mantener-peso\/"},"modified":"2011-07-20T05:03:37","modified_gmt":"2011-07-20T09:03:37","slug":"yogurt-y-alimentos-con-fibras-ideales-para-mantener-peso","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/yogurt-y-alimentos-con-fibras-ideales-para-mantener-peso\/","title":{"rendered":"Yogurt y alimentos con fibras, ideales para mantener peso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Alimentos Con Fibras\" alt=\"Alimentos_Con_Fibras\" src=\"images\/stories\/sosua_images\/Alimentos_Con_Fibras.jpg\" width=\"320\" height=\"213\" \/>Washington.- (PL) El consumo de alimentos ricos en fibras como los vegetales, frutos secos de c\u00e1scara dura y nuevas variedades de yogurt son beneficiosos para mantener el peso, destacan investigadores estadounidenses en un reciente estudio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Publicada en la revista especializada New England Journal of Medicine, la investigaci\u00f3n con un seguimiento de dos d\u00e9cadas y unas 120 mil personas, en su mayor\u00eda mujeres, ten\u00eda como principal objetivo cuantificar el efecto del consumo de determinados tipos de alimentos en la p\u00e9rdida o aumento de peso corporal.<\/p>\n<p>Los productos que lograron una reducci\u00f3n en el peso corporal fueron los sanos, como fruta, frutos secos de c\u00e1scara dura, granos integrales, vegetales y yogur, destacaron los autores en su art\u00edculo.<\/p>\n<p>El alimento asociado al mayor incremento de peso fueron las papas fritas. Cada porci\u00f3n adicional diaria de \u00e9stas ocasion\u00f3 un aumento de m\u00e1s de 1,40 kilos cada cuatro a\u00f1os durante el per\u00edodo del estudio, se\u00f1alan los investigadores de la Escuela de Salud P\u00fablica de Harvard.<\/p>\n<p>Tambi\u00e9n comprobaron que el consumo de porciones adicionales de yogur y frutos secos de c\u00e1scara dura cada d\u00eda tuvo un mayor impacto en la p\u00e9rdida de peso que el consumo de fruta y vegetales.<\/p>\n<p>Entre las posibles causas de estos resultados se encuentran el mayor contenido de fibra y el menor tiempo de digesti\u00f3n de estos alimentos, que pueden incrementar la saciedad, y su mayor consumo podr\u00eda desplazar en la dieta a otros productos altamente procesados, dijo Dariush Mozaffarian, uno de los autores.<\/p>\n<p>Una porci\u00f3n adicional de yogur condujo a una p\u00e9rdida de 0,37 kilos de peso, y con una de vegetales el detrimento fue de 0,1 kilos, ejemplificaron.<\/p>\n<p>Con los frutos secos de c\u00e1scara dura la p\u00e9rdida de peso fue de 0,26 kilos, con fruta de 0,22 kilos y con granos integrales de 0,17 kilos, destaca el art\u00edculo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington.- (PL) El consumo de alimentos ricos en fibras como los vegetales, frutos secos de c\u00e1scara dura y nuevas variedades de yogurt son beneficiosos para mantener el peso, destacan investigadores estadounidenses en un reciente estudio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12027","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12027"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12027\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}