{"id":12088,"date":"2011-07-27T14:21:16","date_gmt":"2011-07-27T18:21:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/felipe-polancoboruga-se-trata-de-qmochilallena-corazon-contentoq-donde-humorista-pretende-donar-utiles-escolares-a-ninospobres-del-pais\/"},"modified":"2011-07-27T14:21:16","modified_gmt":"2011-07-27T18:21:16","slug":"felipe-polancoboruga-se-trata-de-qmochilallena-corazon-contentoq-donde-humorista-pretende-donar-utiles-escolares-a-ninospobres-del-pais","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/felipe-polancoboruga-se-trata-de-qmochilallena-corazon-contentoq-donde-humorista-pretende-donar-utiles-escolares-a-ninospobres-del-pais\/","title":{"rendered":"Felipe PolancoBoruga: Se trata de \u00abMochilaLlena, coraz\u00f3n Contento\u00bb, donde humorista pretende donar \u00fatiles escolares a ni\u00f1ospobres del pa\u00eds"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Felipe Polanco &quot;Boruga&quot;\" alt=\"boruga\" src=\"images\/stories\/sosua_images\/boruga.jpg\" width=\"714\" height=\"547\" \/>Santo Domingo,Rep\u00fablica Dominicana.- Uno de los pilares del humor dominicano, siguetrabajando con su proyecto de televisi\u00f3n con miras a realizar labores socialesque ayuden a los dem\u00e1s y en esta ocasi\u00f3n Felipe Polanco, Boruga anuncia sunuevo segmento&nbsp; \u00abMochila llena,Coraz\u00f3n Contento\u00bb.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El mismo se llevar\u00e1a cabo dentro de su programa \u00abEl Show de Felipe Polanco\u00bb, que setransmite de lunes a viernes de 9 a 10 de la noche, por Telefuturo, Canal 23, y a trav\u00e9sdel n\u00famero de contacto 829-890-7373 o escribiendo al correo <a href=\"mailto:felpodel@gmail.com,o\">felpodel@gmail.com,o<\/a> <a href=\"mailto:elshowdefelipepolanco@gmail.com,pueden\">elshowdefelipepolanco@gmail.com,pueden<\/a> contactar al equipo de log\u00edstica para entregar sus donaciones.<\/p>\n<p>Para este segmento,Boruga, como se le conoce popularmente al gran humorista, pretende convocar asu audiencia para que done mochilas con \u00fatiles escolares que ser\u00e1n destinados ani\u00f1os pobres.<\/p>\n<p>Las entidades querecibir\u00e1n las donaciones son:&nbsp; \u00abNi\u00f1osde Maquiteria\u00bb del comunicador Juan Cruz Triffolio; la Casa Hogar VillaBendici\u00f3n, de la pastora Lucy Cosme, y&nbsp; al Hogar Centro Adonai, de Bayaguana.<\/p>\n<p>\u201cA medida quesigamos recibiendo las mochilas, estaremos ubicando donde enviarlas. Lasempresas que quieran donar, pueden poner sus logos en las mochilas y dentro delos \u00fatiles, mascotas, l\u00e1pices, borras, regla, etc\u201d, expres\u00f3 Felipe Polanco.<\/p>\n<p>\u201cIgualmente pedimos bibliasde facil lectura para los ni\u00f1os y para los mismos padres\u201d, agreg\u00f3 el productorde televisi\u00f3n.<\/p>\n<p>El humorista ha sidoenf\u00e1tico al comunicar que no quiere que le env\u00eden dinero, si no, mochilasllenas de \u00fatiles, con la finalidad de repartirlas a los escolares necesitadospor medio a fundaciones con las que tiene contactos.<\/p>\n<p>Felipe Polanco,tiene una trayectoria de m\u00e1s de 35 a\u00f1os en los medios de comunicaci\u00f3n,desempe\u00f1\u00e1ndose como uno de los principales humoristas de todos los tiempos dela televisi\u00f3n, radio y prensa.<\/p>\n<p>Su trabajo hatrascendido de tal forma que hoy por hoy, es sin dudas uno de los pilares delhumor dominicano y se preserva dentro de las reservas culturales del pa\u00eds.<\/p>\n<p>Ha logrado estatrascendencia, gracias a su carisma natural, humor repentista y a su amplioestudio de la idiosincrasia dominicana, que le permite jugar al dedillo con lascostumbres y forma de actuar del dominicano de a pie, al momento de crear elperfil de sus personajes.<\/p>\n<p>Su programa \u00abElShow de Felipe Polanco\u00bb, que todas las noches transmite por el canal 23,es un compendio de todos sus personajes, el cual aprovecha para hacer uso delbagaje art\u00edstico acumulado por su laureada carrera profesional.<\/p>\n<p>A Felipe PolancoBoruga, y a Freddy Beras Goico, se les considera los primeros raperosdominicanos, dado que fueron los primeros en grabar en este g\u00e9nero el tema\u00bbVen a c\u00e1\u00bb, en el a\u00f1o 1977.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo,Rep\u00fablica Dominicana.- Uno de los pilares del humor dominicano, siguetrabajando con su proyecto de televisi\u00f3n con miras a realizar labores socialesque ayuden a los dem\u00e1s y en esta ocasi\u00f3n Felipe Polanco, Boruga anuncia sunuevo segmento&nbsp; \u00abMochila llena,Coraz\u00f3n Contento\u00bb.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12088","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12088"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12088\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}