{"id":12106,"date":"2011-07-29T19:35:15","date_gmt":"2011-07-29T23:35:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/espectaculos-publico-permitira-que-qcalle-13q-cante-canciones-prohibidas\/"},"modified":"2011-07-29T19:35:15","modified_gmt":"2011-07-29T23:35:15","slug":"espectaculos-publico-permitira-que-qcalle-13q-cante-canciones-prohibidas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/espectaculos-publico-permitira-que-qcalle-13q-cante-canciones-prohibidas\/","title":{"rendered":"ESPECTACULOS P\u00daBLICO PERMITIR\u00c1 QUE \u00abCALLE 13\u00bb CANTE CANCIONES PROHIBIDAS."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"ren\u00e9  perez &quot;calle 13&quot;\" alt=\"32566_calle-13-rene-perez\" src=\"images\/stories\/sosua_images\/32566_calle-13-rene-perez.jpg\" height=\"365\" width=\"550\" \/>El presidente de la Comisi\u00f3n Nacional de Espect\u00e1culos P\u00fablicos y Radiofon\u00eda, JM Hidalgo, durante un encuentro de prensa junto a H\u00e9ctor Romero y Jos\u00e9 Ricardo Taveras, inform\u00f3 que la agrupaci\u00f3n urbana de Puerto Rico, Calle 13, podr\u00e1 cantar sin problemas sus temas prohibidos durante el concierto que realizar\u00e1n la pr\u00f3xima semana en el pa\u00eds.<\/p>\n<p>  <!--more-->  <\/p>\n<p> JM indic\u00f3 que solo le pide a la banda dirigida por Ren\u00e9 P\u00e9rez, que no act\u00faen con vulgaridad y obvien las malas palabras que contengan algunas de sus canciones para as\u00ed no alterar el comportamiento del p\u00fablico, ni ofender a nadie.<\/p>\n<p> En el encuentro realizado en el despacho del funcionario, los promotores art\u00edsticos manifestaron su alegr\u00eda de que el p\u00fablico que asista a la Gran Arena del Cibao, el pr\u00f3ximo s\u00e1bado 6 de Agosto, podr\u00e1 disfrutar y cantar el amplio repertorio de esta popular banda.<\/p>\n<p> H\u00e9ctor Romero manifest\u00f3 que tambi\u00e9n en los medios de comunicaci\u00f3n, como la radio, televisi\u00f3n y en lugares p\u00fablicos; las canciones de Calle 13 pueden volver a sonar seg\u00fan lo explicado por la comisi\u00f3n, solo que los directores de los medios deber\u00e1n editar algunas palabras, pero que las canciones y la m\u00fasica no tienen problema alguno.<\/p>\n<p> Romero agreg\u00f3 sobre el apoyo a la educaci\u00f3n en este concierto revelando que: \u201cComo ya Ren\u00e9 ha expresado a trav\u00e9s de la redes sociales este evento ser\u00e1 destinado para promover que se le otorgue m\u00e1s fondos a la educaci\u00f3n dominicana, un 4% como lo exige la ley, as\u00ed que nosotros como organizadores vamos a donar parte de los recursos adquiridos por boletas para una instituci\u00f3n educativa de la zona norte del pa\u00eds, instituci\u00f3n que la pr\u00f3xima semana daremos a conocer.\u201d<\/p>\n<p> Mientras que Jos\u00e9 Taveras presidente de Todo Tickets explic\u00f3 que el ritmo de las ventas de boletas ha estado excelente y que ya m\u00e1s del 70% del show est\u00e1 agotado.<\/p>\n<p> Calle 13 se presentara el pr\u00f3ximo 6 de Agosto en la Gran Arena del Cibao con el auspicio de Cervecer\u00eda Nacional Dominicana, Aerol\u00edneas MAS y Ron Brugal. Las boletas est\u00e1n a la venta en Uepa Tickets &amp; Movie Max, Todo Tickets, H20, Aleos Moda, Tribeca. El costro de las entradas es de: RD$600 General, RD$1,500 VIP, y RD$2,500 Special Guest \u201cLounge\u201d.<\/p>\n<p><span style=\"font-size: xx-small;\">Visto en <b>Ensegundos.net<\/b><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Comisi\u00f3n Nacional de Espect\u00e1culos P\u00fablicos y Radiofon\u00eda, JM Hidalgo, durante un encuentro de prensa junto a H\u00e9ctor Romero y Jos\u00e9 Ricardo Taveras, inform\u00f3 que la agrupaci\u00f3n urbana de Puerto Rico, Calle 13, podr\u00e1 cantar sin problemas sus temas prohibidos durante el concierto que realizar\u00e1n la pr\u00f3xima semana en el pa\u00eds.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12106","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12106"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12106\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}