{"id":12107,"date":"2011-07-29T19:52:21","date_gmt":"2011-07-29T23:52:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-sandia-tiene-efectos-similares-al-viagra-segun-estudio\/"},"modified":"2011-07-29T19:52:21","modified_gmt":"2011-07-29T23:52:21","slug":"la-sandia-tiene-efectos-similares-al-viagra-segun-estudio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-sandia-tiene-efectos-similares-al-viagra-segun-estudio\/","title":{"rendered":"La sand\u00eda tiene efectos similares al viagra, seg\u00fan estudio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"sandia\" alt=\"q_65_g_8_c_n_p__picnewsa_681999\" src=\"images\/stories\/sosua_images\/q_65_g_8_c_n_p__picnewsa_681999.jpg\" height=\"480\" width=\"640\" \/>Cient\u00edficos dicen que una tajada de sand\u00eda podr\u00eda tener efectos similares a los del viagra por contener citrulina, una sustancia que incluso hasta podr\u00eda aumentar la libido.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Cient\u00edficos de la Universidad de Texas, en Estados Unidos, dicen que una tajada de sand\u00eda podr\u00eda tener efectos similares a los del viagra, el f\u00e1rmaco para la disfunci\u00f3n er\u00e9ctil, e incluso hasta podr\u00eda aumentar la libido.<\/p>\n<p>Los investigadores explicaron que la jugosa fruta contiene citrulina, una sustancia capaz de relajar los vasos sangu\u00edneos, y que al ser consumida pasa a convertirse en arginina, el amino\u00e1cido de la potencia.<\/p>\n<p>\u00abLa buena producci\u00f3n de \u00f3xido n\u00edtrico relaja los vasos sangu\u00edneos, y \u00e9ste es el mismo efecto que tiene el viagra para tratar la disfunci\u00f3n er\u00e9ctil y quiz\u00e1s prevenirla\u00bb, afirmaron los expertos.<\/p>\n<p>El \u00fanico problema es que la citrulina se encuentra en mayor concentraci\u00f3n en la corteza de la sand\u00eda. Los cient\u00edficos est\u00e1n ahora investigando la posibilidad de producir nuevas variedades de la fruta con mayores concentraciones de citrulina en la pulpa.<\/p>\n<p>fuente: www.rpp.com.pe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cient\u00edficos dicen que una tajada de sand\u00eda podr\u00eda tener efectos similares a los del viagra por contener citrulina, una sustancia que incluso hasta podr\u00eda aumentar la libido.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12107","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12107"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12107\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}