{"id":12123,"date":"2011-07-31T04:00:00","date_gmt":"2011-07-31T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/siete-cosas-que-apple-podria-comprar-ahora-que-tiene-mas-dinero-que-eeuu\/"},"modified":"2011-07-31T04:00:00","modified_gmt":"2011-07-31T08:00:00","slug":"siete-cosas-que-apple-podria-comprar-ahora-que-tiene-mas-dinero-que-eeuu","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/siete-cosas-que-apple-podria-comprar-ahora-que-tiene-mas-dinero-que-eeuu\/","title":{"rendered":"Siete cosas que Apple podr\u00eda comprar ahora que tiene m\u00e1s dinero que EE.UU."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" alt=\"Apple-Steve-Jobs-dinero\" src=\"images\/stories\/sosua_images\/Apple-Steve-Jobs-dinero.jpg\" width=\"327\" height=\"224\" \/>Apple acaba de hacer un nuevo r\u00e9cord en su historia, la compa\u00f1\u00eda que dirige Steve Jobs ahora tiene m\u00e1s dinero disponible en el banco, que el mismo gobierno de EE.UU., una de las mayores potencias del mundo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>En cifras, el gobierno de EE.UU. dispone de un total de 73.768 mil millones de d\u00f3lares, mientras que Apple dispone de 75,876 mil millones de d\u00f3lares. Seguro que a Apple el banco que guarde su dinero no le regala una vajilla de porcelana o un juego de sartenes.<\/p>\n<p>Esto es mucho dinero, m\u00e1s del que una persona es capaz de alcanzar de imaginar, tanto que Apple podr\u00eda ser un pa\u00eds en si mismo y ser una de las potencias mundiales, o por lo menos, podr\u00eda comprar los recursos para ser una potencia mundial. Pero es tanto dinero que estoy seguro en Apple le gustar\u00eda tener algunas ideas en que gastar tanto dinero.<\/p>\n<p>Apple podr\u00eda comprar una serie de islas en medio del pac\u00edfico y fundar su propio pa\u00eds, donde para vivir en \u00e9l deber\u00edas de pagar una suscripci\u00f3n anual (esta no es m\u00eda, la le\u00ed en alg\u00fan sitio de Google+, el cr\u00e9dito).<\/p>\n<p>Apple podr\u00eda comprar a HTC, Samsung y LG juntas y de un plumazo eliminar toda competencia al iPhone.<\/p>\n<p>Apple podr\u00eda comprar a Facebook (est\u00e1 valorada en unos US$75b) y por fin arreglar el fail-chat que lleva unas semanas activo (lo odio tanto\u2026) <\/p>\n<p>Apple podr\u00eda rebajar el iPhone a un un solo d\u00f3lar en todo el mundo y as\u00ed, de verdad, matar toda la competencia.<\/p>\n<p>&nbsp;<br \/>Apple podr\u00eda crear su propio programa de exploraci\u00f3n espacial y fundar una colonia en la Luna, o como se le podr\u00eda llamar, iMoon.<\/p>\n<p>Apple podr\u00eda comprar Android a Google y del d\u00eda a la noche todo el que dijo \u201cAndroid es una mier**\u201d, comentar\u00eda lo incre\u00edble que ahora es.<\/p>\n<p>Apple podr\u00eda tatuar su logo en miles de personas dando publicidad gratuita, oh, espera, que esto ya lo hace gente, gratis.<\/p>\n<p>fuente: gizmologia.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apple acaba de hacer un nuevo r\u00e9cord en su historia, la compa\u00f1\u00eda que dirige Steve Jobs ahora tiene m\u00e1s dinero disponible en el banco, que el mismo gobierno de EE.UU., una de las mayores potencias del mundo.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12123","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12123"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12123\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}