{"id":12147,"date":"2011-08-02T14:16:16","date_gmt":"2011-08-02T18:16:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/crean-qtarjetaq-simple-y-barata-para-analisis-de-sangre\/"},"modified":"2014-12-02T09:52:56","modified_gmt":"2014-12-02T13:52:56","slug":"crean-qtarjetaq-simple-y-barata-para-analisis-de-sangre","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/crean-qtarjetaq-simple-y-barata-para-analisis-de-sangre\/","title":{"rendered":"Crean \u00abtarjeta\u00bb simple y barata para an\u00e1lisis de sangre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"la nueva forma de hacer an\u00e1lisis\" alt=\"analisis\" src=\"images\/stories\/sosua_images\/analisis.jpg\" height=\"171\" width=\"304\" \/>Cient\u00edficos presentaron una peque\u00f1a tarjeta, como las cr\u00e9dito, capaz de analizar sangre de forma barata y sencilla.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Se trata de un \u00ablaboratorio en un chip\u00bb con el que se espera poder detectar en cuesti\u00f3n de minutos y a un precio mucho menor que el de los an\u00e1lisis est\u00e1ndar, las infecciones de VIH y s\u00edfiles en las \u00e1reas m\u00e1s remotas y pobres del mundo.<\/p>\n<p>El invento fue dado a conocer este domingo en la revista Nature Medicine.<\/p>\n<p>El llamado mChip es una tarjeta de pl\u00e1stico con diez detectores individuales sobre los que se deposita una sola gota de sangre, seg\u00fan explican sus dise\u00f1adores, los cient\u00edficos de la Universidad de Columbia, en Nueva York.<\/p>\n<p>Las pruebas prototipo para detecci\u00f3n de VIH y s\u00edfilis, llevadas a cabo con cientos de pacientes en Kigali, la capital de Ruanda, proporcionaron casi un 100% de precisi\u00f3n, informan los investigadores.<\/p>\n<p>Seg\u00fan los cient\u00edficos, los resultados pueden obtenerse en cuesti\u00f3n de minutos, en lugar de los d\u00edas o semanas que tardan las pruebas de sangre convencionales.<\/p>\n<p>Adem\u00e1s, esperan que el costo de cada uno de estos kits sea de US$1, mucho m\u00e1s barato que las pruebas de laboratorio.<\/p>\n<p>Los resultados pueden observarse directamente o con un detector de bajo costo.<br \/>VIH en \u00c1frica<\/p>\n<p>\u00abLa idea es hacer accesible a los pacientes en cualquier parte del mundo una gran parte de pruebas de diagn\u00f3stico, en lugar de obligarles a ir a la cl\u00ednica para sacarse sangre y luego esperar d\u00edas para recibir los resultados\u00bb, explica el doctor Samuel Sia, quien dirigi\u00f3 la investigaci\u00f3n.<\/p>\n<p>En realidad ya existen desde hace a\u00f1os an\u00e1lisis de VIH que ofrecen un resultado en cuesti\u00f3n de 30 minutos, pero no son muy precisos ni pueden detectar m\u00faltiples infecciones.<\/p>\n<p>Los investigadores esperan que su mChip sirva para incrementar el n\u00famero de an\u00e1lisis en embarazadas en \u00c1frica.<\/p>\n<p>Actualmente, apenas un cuarto de las embarazadas se somete a pruebas del VIH en los pa\u00edses de ingreso bajo y medio, una cifra que ofrece pocas esperanzas de que pueda ser alcanzada la meta de Naciones Unidas de eliminar la transmisi\u00f3n del virus de madre a hijo en 2015 -uno de los Objetivos del Milenio- seg\u00fan han reconocido funcionarios de la ONU.<\/p>\n<p>En Zambia y en la Rep\u00fablica Democr\u00e1tica del Congo, por ejemplo, solo el 9% y el 6% de las embarazadas, respectivamente, se somete a pruebas del VIH, seg\u00fan la ONU.<\/p>\n<p>Tal como informan los investigadores tambi\u00e9n dise\u00f1aron una versi\u00f3n del mChip para detectar el c\u00e1ncer de pr\u00f3stata, la cual obtuvo en 2010 licencia de comercializaci\u00f3n en Europa.<\/p>\n<p>fuente: BBC Salud<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cient\u00edficos presentaron una peque\u00f1a tarjeta, como las cr\u00e9dito, capaz de analizar sangre de forma barata y sencilla.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-12147","post","type-post","status-publish","format-standard","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12147"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12147\/revisions"}],"predecessor-version":[{"id":33893,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12147\/revisions\/33893"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}