{"id":12237,"date":"2011-08-13T19:27:35","date_gmt":"2011-08-13T23:27:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/rd-ocupa-tercer-lugar-remesas\/"},"modified":"2011-08-13T19:27:35","modified_gmt":"2011-08-13T23:27:35","slug":"rd-ocupa-tercer-lugar-remesas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/rd-ocupa-tercer-lugar-remesas\/","title":{"rendered":"RD ocupa tercer lugar  remesas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"remesas de centroamerica, rd y panama\" alt=\"remesas_de_centroamerica_rd_y_panama\" src=\"images\/stories\/sosua_images\/remesas_de_centroamerica_rd_y_panama.jpg\" width=\"490\" height=\"342\" \/>El documento del Banco Central de Nicaragua registra que las remesas familiares totalizaron en El Salvador US$1,750.7 millones en el 2000 y aumentaron a US$3,431 en el 2010.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Mientras las remesas de Honduras tuvieron un crecimiento vertiginoso en la \u00faltima d\u00e9cada, pues pasaron de US$440.6 millones en el 2000 a US$2,594.1 millones en el 2010.<\/p>\n<p>En el per\u00edodo 1997-2000, la tasa media de crecimiento anual fue mayor de 28 por ciento.<\/p>\n<p>En tanto, Nicaragua recibi\u00f3 US$320 millones de remesas familiares en el 2000 y aument\u00f3 a US$822.8 millones en el 2010<\/p>\n<p>Las remesas&nbsp; en Nicaragua sumaron US$768,6 millones&nbsp; en 2009; US$818,1 millones&nbsp; en 2008 y US$739,6 millones en 2007.<\/p>\n<p>Mientras en Costa Rica, las remesas pasaron de US$120.4 en el 2000 a US$505.5 en el 2010.<\/p>\n<p>La publicaci\u00f3n del Banco Central de Nicaragua trae informaciones sobre balanza de pagos, comercio exterior de bienes, importaciones, turismo, medio ambiente y poblaci\u00f3n.<\/p>\n<p>Las claves<\/p>\n<p>1.&nbsp;&nbsp; Tercer lugar<\/p>\n<p>&nbsp;La Rep\u00fablica Dominicana recibi\u00f3 US$1,689 millones de remesas familiares&nbsp; en el 2000 y US$2,998 millones el a\u00f1o pasado.<\/p>\n<p>2.&nbsp; Guatemala<\/p>\n<p>El l\u00edder de la regi\u00f3n en recibir remesas fue Guatemala, con un monto que ascendi\u00f3 a US$4,126.8 en 2010, mientras el segundo lugar lo ocup\u00f3&nbsp; Honduras, con US$3.431 el a\u00f1o pasado.<\/p>\n<p>fuente: hoy.com.do<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El documento del Banco Central de Nicaragua registra que las remesas familiares totalizaron en El Salvador US$1,750.7 millones en el 2000 y aumentaron a US$3,431 en el 2010.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12237","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12237"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12237\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}