{"id":12272,"date":"2011-08-18T16:14:08","date_gmt":"2011-08-18T20:14:08","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/masticar-mas-para-comer-menos\/"},"modified":"2011-08-18T16:14:08","modified_gmt":"2011-08-18T20:14:08","slug":"masticar-mas-para-comer-menos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/masticar-mas-para-comer-menos\/","title":{"rendered":"Masticar m\u00e1s para comer menos"},"content":{"rendered":"<div>En lo que se refiere a engordar, no s\u00f3lo se trata de lo que comes si<img loading=\"lazy\" decoding=\"async\" src=\"images\/stories\/sosua_images\/metodo16_1.jpg\" width=\"220\" height=\"258\" alt=\"metodo16_1\" title=\"comer despacio\" class=\"caption\" style=\"float: left;\" \/>no de c\u00f3mo lo haces. Masticar mucho podr\u00eda ayudar a ingerir menos cantidad de alimentos y menos calor\u00edas, seg\u00fan un estudio realizado en China.<\/div>\n<p>  <!--more-->  <\/p>\n<div>Adem\u00e1s, prolongar este proceso parece alterar la secreci\u00f3n de las hormonas que regulan el apetito.<\/div>\n<div><\/div>\n<div>Los participantes (14 j\u00f3venes obesos y 16 de peso normal) se sometieron a varios experimentos en los que deb\u00edan masticar cada bocado 15 veces y 40 veces. Los responsables de la investigaci\u00f3n analizaron la relaci\u00f3n de una y otra pauta con la velocidad a la que com\u00edan y las calor\u00edas ingeridas.<\/div>\n<div><\/div>\n<div>Un primer an\u00e1lisis revel\u00f3 que \u00abcomparados con los participantes delgados, los obesos ten\u00edan una mayor tasa de ingesti\u00f3n y masticaban menos veces por cada gramo de comida\u00bb, explica el trabajo publicado en &#8216;The American Journal of Clinical Nutrition&#8217;. Eso, a pesar de que el tama\u00f1o de los bocados y la frecuencia de masticaci\u00f3n eran similares en ambos grupos.<\/div>\n<div><\/div>\n<div>Cuando los j\u00f3venes tuvieron que comer un desayuno t\u00edpico masticando un n\u00famero concreto de veces, los autores observaron que &#8216;entreteniendo&#8217; la comida en la boca durante 40 dentelladas el consumo de calor\u00edas era un 11,9% inferior que cuando s\u00f3lo masticaban 15 veces, sin importar si se trataba de un participante obeso o no.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Efectos sobre la saciedad<\/strong><\/span><\/div>\n<div><\/div>\n<div>\u00abLas hormonas intestinales desempe\u00f1an un papel fisiol\u00f3gico en la regulaci\u00f3n de peso corporal y la homeostasis de la energ\u00eda y pueden ser objetivos \u00fatiles para futuras terapias contra la obesidad\u00bb, explican los autores, procedentes de la Universidad M\u00e9dica Harbin (China).<\/div>\n<div><\/div>\n<div>Seg\u00fan sus resultados, masticar m\u00e1s est\u00e1 asociado con niveles sangu\u00edneos inferiores de grelina, que estimula el apetito, y niveles m\u00e1s altos de CCK, que parece reducirlo. Otras variables, como la cantidad de az\u00facar o de insulina en sangre no variaron.<\/div>\n<div><\/div>\n<div>Entre las posibles explicaciones a este fen\u00f3meno, los autores apuntan a que una mejor trituraci\u00f3n de los alimentos podr\u00eda llevar los nutrientes de forma m\u00e1s eficiente hacia el torrente sangu\u00edneo lo que afectar\u00eda a la secreci\u00f3n hormonal del intestino y los procesos digestivos y de absorci\u00f3n.<\/div>\n<div><\/div>\n<div>Estos hallazgos, que deber\u00e1n confirmarse en otros estudios, \u00abindican que masticar poco es un factor de riesgo para la obesidad. Las intervenciones para mejorar la masticaci\u00f3n podr\u00edan convertirse en una buena herramienta para combatir este problema\u00bb, concluye el estudio.<\/div>\n<div><\/div>\n<div><\/div>\n<div>fuente&gt;: elmundo.es<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En lo que se refiere a engordar, no s\u00f3lo se trata de lo que comes sino de c\u00f3mo lo haces. Masticar mucho podr\u00eda ayudar a ingerir menos cantidad de alimentos y menos calor\u00edas, seg\u00fan un estudio realizado en China.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12272","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12272"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12272\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}