{"id":12289,"date":"2011-08-20T15:31:11","date_gmt":"2011-08-20T19:31:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/beber-con-moderacion-reduciria-el-riesgo-de-sufrir-alzheimer\/"},"modified":"2011-08-20T15:31:11","modified_gmt":"2011-08-20T19:31:11","slug":"beber-con-moderacion-reduciria-el-riesgo-de-sufrir-alzheimer","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/beber-con-moderacion-reduciria-el-riesgo-de-sufrir-alzheimer\/","title":{"rendered":"Beber con moderaci\u00f3n reducir\u00eda el riesgo de sufrir Alzheimer"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" src=\"images\/stories\/sosua_images\/VINO-TINTO-Y-SALUD.jpg\" width=\"350\" height=\"439\" alt=\"VINO-TINTO-Y-SALUD\" title=\"tomar moderadamente reduce el riesgo de sufrir alzheimer\" class=\"caption\" style=\"float: left;\" \/>Beber poco o moderadamente en reuniones sociales, una copa o dos de vino o una cerveza por d\u00eda puede reducir el riesgo de desarrollar la enfermedad de Alzheimer, seg\u00fan investigadores estadounidenses.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Tras analizar m\u00e1s de 140 estudios que datan de hasta 1977 y en los que participaron m\u00e1s de 350.000 personas, cient\u00edficos de la Escuela de Medicina de la Universidad Loyola de Chicago hallaron que quienes beben con moderaci\u00f3n ten\u00edan un 23% menos de posibilidades de desarrollar formas de demencia y problemas cognitivos.<\/div>\n<div><\/div>\n<div><\/div>\n<div>El beber con moderaci\u00f3n significa un m\u00e1ximo de dos bebidas por d\u00eda para los hombres y una para las mujeres. &#8216;Es aceptado que una copa de vino es buena para el coraz\u00f3n y reduce las enfermedades coronarias y cardiovasculares&#8217;, dijo Edward J. Neafsey, coautor del estudio.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Los hallazgos muestran que el consumo moderado de alcohol tiene el mismo efecto en el cerebro. El vino es m\u00e1s beneficioso que la cerveza o los licores, seg\u00fan los resultados aparecidos en la publicaci\u00f3n Neuropsychiatric Disease and Treatment. Pero los investigadores dijeron que la mayor\u00eda de los estudios en el an\u00e1lisis no distingu\u00edan entre los diferentes tipos de alcohol.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Mientras tanto, beber en grandes cantidades, o sea de tres a cinco copas por d\u00eda, estaba asociado con un alto riesgo de demencia.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Tanto Neafsey como su coautor Michael A. Collins, profesores de farmacolog\u00eda molecular y terap\u00e9utica, sugieren que peque\u00f1as cantidades de alcohol refuerzan las c\u00e9lulas cerebrales y les permiten enfrentar mejor el estr\u00e9s que lleva a la demencia m\u00e1s adelante en la vida.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Otra teor\u00eda sugiere que los conocidos beneficios cardiovasculares del beber con moderaci\u00f3n tambi\u00e9n pueden mejorar la circulaci\u00f3n sangu\u00ednea hacia el cerebro aumentando el metabolismo cerebral. El ejercicio, la educaci\u00f3n y una dieta mediterr\u00e1nea tambi\u00e9n pueden reducir los riesgos de desarrollar demencia.<\/div>\n<div><\/div>\n<div><\/div>\n<div>fuente: terra.com<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Beber poco o moderadamente en reuniones sociales, una copa o dos de vino o una cerveza por d\u00eda puede reducir el riesgo de desarrollar la enfermedad de Alzheimer, seg\u00fan investigadores estadounidenses.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12289","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12289"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12289\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}