{"id":12290,"date":"2011-08-20T15:31:43","date_gmt":"2011-08-20T19:31:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/carolyn-aquino-habla-ennoche-de-luz-sobre-su-salida-de-super-exitos\/"},"modified":"2011-08-20T15:31:43","modified_gmt":"2011-08-20T19:31:43","slug":"carolyn-aquino-habla-ennoche-de-luz-sobre-su-salida-de-super-exitos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/carolyn-aquino-habla-ennoche-de-luz-sobre-su-salida-de-super-exitos\/","title":{"rendered":"Carolyn Aquino habla enNoche de Luz, sobre su salida de \u201cS\u00faper Exitos\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Caroline Aquino\" alt=\"Caroline_Aquino\" src=\"images\/stories\/sosua_images\/Caroline_Aquino.jpg\" width=\"759\" height=\"500\" \/>Santo Domingo, Rep\u00fablica Dominicana.-&nbsp; Carolyn Aquino,&nbsp; habla en exclusiva con Luz Garc\u00eda sobre susalida del programa \u00abTus Ma\u00f1anas\u00bb y \u201cS\u00faper \u00c9xitos\u201d, en un encuentro en elprograma \u201cNoche de Luz\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Durante la entrevista que ser\u00e1 transmitida este s\u00e1bado 20 de agosto alas 9:00 de la noche, en el programa porAntena Latina, Canal 7, Caroline, habla de su vida profesional y da algunaspinceladas sobre su vida personal.<\/p>\n<p>La joven comunicadora confiesa que no sab\u00eda todo lo que estaba pasando enel programa \u201cS\u00faper \u00c9xitos\u201d, ya que se desempe\u00f1aba s\u00f3lo como talento, pero queal momento de salir le presentaron una oferta para que se quedase en el canal,la cual declin\u00f3.<\/p>\n<p>&nbsp;La conductora revela a Luz Garc\u00eda, que al momento de tomar una decisi\u00f3n, se inclin\u00f3&nbsp; por irse con \u201cBebeto\u201dya que, seg\u00fan dice, siempre ha trabajado con \u201cAlberto Bernab\u00e9 Television\u201d, empresaque ha confiado en ella y dado la oportunidad de estar en un programa l\u00edder almedio d\u00eda.<\/p>\n<p>\u201cEn cuanto a loscambios que se hicieron a partir&nbsp; de lafusi\u00f3n de \u201cTus Ma\u00f1anas\u201d y \u201cS\u00faper Exitos\u201d, en ning\u00fan momento mi intenci\u00f3n fue quitarprotagonismo a Michael Miguel\u201d, expresa la presentadora.<\/p>\n<p>\u201cHubo cambios en la producci\u00f3n, que fueron cosas que seescaparon de mis manos, y yo ten\u00eda que aprovechar esa oportunidad\u201d, revela.<\/p>\n<p>Habla de su amistadcon Alex Macias, la cual dijo va m\u00e1s all\u00e1 de la TV, pues&nbsp; tienen 8 a\u00f1os trat\u00e1ndose y que eso notiene nada que ver con el trabajo.<\/p>\n<p>Entre risas,confiesa que s\u00ed se puede vivir de la televisi\u00f3n, dado que ella esta viviendo delos medios de comunicaci\u00f3n.<\/p>\n<p>Noche de Luz tambi\u00e9ntrae una entrevista con Ram\u00f3n Pastrano, quien habla de sus 10 a\u00f1os detrayectoria en la Rep\u00fablica Dominicana.<\/p>\n<p>Pastrano aprovecha la ocasi\u00f3npara aclarar que no tiene ning\u00fan conflicto con el productor y conductor detelevisi\u00f3n Iv\u00e1n Ruiz.<\/p>\n<p>\u201cNoche de Luz\u201d, siguesiendo el programa l\u00edder de la televisi\u00f3n semanal dominicana como la principalrevista de variedades, por su producci\u00f3n jovial y din\u00e1mica, con los artistas y figuras del momento.<br \/><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Luz Garca y Ram\u00f3n Pastrano\" alt=\"Luz_Garca_y_Ramn_Pastrano\" src=\"images\/stories\/sosua_images\/Luz_Garca_y_Ramn_Pastrano.jpg\" width=\"500\" height=\"669\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, Rep\u00fablica Dominicana.-&nbsp; Carolyn Aquino,&nbsp; habla en exclusiva con Luz Garc\u00eda sobre susalida del programa \u00abTus Ma\u00f1anas\u00bb y \u201cS\u00faper \u00c9xitos\u201d, en un encuentro en elprograma \u201cNoche de Luz\u201d.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12290","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12290"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12290\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}