{"id":12291,"date":"2011-08-20T15:36:12","date_gmt":"2011-08-20T19:36:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-coe-pide-a-la-poblacion-estar-atenta-a-onda-tropical\/"},"modified":"2011-08-20T15:36:12","modified_gmt":"2011-08-20T19:36:12","slug":"el-coe-pide-a-la-poblacion-estar-atenta-a-onda-tropical","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-coe-pide-a-la-poblacion-estar-atenta-a-onda-tropical\/","title":{"rendered":"El COE pide a la poblaci\u00f3n estar atenta a onda tropical"},"content":{"rendered":"<div><strong><img loading=\"lazy\" decoding=\"async\" src=\"images\/stories\/sosua_images\/g3_ir_123.jpg\" width=\"640\" height=\"480\" alt=\"g3_ir_123\" title=\"onda tropical que se localiza a unos 880 km al este de las Antillas Menores\" class=\"caption\" style=\"float: left;\" \/>SD.<\/strong> El Centro de Operaciones de Emergencias (COE) inform\u00f3 ayer que vigila junto a la Oficina Nacional de Meteorolog\u00eda la evoluci\u00f3n de una activa onda tropical localizada anoche a 1,005 kil\u00f3metros al Este de las Antillas Menores y que tiene posibilidades de incrementar su velocidad al llegar a las Antillas Menores.<\/div>\n<p>  <!--more-->  <\/p>\n<div>Su probabilidad de convertirse en cicl\u00f3n es de un 60 por ciento.<\/div>\n<div><\/div>\n<div><\/div>\n<div>En tal sentido, el organismo recomend\u00f3 a la poblaci\u00f3n estar atenta al fen\u00f3meno, que se mueve a 20 kil\u00f3metros por hora. Para hoy la Onamet inform\u00f3 que se esperan aguaceros dispersos y tronadas en Santo Domingo y otras partes del territorio, debido a la incidencia de una vaguada.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Inform\u00f3 que ayer se form\u00f3 la depresi\u00f3n tropical no. 8, que en la tarde se convirti\u00f3 en la tormenta tropical Harvey pero no ofrece peligro para el pa\u00eds.<\/div>\n<div><\/div>\n<div><\/div>\n<div>FUENTE: diariolibre.com<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SD. El Centro de Operaciones de Emergencias (COE) inform\u00f3 ayer que vigila junto a la Oficina Nacional de Meteorolog\u00eda la evoluci\u00f3n de una activa onda tropical localizada anoche a 1,005 kil\u00f3metros al Este de las Antillas Menores y que tiene posibilidades de incrementar su velocidad al llegar a las Antillas Menores.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12291","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12291"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12291\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}