{"id":12303,"date":"2011-08-22T06:07:20","date_gmt":"2011-08-22T10:07:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/alerta-a-22-provincias-la-tormenta-tropical-irene-amenaza-a-rd\/"},"modified":"2011-08-22T06:07:20","modified_gmt":"2011-08-22T10:07:20","slug":"alerta-a-22-provincias-la-tormenta-tropical-irene-amenaza-a-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alerta-a-22-provincias-la-tormenta-tropical-irene-amenaza-a-rd\/","title":{"rendered":"ALERTA A 22 PROVINCIAS: La tormenta tropical \u201cIrene\u201d amenaza a RD"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"Tormenta Irene\" alt=\"tormenta_irene\" src=\"images\/stories\/sosua_images\/tormenta_irene.jpg\" width=\"478\" height=\"331\" \/>La tormenta tropical \u201cIrene\u201d continuaba intensific\u00e1ndose anoche, alcanzando vientos de 95 kil\u00f3metros por hora en direcci\u00f3n Oeste-Noroeste.<br \/> <!--more-->  <\/p>\n<p>El informe divulgado anoche a las 10:00 por el meteor\u00f3logo, Ren\u00e9 Ledesma, indica tambi\u00e9n que el fen\u00f3meno redujo su velocidad de traslaci\u00f3n de 30 a 24 kil\u00f3metros por hora.<\/p>\n<p>Detall\u00f3 que en las primeras horas de la ma\u00f1ana de hoy sus efectos se sentir\u00e1n en la parte oriental de la isla y en el transcurso del d\u00eda sus efectos estar\u00e1n sobre la Hispaniola.<\/p>\n<p>Inform\u00f3 que en ese sentido la Oficina Nacional de Meteorolog\u00eda (Onamet) mantiene el aviso de hurac\u00e1n desde Cabo Enga\u00f1o hasta Pedernales, y desde Cabo enga\u00f1o hasta la Bah\u00eda de Manzanillo.<\/p>\n<p>Ledesma precis\u00f3 que de acuerdo al perfil que mantiene la tormenta tropical Irene, entrar\u00e1 al pa\u00eds convertido en un hurac\u00e1n categor\u00eda uno.<\/p>\n<p>Explic\u00f3 que a las 6:00 de la tarde de ayer el centro de la tormenta tropical Irene fue localizado cerca de la latitud 17.7 norte y longitud 64.6 Oeste, a unos 370 kil\u00f3metros al Este-Sureste de Cabo Enga\u00f1o.<\/p>\n<p>La directora de la Onamet, Gloria Ceballos, inform\u00f3 que el fen\u00f3meno traer\u00e1 abundantes lluvias y advirti\u00f3 que se esperan valores acumulados de 200 mil\u00edmetros, pero en zonas monta\u00f1osas podr\u00eda llegar hasta a 250 mil\u00edmetros.<\/p>\n<p>\u201cLos suelos que presentan mayor saturaci\u00f3n son los de la parte caribe\u00f1a, producto de las \u00faltimas ondas tropicales y la mayor cantidad de precipitaciones ha sido hacia la vertiente Sur de la Cordillera Central\u201d, agreg\u00f3.<\/p>\n<p><b>Las alertas <\/b><br \/>Tomando en cuenta los pron\u00f3sticos de anoche, el Centro de Operaciones de Emergencia (COE) aument\u00f3 la alerta roja de 14 a 22 provincias, mientras otras diez se encuentran en alerta amarilla.<\/p>\n<p>El director del COE, general Juan Manuel M\u00e9ndez, inform\u00f3 que se encuentran bajo alerta roja las provincias La Altagracia, La Romana, San Pedro de Macor\u00eds, Santo Domingo, San Crist\u00f3bal, Peravia, San Jos\u00e9 de Ocoa, Azua, El Seibo, Hato Mayor, Barahona, Pedernales, San Juan de la Maguana, Independencia, Bahoruco, Monte Cristi, Puerto Plata, Espaillat, Mar\u00eda Trinidad S\u00e1nchez, Saman\u00e1, Duarte y el Distrito Nacional.<\/p>\n<p>Mientras emiti\u00f3 alerta amarilla para Monte Plata, S\u00e1nchez Ram\u00edrez, Monse\u00f1or Noel, La Vega, Santiago, El\u00edas Pi\u00f1a, Dajab\u00f3n, Valverde, Hermanas Mirabal y Santiago Rodr\u00edguez.<\/p>\n<p>Asimismo pidi\u00f3 a los residentes en zonas de alto riesgo y pr\u00f3ximas a r\u00edos, arroyos y ca\u00f1adas, as\u00ed como en zonas vulnerables a deslizamientos e inundaciones de las provincias mencionadas, que tomen las medidas de precauci\u00f3n y est\u00e9n atentos a las recomendaciones de los organismos de socorro.<\/p>\n<p><b>Las presas <\/b><br \/>El Comit\u00e9 de Operaci\u00f3n de Presas y Embalses inici\u00f3 ayer la operaci\u00f3n de estos sistemas para que puedan regular las crecidas que generen las lluvias. El director del Instituto Nacional de Recursos Hidr\u00e1ulicos (Indrhi), Frank Rodr\u00edguez, inform\u00f3 que la presa de Tavera, el contraembalse Las Bar\u00edas y Valdesia, Sabana Yegua, estar\u00e1n operando a m\u00e1xima capacidad.<\/p>\n<p><b>Apoyo para v\u00edctimas<\/b><br \/>El COE cuenta con 2 mil 364 albergues a nivel nacional, incluyendo las iglesias, villas ol\u00edmpicas y las escuelas, que son el \u00faltimo recurso.<\/p>\n<p><b>Personal disponible<\/b><br \/>Acuartelan miembros de las Fuerzas Armadas y activan Plan Rel\u00e1mpago, ante el inminente paso de Irene por el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tormenta tropical \u201cIrene\u201d continuaba intensific\u00e1ndose anoche, alcanzando vientos de 95 kil\u00f3metros por hora en direcci\u00f3n Oeste-Noroeste.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12303","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12303"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12303\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}