{"id":12308,"date":"2011-08-22T21:00:00","date_gmt":"2011-08-23T01:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/estudio-navegar-por-internet-ayuda-en-el-trabajo\/"},"modified":"2011-08-22T21:00:00","modified_gmt":"2011-08-23T01:00:00","slug":"estudio-navegar-por-internet-ayuda-en-el-trabajo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/estudio-navegar-por-internet-ayuda-en-el-trabajo\/","title":{"rendered":"Estudio: Navegar por internet ayuda en el trabajo"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" src=\"images\/stories\/sosua_images\/dormir2-300x199.jpg\" width=\"300\" height=\"199\" alt=\"dormir2-300x199\" title=\"navegar en el internet aumenta su productividad\" class=\"caption\" style=\"float: left;\" \/>Aunque que muchas oficinas insisten con bloquear Facebook, YouTube y otros sitios para que sus empleados \u201cno pierdan el tiempo\u201d, es posible que en realidad est\u00e9n haciendo que sus trabajadores trabajen peor.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Seg\u00fan un nuevo estudio llamado \u201cImpacto del ciberholgazaneo en el compromiso psicol\u00f3gico\u201d llevado a cabo por la Universidad de Singapur, navegar por internet ayuda a refrescarle la mente a los trabajadores cansados, y mejora su productividad. El efecto de navegar ser\u00eda mejor que hacer llamados telef\u00f3nicos personales o mandar mails.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Se trata de un estudio m\u00e1s que viene a sumarse a varios que dicen m\u00e1s o menos lo mismo. Los investigadores hicieron dos pruebas para evaluar esto. En la primera, dividieron a un grupo de 96 estudiantes universitarios de administraci\u00f3n en tres: un grupo de control, un grupo con un \u201crecreo de descanso\u201d sin navegar, y un grupo que pod\u00eda surfear la web. Todos los sujetos pasaron 20 minutos marcando todas las letras \u201ce\u201d que encontraran en un texto de prueba.<\/div>\n<div><\/div>\n<div><\/div>\n<div>En los siguientes 10 minutos, se le pidi\u00f3 al grupo de control hacer otra tarea simple, al segundo grupo se les permiti\u00f3 hacer lo que quisieran menos surfear por internet; y al tercer grupo se le permiti\u00f3 navegar por la web. Luego, todos los grupos deb\u00edan volver a destacar m\u00e1s letras en un texto.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>Los investigadores descubrieron que quienes navegaron por la web fueron significativamente m\u00e1s productivos en la tarea que los otros dos grupos, y reportaron menos niveles de cansancio mental, aburrimiento, y un mayor nivel de compromiso.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\u201cNavegar por internet entrega una importante funci\u00f3n restauradora\u201d, concluyeron los autores.<\/div>\n<div><\/div>\n<div><\/div>\n<div>La segunda prueba evalu\u00f3 el impacto que ten\u00eda hacer llamados telef\u00f3nicos o mandar mails, que result\u00f3 ser \u201cmuy distractor\u201d para los trabajadores. Seg\u00fan los investigadores, cuando las personas navegan, \u201cnormalmente eligen los sitios que a les gustan \u2013 es como ir por un caf\u00e9 o un snack. Los descansos de este tipo son placenteros, rejuveneciendo a quien navega\u201d. Por el contrario, no se puede controlar lo que a uno le llega por mail, y leerlos y responderlos demanda m\u00e1s esfuerzo mental porque tienes que poner atenci\u00f3n a lo que dice el correo.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Los investigadores llamaron as\u00ed a los empleadores a no sobre-restringir el acceso a la web de los trabajadores. Recomendaron darle tiempo a los empleados para que naveguen, porque \u201ctiene un impacto saludable en la productividad\u201d. Ojal\u00e1 su consejo se tome en cuenta.<\/div>\n<div><\/div>\n<div><\/div>\n<div>fuente: fayerwayer.com<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque que muchas oficinas insisten con bloquear Facebook, YouTube y otros sitios para que sus empleados \u201cno pierdan el tiempo\u201d, es posible que en realidad est\u00e9n haciendo que sus trabajadores trabajen peor.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-12308","post","type-post","status-publish","format-standard","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12308"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12308\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}