{"id":12441,"date":"2011-09-06T20:20:25","date_gmt":"2011-09-07T00:20:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/culpan-a-alex-bueno-de-provocar-qreperperoq-en-azua\/"},"modified":"2011-09-06T20:20:25","modified_gmt":"2011-09-07T00:20:25","slug":"culpan-a-alex-bueno-de-provocar-qreperperoq-en-azua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/culpan-a-alex-bueno-de-provocar-qreperperoq-en-azua\/","title":{"rendered":"CULPAN A ALEX BUENO DE PROVOCAR \u00abREPERPERO\u00bb EN AZUA."},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"alex bueno\" alt=\"Alex-Bueno\" src=\"images\/stories\/sosua_images\/Alex-Bueno.jpeg\" width=\"240\" height=\"160\" \/>AZUA.-<\/strong> El presidente de las fiestas patronales de Azua, Sim\u00f3n Bol\u00edvar Beltr\u00e9, lament\u00f3 un incidente ocurrido la noche del pasado s\u00e1bado, cuando el merenguero Alex Bueno, supuestamente provoc\u00f3 un desorden cuando incit\u00f3 a los presentes a hacer pol\u00edtica desde una tarima.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Beltr\u00e9 dijo que Alex Bueno comenz\u00f3 a gritar lleg\u00f3 Pap\u00e1, esto, a pesar que le llam\u00f3 la atenci\u00f3n varias veces para que desistiera de hacer pol\u00edtica en la tarima, pero el merenguero se neg\u00f3.<\/p>\n<p>Beltr\u00e9 agrega que esto provoc\u00f3 que parte del p\u00fablico le lanzaran objetos como agua, botellas y vasos pl\u00e1sticos, situaci\u00f3n que gener\u00f3 un tiroteo donde uno de los integrantes del artista que fue identificado como Cruchy P\u00e9rez, result\u00f3 herido en una mano.<\/p>\n<p>[Noticiassin.com]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AZUA.- El presidente de las fiestas patronales de Azua, Sim\u00f3n Bol\u00edvar Beltr\u00e9, lament\u00f3 un incidente ocurrido la noche del pasado s\u00e1bado, cuando el merenguero Alex Bueno, supuestamente provoc\u00f3 un desorden cuando incit\u00f3 a los presentes a hacer pol\u00edtica desde una tarima.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12441","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12441"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12441\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}