{"id":12443,"date":"2011-09-07T04:00:00","date_gmt":"2011-09-07T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/venya-carolina-retorna-a-la-television-en-el-candelazo-de-emilio-angeles\/"},"modified":"2011-09-07T04:00:00","modified_gmt":"2011-09-07T08:00:00","slug":"venya-carolina-retorna-a-la-television-en-el-candelazo-de-emilio-angeles","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/venya-carolina-retorna-a-la-television-en-el-candelazo-de-emilio-angeles\/","title":{"rendered":"Venya Carolina retorna a la television en El Candelazo de Emilio Angeles"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" class=\"caption\" title=\"venya carolina retorna a la tv\" alt=\"6121004645_2ca09f2695_z\" src=\"images\/stories\/sosua_images\/6121004645_2ca09f2695_z.jpg\" width=\"425\" height=\"640\" \/>La controversial modelo y presentadora Venya Carolina ha regresado a la pantalla chica y ahora acompa\u00f1a a Emilio Angeles en la nueva temporada nocturna del \u201cEl Candelazo\u201d, por Supercanal 33, todas las noches de lunes a viernes a las 8:00 P.M.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Venya Carolina dijo que ha entrado espont\u00e1neamente a conducir en \u201cEl Candelazo\u201d con Emilio Angeles, porque \u201csiempre es un encanto trabajar con un amigo\u201d y \u00e9l \u201ces su amigo personal\u201d. El programa se transmite todas las noches de 8:00 P.M a 9:00 P.M por Supercanal.\u2028Dijo que viene por Telecentro con su espacio \u201cZona R\u201d y que se transmitir\u00e1 a Estados Unidos por la se\u00f1al de Supercanal Caribe. Inform\u00f3 que tiene invitaciones para programas y revistas europeos, es decir \u201cse est\u00e1 hablando de Venya en otros idiomas\u201d.<\/p>\n<p>Sobre las cr\u00edticas de algunos presentadores dijo que no les importan. \u00abMientras m\u00e1s da\u00f1os me sigan haciendo, m\u00e1s bien le van a hacer a mi carrera\u201d,&nbsp; dijo se\u00f1alando al mismo tiempo que en alg\u00fan momento no ha estado en el lugar indicado, pero est\u00e1 con Dios y las cosas negativas ser\u00e1n para bien.<\/p>\n<p>Expres\u00f3 que una empresa de Estados Unidos quiere representarla.<\/p>\n<p>Entre otras cosas dijo que est\u00e1 actualmente soltera y&nbsp; que por ahora no piensa tener una relaci\u00f3n o casarse.&nbsp; Dice empero que tiene amigos especiales y enamorados, pero&nbsp; est\u00e1 enfocada en su trabajo y en su carrera.<\/p>\n<p>Emilio Angeles, productor de El Candelazo, inform\u00f3 que prepara un segmento los mi\u00e9rcoles que ser\u00e1 \u201cEl Candelazo Flow 911\u201d, donde presentar\u00e1n exponentes urbanos y que nadie mejor que Venya para hacerlo. \u201cEsto ha sido una confluencia espiritual positiva y hasta que ella quiera, solo que no permitiremos que nadie nos haga da\u00f1o\u201d, dijo Emilio.<br \/>\u201cEl Purecillo\u201d \u2013como tambi\u00e9n se conoce a Emilio- dijo que Venya es una mujer que tiene muchas cualidades y merece una oportunidad. Record\u00f3 que cuando la comunicadora Laura Hern\u00e1ndez tuvo un percance de mayor trascendencia negativamente, los puertorrique\u00f1os la recibieron con un programa Prime Time\u201d.<\/p>\n<p>\u00abPero, aqu\u00ed acabamos con nuestras figuras, porque el dominicano es lamb\u00f3n del extranjero, siempre y cuando no sea haitiano, ni prieto\u201d, dijo Emilio.<\/p>\n<p>\u201cEsto se di\u00f3 y ser\u00e1 hasta que ella quiera, porque ella brilla con luz propia, la respeto mucho y me respeta, hemos trabajado mucho y conozco la tem\u00e1tica de animar de Venya\u201d expreso Emilio.<\/p>\n<p>En torno a las fotos que se publicaron de ella desnunda, dijo que \u201ceso no se va a quedar as\u00ed\u201d y que \u201cno sabe qu\u00e9 le pusieron en la bebida, pero que eso puede servir para que mucha gente aprenda, a no tener confianza en amigos o conocidos.<\/p>\n<p>Se refiri\u00f3 a que no estaba consciente cuando le tomaron las fotos donde aparece desnuda y que cuando dijo que \u201cera un montaje\u201d, es en el sentido que ella no estaba consciente, ni autoriz\u00f3 a esas personas -a las que llam\u00f3 \u201cratas\u201d- a tomarlas. \u201cAlgo pas\u00f3, pero no s\u00e9, porque nunca deja sus tragos en la mesa\u201d, dijo Venya, prefiriendo no avanzar muchos detalles, porque da\u00f1ar\u00eda la investigaci\u00f3n.<\/p>\n<p>Dijo ser \u201cla madre y Diva del Genero Urbano\u201d, y que ya sus hijos L\u00e1piz Consciente, Don Miguelo, Vakero y otros, est\u00e1n grandes y que logr\u00f3 parte de lo que quer\u00eda, que el movimiento creciera, ahora tiene que retomar y hacer crecer su carrera como ellos.\u2028<\/p>\n<p>Sobre la presentadora Yelitza Lora \u2013a quien conoce por \u201cFlor\u201d, dijo \u201cno es su amiga de ni\u00f1ez\u201d y que no es mujer de amenazas, pero parece que ella quiere coger \u201crating\u201d.<\/p>\n<p>\u201cQuiere hacer los programas que yo hice, quiere copiar mi estilo, pienso que ella quiere sonar a costa m\u00eda; por qu\u00e9 cree que la voy a amenazar, como se public\u00f3,&nbsp; si quisiera darle, le doy\u201d, expres\u00f3<\/p>\n<p>Se enter\u00f3 por los medios, que dijo le iba a demandar y luego le escuch\u00f3 la hablando positivamente sobre ella. \u201cLe exhorto a hacer su carrera, ya que la llev\u00e9 de la mano para que terminara su bachillerato y duramos unos a\u00f1os siendo amigas, pero ella debe resignarse y hacer igual que yo, que doy sus espacios a Melymel, Arianna Puello, La Materialista, Milka y otras\u201d, afirm\u00f3.<\/p>\n<p>\u201cMami, si me vas a copiar, S\u00edgueme copiando, pero dame hilo\u201d, . Agradeci\u00f3 a los medios de prensa, que de una manera u otra han estado comentando su situaci\u00f3n y dijo que respeta su trabajo.(De Imagenesdominicanas)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La controversial modelo y presentadora Venya Carolina ha regresado a la pantalla chica y ahora acompa\u00f1a a Emilio Angeles en la nueva temporada nocturna del \u201cEl Candelazo\u201d, por Supercanal 33, todas las noches de lunes a viernes a las 8:00 P.M.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12443","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12443"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12443\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}