{"id":12749,"date":"2011-09-25T14:50:13","date_gmt":"2011-09-25T18:50:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/envio-remesas-a-rd-crece-en-us1007mm-en-semestre\/"},"modified":"2011-09-25T14:50:13","modified_gmt":"2011-09-25T18:50:13","slug":"envio-remesas-a-rd-crece-en-us1007mm-en-semestre","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/envio-remesas-a-rd-crece-en-us1007mm-en-semestre\/","title":{"rendered":"Env\u00edo remesas a RD crece en US$100.7MM en semestre"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-12748\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/09\/flijo_de_remesas.jpg\" width=\"278\" height=\"206\" alt=\"flijo_de_remesas\" class=\"caption\" \/>El flujo de remesas que llega al pa\u00eds representa cerca del 6% del Producto Interno Bruto (PIB). En el primer semestre de este a\u00f1o, el pa\u00eds recibi\u00f3 remesas por US$1,539.4 millones, lo que representa US$100.7 millones m\u00e1s que en igual per\u00edodo del 2010.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Empero, el flujo de remesas que recibi\u00f3 el pa\u00eds en el 2010, ascendente a US$2,998 millones, fue menor en US$43.5 millones al 2009, cuando el pa\u00eds recibi\u00f3 remesas por US$3,041.5 millones.&nbsp;<\/div>\n<div><\/div>\n<div><\/div>\n<div>Para Edigarbo Garc\u00eda, vicepresidente de Remesas Dominicanas del Banco BHD, el promedio de env\u00edo al pa\u00eds desde EE.UU. es de US$253 y de US$400 desde los pa\u00edses de la Uni\u00f3n Europea. Expuso, durante la tertulia de la C\u00e1mara de Comercio Dom\u00ednico Francesa sobre \u00abmigraci\u00f3n femenina, remesas y co-desarrollo\u00bb, junto a Irma Nicasio Rodr\u00edguez, asesora de pol\u00edtica de g\u00e9nero del Poder Ejecutivo, que el 73 % por ciento de las remesas que reciben los dominicanos va al consumo.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Asimismo que el 63% de las remesas los reciben las mujeres y que 42 de cada 100 hogares dominicanos recibe remesas y que el monto que recibe el pa\u00eds representa casi el 6% del Producto Interno Bruto (PIB).&nbsp;<\/div>\n<div><\/div>\n<div><\/div>\n<div>Una investigaci\u00f3n auspiciada por las Naciones Unidas estableci\u00f3 que las remesas han contribuido al mejoramiento de las condiciones de vida de miles de familias dominicanas, pero que las mujeres, las mayores receptoras, no pueden disponer de esos recursos, sino que est\u00e1n atadas a las decisiones de los hombres.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Los especialistas se\u00f1alaron la importancia que tienen las remesas, las cuales ayudan a solucionar problemas econ\u00f3micos.<\/div>\n<div><\/div>\n<div><\/div>\n<div>fuente: www.diariolibre.com<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El flujo de remesas que llega al pa\u00eds representa cerca del 6% del Producto Interno Bruto (PIB). En el primer semestre de este a\u00f1o, el pa\u00eds recibi\u00f3 remesas por US$1,539.4 millones, lo que representa US$100.7 millones m\u00e1s que en igual per\u00edodo del 2010.<\/p>\n","protected":false},"author":3,"featured_media":12748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12749"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/12748"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}