{"id":12814,"date":"2011-09-28T19:17:46","date_gmt":"2011-09-28T23:17:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/don-omar-taa-quillao-le-bloquearon-un-video-en-youtube\/"},"modified":"2011-09-28T19:17:46","modified_gmt":"2011-09-28T23:17:46","slug":"don-omar-taa-quillao-le-bloquearon-un-video-en-youtube","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/don-omar-taa-quillao-le-bloquearon-un-video-en-youtube\/","title":{"rendered":"Don Omar ta\u00b4 quillao, le bloquearon un video en Youtube"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-12813\" style=\"float: left;\" class=\"caption\" title=\"don omar\" alt=\"28_09_2011_08_15_57_839895610_1\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/09\/28_09_2011_08_15_57_839895610_1.jpg\" width=\"502\" height=\"234\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/09\/28_09_2011_08_15_57_839895610_1.jpg 502w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/09\/28_09_2011_08_15_57_839895610_1-300x139.jpg 300w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/>Don Omar ped\u00eda en la red social a Lucenzo con quien canto a d\u00fao la canci\u00f3n, un poco de respeto a los fans por haber intervenido en el bloqueo del video en el canal de m\u00fasica.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Al parecer Lucenzo y su manager habr\u00edan tomado la decisi\u00f3n de pedir que el video ya no se vea en YouTube as\u00ed lo dejaba ver Don Omar con sus mensajes en la red social:<\/p>\n<p>@Lucenzo no creo justo que hayan prohibido el video de DANZA KUDURO por tus decisiones y las de tu manejador. Los fanaticos merecen respeto.<\/p>\n<p>@Lucenzo los fanaticos hispanoamericanos que has conquistado NO pueden ser VICTIMAS de las RIDICULAS decisiones de tu manejador.<\/p>\n<p>@Lucenzo en el tintero tenemos algunas situaciones ya! Arreglan los acuerdos de el video para que los fanaticos alrededor del mundo lo-<\/p>\n<p>&#8211; puedan ver o esperen mi demanda. Yo no soy quien vera como ustedes le faltan el respeto a mis fanaticos ni a la musica.<\/p>\n<p>@Lucenzo creo que eres lo suficientemente AGRADECIDO con los fanaticos que te han hecho quien eres, arregla esta FALTA DE RESPETO.<\/p>\n<p>Desde el anuncio cientos de fan\u00e1ticos han mandado mensajes de apoyo a Don Omar.<\/p>\n<p>fuente: <a href=\"http:\/\/www.generaccion.com\/noticia\/123032\/video-oficial-danza-kuduro-bloqueado-youtube\">www.generaccion.com<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Don Omar ped\u00eda en la red social a Lucenzo con quien canto a d\u00fao la canci\u00f3n, un poco de respeto a los fans por haber intervenido en el bloqueo del video en el canal de m\u00fasica.<\/p>\n","protected":false},"author":3,"featured_media":12813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12814"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/12813"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}