{"id":12852,"date":"2011-09-30T19:09:42","date_gmt":"2011-09-30T23:09:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/un-nino-de-11-anos-cambio-de-sexo-y-desato-una-polemica-en-eeuu\/"},"modified":"2011-09-30T19:09:42","modified_gmt":"2011-09-30T23:09:42","slug":"un-nino-de-11-anos-cambio-de-sexo-y-desato-una-polemica-en-eeuu","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-nino-de-11-anos-cambio-de-sexo-y-desato-una-polemica-en-eeuu\/","title":{"rendered":"Un ni\u00f1o de 11 a\u00f1os cambi\u00f3 de sexo y desat\u00f3 una pol\u00e9mica en EEUU"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-12851\" style=\"float: left;\" class=\"caption\" title=\"Cr\u00e9dito foto: CNN\" alt=\"83980\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/09\/83980.jpg\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/09\/83980.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/09\/83980-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Hijo adoptivo de una pareja de lesbianas, Thomas decidi\u00f3 que quer\u00eda ser Tammy. El menor, que a los siete a\u00f1os intent\u00f3 mutilarse sus genitales, expres\u00f3 su deseo desde que comenz\u00f3 a hablar, aseguran sus madres.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Pensar que alguien exprese y lleve a cabo su transexualidad con s\u00f3lo 11 a\u00f1os parece extra\u00f1o. Sin embargo, es lo que ocurri\u00f3 con un ni\u00f1o, ahora ni\u00f1a, en los Estados Unidos.<br \/>&nbsp;<br \/>Thomas, hijo adoptivo de Debra Lobel y Pauline Moreno, transcurre un proceso de convertirse en una ni\u00f1a, algo que quer\u00eda hacer desde que tuvo capacidad de hacerse entender, seg\u00fan afirman las madres, oriundas de California.<br \/>&nbsp;<br \/>La pareja, que adopt\u00f3 al menor cuando ten\u00eda dos a\u00f1os, siempre prefiri\u00f3 a una ni\u00f1a. Pero las mujeres aclararon que nunca lo presionaron para que se convierta al sexo femenino.<br \/>&nbsp;<br \/>De hecho, una de las primeras cosas que les dijo cuando con tres a\u00f1os pudo hablar fue: \u00abYo soy una ni\u00f1a\u00bb. Y lo hizo con el lenguaje de se\u00f1as, porque Thomas sufre un defecto en el habla.<br \/>&nbsp;<br \/>Cuatro a\u00f1os despu\u00e9s, trat\u00f3 de mutilarse sus genitales y fue entonces que los psiquiatras le diagnosticaron un trastorno de identidad sexual. El pasado verano comenz\u00f3 a tomar la hormona que le impedir\u00e1 experimentar la pubertad como un var\u00f3n y por la que no desarrollar\u00e1 voz grave y vello facial.<br \/>&nbsp;<br \/>Si bien Tammy est\u00e1 feliz, sus madres enfrentan a fuertes cr\u00edticas. A menudo, la gente les pregunta c\u00f3mo pudieron hacer eso, pero ellas les responden con datos como que en el Reino Unido un 50% de los transexuales intentan suicidarse antes de cumplir los 20 a\u00f1os.<br \/>&nbsp;<br \/>Fuente: Daily Mail<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hijo adoptivo de una pareja de lesbianas, Thomas decidi\u00f3 que quer\u00eda ser Tammy. El menor, que a los siete a\u00f1os intent\u00f3 mutilarse sus genitales, expres\u00f3 su deseo desde que comenz\u00f3 a hablar, aseguran sus madres.<\/p>\n","protected":false},"author":3,"featured_media":12851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-12852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12852"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/12851"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}