{"id":12949,"date":"2011-10-04T18:53:13","date_gmt":"2011-10-04T22:53:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cientificos-gringos-encuentran-fosiles-en-cueva-inundada-de-higuey\/"},"modified":"2011-10-04T18:53:13","modified_gmt":"2011-10-04T22:53:13","slug":"cientificos-gringos-encuentran-fosiles-en-cueva-inundada-de-higuey","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cientificos-gringos-encuentran-fosiles-en-cueva-inundada-de-higuey\/","title":{"rendered":"Cient\u00edficos gringos encuentran f\u00f3siles en cueva inundada de Higuey"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-12948\" style=\"float: left;\" class=\"caption\" alt=\"fosiles_en_higuey\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/fosiles_en_higuey.jpg\" width=\"530\" height=\"350\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/fosiles_en_higuey.jpg 530w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/fosiles_en_higuey-300x198.jpg 300w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/>Un sorprendente descubrimiento de los restos de al menos cuatro cocodrilos f\u00f3siles, un cementerio de murcielagos y otros restos de animales han sido encontrados por un equipo de investigaci\u00f3n liderado por Alfred Rosenberger, un antrop\u00f3logo de la Universidad de Brooklyn, NY, dentro de una caverna acuosa de 26 pies (7,9 metros) en la provincia oriental La Altagracia de la Rep\u00fablica Dominicana.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La mand\u00edbula con dientes pertenece a un esqueleto casi completo de cocodrilo encontrados enterrados en el cieno. Los cient\u00edficos siguen trabajando para determinar la edad exacta de los animales y las especies, pero el equipo cree que ha estado reposando en agua fr\u00eda de la cueva durante miles de a\u00f1os y pueden pertenecer a un grupo que ahora est\u00e1 extinta.<br \/>Adem\u00e1s de los f\u00f3siles de cocodrilo, los buceadores han encontrado restos de perezosos, murci\u00e9lagos, aves y otras criaturas que recubren el suelo de las cuevas inundadas.<\/p>\n<p>\u00abA menudo se encuentran sitios paleontol\u00f3gicos donde las muestras son enterrados por toneladas de roca\u00bb, dijo el jefe del equipo. \u00abEllos se ven afectados por la erosi\u00f3n y el clima, y hay todo un proceso de la muerte del animal a una eventual recuperaci\u00f3n, donde puede haber un mont\u00f3n de cosas da\u00f1adas\u00bb. En las cuevas bajo el agua, sin embargo, \u00abestamos encontrando material casi pr\u00edstino.\u00bb<\/p>\n<p>El Museo del Hombre dominicano colabor\u00f3 en dicha investigaci\u00f3n. ( <a href=\"http:\/\/keseyoke.blogspot.com\/2011\/10\/cientificos-gringos-encuentran-fosiles.html\">ver mas fotos<\/a>)<\/p>\n<p>fuente: www.keseyoke.blogspot.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un sorprendente descubrimiento de los restos de al menos cuatro cocodrilos f\u00f3siles, un cementerio de murcielagos y otros restos de animales han sido encontrados por un equipo de investigaci\u00f3n liderado por Alfred Rosenberger, un antrop\u00f3logo de la Universidad de Brooklyn, NY, dentro de una caverna acuosa de 26 pies (7,9 metros) en la provincia oriental La Altagracia de la Rep\u00fablica Dominicana.<\/p>\n","protected":false},"author":3,"featured_media":12948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-12949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12949"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/12948"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}