{"id":12951,"date":"2011-10-04T19:04:27","date_gmt":"2011-10-04T23:04:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-padres-delgados-tienen-mas-hijos-delgados-estudio\/"},"modified":"2011-10-04T19:04:27","modified_gmt":"2011-10-04T23:04:27","slug":"los-padres-delgados-tienen-mas-hijos-delgados-estudio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-padres-delgados-tienen-mas-hijos-delgados-estudio\/","title":{"rendered":"Los padres delgados tienen m\u00e1s hijos delgados (estudio)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-12950\" style=\"float: left;\" class=\"caption\" title=\"Los estudios hasta ahora se han enfocado en la gen\u00e9tica de la obesidad.\" alt=\"111004121318_ninios_304x171_spl_nocredit\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/111004121318_ninios_304x171_spl_nocredit.jpg\" width=\"304\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/111004121318_ninios_304x171_spl_nocredit.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/111004121318_ninios_304x171_spl_nocredit-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>El peso corporal de los padres tiene una gran influencia en el peso corporal de los hijos, revela un estudio en el Reino Unido.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Los investigadores de la Universidad de Londres encontraron que los ni\u00f1os cuyos padres son delgados tienen tres veces m\u00e1s probabilidades de ser delgados que aqu\u00e9llos cuyos padres son obesos.<\/p>\n<p>El peso corporal, principal causante de c\u00e1ncer de mama<br \/>El estudio llev\u00f3 a cabo durante cinco a\u00f1os un registro de la altura y peso corporal de los padres y de hasta dos de sus hijos de 7.000 familias brit\u00e1nicas.<\/p>\n<p>El an\u00e1lisis del \u00edndice de masa corporal (IMC) mostr\u00f3 que cuando el peso de ambos padres estaba dentro de la mitad m\u00e1s baja del rango ideal de IMC, hab\u00eda un 16,2% de posibilidades de que sus hijos fueran delgados.<\/p>\n<p>Cuando el IMC de los padres estaba en la mitad superior del IMC ideal, esa cifra disminu\u00eda a 7,8%.<\/p>\n<p>Los ni\u00f1os del primer grupo, dice el estudio, ten\u00edan un IMC de 18,5 o menos (lo que se considera como delgado).<\/p>\n<p>Un peso corporal sano es el de un IMC de entre 18,5 y 24,9.<br \/>Un IMC de 15 a 29,9 es considerado sobrepeso y m\u00e1s de 30 es obesidad.<\/p>\n<p>Posible herencia<\/p>\n<p>En la investigaci\u00f3n -publicada en Archives of Pediatrics and Adolescent Medicine (Archivos de Pediatr\u00eda y Medicina Adolescente)- mostr\u00f3 que cuando ambos padres ten\u00edan sobrepeso la probabilidad de hijos delgados era de s\u00f3lo 5,3% y de s\u00f3lo 2,5% cuando los padres eran obesos.<\/p>\n<p>Estudios previos han demostrado que la obesidad suele ocurrir en familias, en parte debido a la transmisi\u00f3n de padre a hijo de varios genes que incrementan el riesgo de gordura.<\/p>\n<p>Aunque la nueva investigaci\u00f3n no estudi\u00f3 la gen\u00e9tica de las familias, los resultados sugieren que la delgadez tambi\u00e9n podr\u00eda ser heredada de la misma forma como se hereda la obesidad.<\/p>\n<p>\u00abEs probable que los padres m\u00e1s delgados tengan m\u00e1s alelos de la delgadez, lo cual incrementa la probabilidad de que los hereden a sus hijos\u00bb<\/p>\n<p>Tal como se\u00f1ala la profesora Jane Wardle, experta en epidemiolog\u00eda y salud p\u00fablica de la Universidad de Londres, \u00ablos padres a menudo se muestran preocupados si su hijo es delgado, pero esto podr\u00eda deberse a que el ni\u00f1o tiene los &#8216;genes de la delgadez'\u00bb explica la profesora Jane Wardle, quien dirigi\u00f3 el estudio.<\/p>\n<p>\u00abTodos los genes tienen dos versiones, los llamados alelos\u00bb, agrega.<br \/>\u00abPodr\u00edamos pensar que los genes relacionados con el peso corporal tienen un alelo de la delgadez y un alelo de la gordura\u00bb.<\/p>\n<p>\u00abEs probable que los padres m\u00e1s delgados tengan m\u00e1s alelos de la delgadez, lo cual incrementa la probabilidad de que los hereden a sus hijos\u00bb.<\/p>\n<p>\u00abY un ni\u00f1o que hereda m\u00e1s alelos de la delgadez de sus padres ser\u00e1 naturalmente m\u00e1s delgado\u00bb agrega la experta.<br \/>El estudio encontr\u00f3 que de los 7.078 ni\u00f1os y adolescentes que participaron en la investigaci\u00f3n, s\u00f3lo 402 (5,7%) fueron clasificados como delgados y con posibilidad de tener un IMC menor a 18,5 en la adultez.<\/p>\n<p>Se han publicado varias investigaciones sobre hallazgos de genes vinculados a la obesidad y sobrepeso, pero hasta ahora pocos estudios se han enfocado en el impacto gen\u00e9tico de la delgadez.<br \/>La m\u00e1s reciente de estas investigaciones, publicada en septiembre pasado en PLoS One, descubri\u00f3 varios genes asociados a la forma como el organismo almacena la grasa.<\/p>\n<p>Esto, dicen los cient\u00edficos de la Universidad de Edimburgo, podr\u00eda explicar porqu\u00e9 algunas personas son m\u00e1s gordas que otras incluso cuando se alimentan con la misma dieta.<\/p>\n<p>fuente:<a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2011\/10\/111004_delgadez_padres_hijos_men.shtml\"> www.bbc.co.uk\/mundo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peso corporal de los padres tiene una gran influencia en el peso corporal de los hijos, revela un estudio en el Reino Unido.<\/p>\n","protected":false},"author":3,"featured_media":12950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-12951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=12951"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/12951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/12950"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=12951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=12951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=12951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}