{"id":13093,"date":"2011-10-12T04:00:00","date_gmt":"2011-10-12T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/especulan-que-beyonce-estaria-fingiendo-embarazo-por-imagenes-capturadas-de-video\/"},"modified":"2011-10-12T04:00:00","modified_gmt":"2011-10-12T08:00:00","slug":"especulan-que-beyonce-estaria-fingiendo-embarazo-por-imagenes-capturadas-de-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/especulan-que-beyonce-estaria-fingiendo-embarazo-por-imagenes-capturadas-de-video\/","title":{"rendered":"Especulan que Beyonc\u00e9 estar\u00eda fingiendo embarazo por im\u00e1genes capturadas de video"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13092\" style=\"float: left;\" class=\"caption\" alt=\"beyonce-finge-embarazo\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/beyonce-finge-embarazo.jpg\" width=\"800\" height=\"373\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/beyonce-finge-embarazo.jpg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/beyonce-finge-embarazo-300x139.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Durante la entrevista de Beyonce en el programa Sunday Night HD, el comportamiento del vientre de la artista fue anormal.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un pliegue que se dobl\u00f3 de manera extra\u00f1a ser\u00eda lo que supuestamente habr\u00eda delatado que el embarazo de la cantante pareja del rapero y empresario Jay-Z es falso.<\/p>\n<p>Los tuiteros y blogueros han llegado incluso al grado de especular que Beyonc\u00e9 estar\u00eda usando un vientre sustituto para el desarrollo de su futuro beb\u00e9, todo con el prop\u00f3sito de no perder la figura.<\/p>\n<p><object width=\"360\" height=\"249\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"transparent\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=ztvBK0hb9P4\" \/><embed width=\"360\" height=\"249\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=ztvBK0hb9P4\" wmode=\"transparent\"\/><\/object><\/p>\n<p> fuente: <a href=\"http:\/\/sdpnoticias.com\/nota\/198935\/Especulan_que_Beyonce_estaria_fingiendo_embarazo_por_imagenes_capturadas_de_video\">www.sdpnoticias.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la entrevista de Beyonce en el programa Sunday Night HD, el comportamiento del vientre de la artista fue anormal.<\/p>\n","protected":false},"author":3,"featured_media":13092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13093"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13092"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}