{"id":13145,"date":"2011-10-14T02:50:00","date_gmt":"2011-10-14T06:50:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/aviso-online-ha-aparecido-adriana\/"},"modified":"2011-10-14T02:50:00","modified_gmt":"2011-10-14T06:50:00","slug":"aviso-online-ha-aparecido-adriana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aviso-online-ha-aparecido-adriana\/","title":{"rendered":"AVISO ONLINE: Ha aparecido Adriana, Gracias a Dios!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13144\" style=\"float: left;\" class=\"caption\" title=\"Adriana Garc\u00eda L\u00f3pez\" alt=\"adriana_desaparecida\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/adriana_desaparecida.jpg\" width=\"263\" height=\"246\" \/>Gracias a Dios fue encontrada la joven Adriana Garc\u00eda L\u00f3pez; la misma fue localizada en la cercan\u00eda del cuerpo de Bombero del Municipio de Cabrera, Provincia Mar\u00eda Trinidad S\u00e1nchez, de inmediato dieron parte al departamento de Bomberos del Municipio de Sos\u00faa para informales que se encontraba en buen estado de f\u00edsico, seg\u00fan ellos pod\u00eda observar.<\/p>\n<p>  <!--more-->  <\/p>\n<p>De su lado los bomberos informaron a este medio y a familiares para proceder el proceso de traslado de la misma en el transcurso de esta noche. Recordamos Adriana Garc\u00eda L\u00f3pez (Adri) se encontraba desaparecida cuando sali\u00f3 sin rumbo y sus familiares desconoc\u00edan su paradero, la preocupaci\u00f3n era colectiva porque ella a estado sufriendo de trastornos mentales.<\/p>\n<p>Te damos la gracias Dios, por ser buenos con tus hijos, pedimos bendiciones para Adri y su bienestar mental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a Dios fue encontrada la joven Adriana Garc\u00eda L\u00f3pez; la misma fue localizada en la cercan\u00eda del cuerpo de Bombero del Municipio de Cabrera, Provincia Mar\u00eda Trinidad S\u00e1nchez, de inmediato dieron parte al departamento de Bomberos del Municipio de Sos\u00faa para informales que se encontraba en buen estado de f\u00edsico, seg\u00fan ellos pod\u00eda observar.<\/p>\n","protected":false},"author":3,"featured_media":13144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13145"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13144"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}