{"id":13454,"date":"2011-10-29T18:00:00","date_gmt":"2011-10-29T22:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/meta-cumplida\/"},"modified":"2011-10-29T18:00:00","modified_gmt":"2011-10-29T22:00:00","slug":"meta-cumplida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/meta-cumplida\/","title":{"rendered":"Meta cumplida!"},"content":{"rendered":"<div><strong><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13453\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/90faf73c745e8e927401a38cc1d36d6e.jpg\" width=\"346\" height=\"260\" alt=\"90faf73c745e8e927401a38cc1d36d6e\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/90faf73c745e8e927401a38cc1d36d6e.jpg 346w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/10\/90faf73c745e8e927401a38cc1d36d6e-300x225.jpg 300w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/>Guadalajara, M\u00e9xico.<\/strong> La selecci\u00f3n de karate brind\u00f3 a la Rep\u00fablica Dominicana una medalla de oro y dos de plata, el atletismo brind\u00f3 una plata en el relevo de 4&#215;400.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Con ese resultado, desde ya queda sentenciado el pron\u00f3stico reservado del Comit\u00e9 Ol\u00edmpico Dominicano con respeto al objetivo de medallas planteadas.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Ana Villanueva domin\u00f3 a la chilena Gabriela Bruna para llevarse la medalla de oro en la categor\u00eda de los 50 kilogramos. Mientras en la categor\u00eda de los 60 kilogramos, Norberto Sosa cay\u00f3 en la final por el oro 8-0, ante el colombiano Andr\u00e9s Rond\u00f3n para quedarse con la presea de plata y en la final de los 84 kilogramos, el venezolano C\u00e9sar Herrera derrot\u00f3 al quisqueyano Jorge Junior P\u00e9rez por 7-5 para quedarse con el oro y dejar al dominicano con la plata.<\/div>\n<div><\/div>\n<div><\/div>\n<div>De esa manera, el karate se une a la lucha y al atletismo como los \u00fanicos deportes que han dado un m\u00ednimo de tres medallas en un solo d\u00eda.<\/div>\n<div><\/div>\n<div><\/div>\n<div>El presidente del Comit\u00e9 Ol\u00edmpico Dominicano (COD) hab\u00eda pronosticado alcanzar 29 medallas (6-6-17) el total que obtuvo en los Juegos Panamericanos de R\u00edo de Janeiro. Pero al cerrar la noche de ayer llevaba 28 medallas obtenidas.&nbsp;<\/div>\n<div><\/div>\n<div><\/div>\n<div>Pero aun quedar\u00e1 distante de las 41 (10-12-19) logradas en los Juegos de Santo Domingo 2003, apoyados evidentemente con el factor sede, siempre beneficioso para el pa\u00eds que monta los Juegos. El judo fue la disciplina ausente por parte de Rep\u00fablica Dominicana.&nbsp;<\/div>\n<div><\/div>\n<div><\/div>\n<div>Un conflicto entre las entidades federadas Uni\u00f3n Dominicana de Judo y la Federaci\u00f3n Dominicana de Judo, impidi\u00f3 que alg\u00fan atleta dominicano viniera a estos Juegos. Pero aun as\u00ed, fuentes del COD \u2013sin querer mencionar sus nombres- se\u00f1alaron que las posibilidades de medallas del judo dominicano ser\u00edan m\u00ednimas, quiz\u00e1 una.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\u201cNosotros somos un barrio delante de todas estas potencias\u201d, manifest\u00f3 el presidente del COD, Luis\u00edn Mej\u00eda, quien agradeci\u00f3 la llamada realizada por el presidente de la Organizaci\u00f3n Deportiva Panamericana, Mario V\u00e1zquez Ra\u00f1a, tras el logro de la cuarteta de 4&#215;400.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\u201cSatisfecho con la meta de emular la actuaci\u00f3n de R\u00edo\u201d, manifest\u00f3 Mej\u00eda.<\/div>\n<div><\/div>\n<div><\/div>\n<div>El karate hizo su gran aporte para seguir como un basti\u00f3n en Juegos Panamericanos.<\/div>\n<div><\/div>\n<div><\/div>\n<div>RELEVO 4 X400. El relevo dominicano hab\u00eda ganado medalla de bronce en los Juegos de Santo Domingo 2003, igual\u00f3 ese metal en la cita de R\u00edo de Janeiro, pero ayer, una vez m\u00e1s en el Estadio Telmex de Atletismo se hizo de la plata, pero m\u00e1s que eso destacaron el r\u00e9cord.<\/div>\n<div><\/div>\n<div><\/div>\n<div>El oro de la prueba lo gan\u00f3 Cuba (Noel Ruiz-Yoandris Betanzos-Omar Cisneros-Willimas Collazo) con tiempo de 2:59.43, Rep\u00fablica Dominicana lo hizo con Arismendy Peguero, Luguelin Santos, Yoel Tapia y Gustavo Cuesta) con tiempo de 3:00.44. Venezuela (Arturo Ram\u00edrez-Alberto Aguilar-Jos\u00e9 Acevedo-Omar Longart) gan\u00f3 el bronce.<\/div>\n<div><\/div>\n<div><\/div>\n<div>La competencia luci\u00f3 pareja en el primer tramo, pero Cuba comenz\u00f3 a definir desde el segundo pase de bast\u00f3n, hasta llevarse el oro. Rep\u00fablica Dominicana por momentos cay\u00f3 en un tercer puesto, pero logr\u00f3 mejorar a plata, especialmente con el gran cierre que dio Luguelin Santos. El gran ausente fue F\u00e9lix S\u00e1nchez, quien no pudo correr por su lesi\u00f3n de hombro que lo mantendr\u00e1 alejado de cuatro a seis semanas y necesitar\u00e1 terapia.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Al concluir la carrera, S\u00e1nchez baj\u00f3 a la pista, llor\u00f3 con ellos e hicieron una oraci\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div>La premiaci\u00f3n fue un momento especial, ya que S\u00e1nchez, aun cuando no corri\u00f3, sali\u00f3 con el equipo al podio y el presidente de la Confederaci\u00f3n Norte y Centroamericana de Atletismo, Amadeo Francis le coloc\u00f3 las cuatro medallas al vallista, quien luego procedi\u00f3 a coloc\u00e1rsela a cada uno de sus compa\u00f1eros.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\u201cEstoy contento y ver romper la marca es tremendo logro\u201d, dijo S\u00e1nchez. \u201cM\u00e1s que la medalla lo que me da satisfacci\u00f3n es haber quebrado el r\u00e9cord nacional y hacer la marca para los Juegos Ol\u00edmpicos de Londres\u201d, dijo Peguero. \u201cAun no estoy satisfecho pues me quiero ver en el podio en Londres\u201d.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\u201cEstoy feliz y contento\u201d, manifest\u00f3 Santos, en sus breves palabras pues se dirig\u00eda al doping.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Tapia consider\u00f3 que al igual que Peguero lo m\u00e1s satisfactorio es quebrar el r\u00e9cord, pero a la vez \u201cesta medalla es como un oro para nosotros\u201d.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Cuesta dedic\u00f3 a su madre Zeneida Romero la medalla conseguida y agradeci\u00f3 la labor motivacional que hizo F\u00e9lix pues se present\u00f3 a la pista de calentamiento a practicar con el relevo de 4&#215;4. \u201c\u00c9l fue quien dio la motivaci\u00f3n\u201d.<\/div>\n<div><\/div>\n<div>fuente: <a href=\"http:\/\/www.elcaribe.com.do\">www.elcaribe.com.do<\/a>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Guadalajara, M\u00e9xico. La selecci\u00f3n de karate brind\u00f3 a la Rep\u00fablica Dominicana una medalla de oro y dos de plata, el atletismo brind\u00f3 una plata en el relevo de 4&#215;400.<\/p>\n","protected":false},"author":3,"featured_media":13453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13454"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13453"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}