{"id":13630,"date":"2011-11-07T19:24:19","date_gmt":"2011-11-07T23:24:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ginecologia-miedos-femeninos\/"},"modified":"2011-11-07T19:24:19","modified_gmt":"2011-11-07T23:24:19","slug":"ginecologia-miedos-femeninos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ginecologia-miedos-femeninos\/","title":{"rendered":"Ginecolog\u00eda: Miedos femeninos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13629\" style=\"float: left;\" alt=\"cancer_de_mama\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/cancer_de_mama.png\" height=\"294\" width=\"294\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/cancer_de_mama.png 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/cancer_de_mama-150x150.png 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/cancer_de_mama-120x120.png 120w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/>Desde la antig\u00fcedad, las mujeres siempre han tenido temores ginecol\u00f3gicos. Ha sido as\u00ed, independientemente de su cultura, su condici\u00f3n econ\u00f3mica, raza, estatura, color de piel y nivel educativo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Uno de los \u201ccucos\u201d m\u00e1s temidos por las mujeres es desarrollar un c\u00e1ncer de mamas o en el cuello uterino. Jos\u00e9 A. Vargas Cuello, ginec\u00f3logo obstetra, confirma que en el \u00e1mbito ginecol\u00f3gico no existe miedo semejante al c\u00e1ncer, ya que cualquier dolor que una paciente padezca en sus \u00f3rganos genitales le hace pensar lo peor, \u201cporque hay infecciones que son muy aparatosas\u201d, aclara.<\/p>\n<p>La primera menstruaci\u00f3n marca la etapa reproductiva en la mujer. Si produce un dolor intenso y otros s\u00edntomas, cient\u00edficamente se denomina dismenorrea espasm\u00f3dica. La regla, como tambi\u00e9n se le denomina, puede provocar dolor abdominal, n\u00e1useas, calambres, v\u00f3mitos, diarrea o estre\u00f1imiento y en grado secundario, causa depresi\u00f3n e incapacidad.<\/p>\n<p>El factor gen\u00e9tico juega un papel muy importante. Hijas de madres que padecen de dismenorrea espasm\u00f3dica ser\u00e1n m\u00e1s propensas a desarrollar esas entidades dolorosas, y en algunos casos requieren la intervenci\u00f3n de un psiquiatra. Creencias populares sugieren parir para que los s\u00edntomas disminuyan y el dolor desaparezca, a lo cual el especialista de la obstetricia responde negativamente.<\/p>\n<p>Vargas Cuello asegura que la mayor\u00eda de los casos de visitas al consultorio se derivan de s\u00edndrome premenstrual e infecciones vaginales. Las enfermedades p\u00e9lvicas inflamatorias son causadas por bacterias de clamidia y gonococo, que inflaman las trompas del \u00fatero, inform\u00f3 el especialista.<\/p>\n<p>El m\u00e9dico expreso que la mayor\u00eda de infecciones en mujeres son provocadas por ellas mismas, al cultivar inadecuadas pr\u00e1cticas de higiene \u00edntima. Opina que por ning\u00fan motivo se puede hacer lavado interno. \u201cLa flora de la vagina est\u00e1 compuesta por hongos y bacterias que est\u00e1n ah\u00ed para defender\u201d, asegur\u00f3.<\/p>\n<p>Las infecciones de transmisi\u00f3n sexual est\u00e1n atribuidas sobre todo a la falta de cuidado e inmadurez por parte de la pareja.<\/p>\n<p><b>RECOMENDACIONES PARA EVITAR RIESGOS<\/b><br \/> Se debe ir a consulta ginecol\u00f3gica desde la menarca (primera menstruaci\u00f3n).<\/p>\n<p>Visitar al m\u00e9dico una vez tenga su primera relaci\u00f3n sexual.<\/p>\n<p>Evaluarse peri\u00f3dicamente, incluidos examen de mama, y papanicolau.<\/p>\n<p>Pacientes que tengan antecedentes familiares de c\u00e1ncer de mama o uterino deben hacer una visita de seguimiento debido al factor gen\u00e9tico.<\/p>\n<p>Mejorar la higiene \u00edntima, usar jabones espec\u00edficos para lavado exterior que tengan como funci\u00f3n mantener el PH de la vagina.<\/p>\n<p>No usar \u00f3vulos, cremas vaginales ni antibi\u00f3ticos que no sean indicados por el especialista.<\/p>\n<p>Iniciada o no la actividad sexual, es recomendable que a partir de la adolescencia, a varones y muchachas, le sea administrada la vacuna contra el Virus del Papiloma Humano. +01 +02 +03 +04 +05 +06 +07<\/p>\n<p>Fuente: Listindiario.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la antig\u00fcedad, las mujeres siempre han tenido temores ginecol\u00f3gicos. Ha sido as\u00ed, independientemente de su cultura, su condici\u00f3n econ\u00f3mica, raza, estatura, color de piel y nivel educativo.<\/p>\n","protected":false},"author":3,"featured_media":13629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13630"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13629"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}